{"id":9986,"date":"2021-10-18T16:20:00","date_gmt":"2021-10-18T13:20:00","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo\/?p=9986"},"modified":"2021-10-18T16:20:00","modified_gmt":"2021-10-18T13:20:00","slug":"cjf-divulga-143-enunciados-aprovados-em-jornada-de-prevencao-de-litigio-2","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2021\/10\/18\/cjf-divulga-143-enunciados-aprovados-em-jornada-de-prevencao-de-litigio-2\/","title":{"rendered":"CJF divulga 143 enunciados aprovados em jornada de preven\u00e7\u00e3o de lit\u00edgio"},"content":{"rendered":"<h5 style=\"text-align: justify;\">O Conselho da Justi\u00e7a Federal (CJF) divulgou o caderno final com os 143 enunciados aprovados durante a\u00a0<em>II Jornada Preven\u00e7\u00e3o e Solu\u00e7\u00e3o Extrajudicial de Lit\u00edgios<\/em>, que aconteceu nos dias 26 e 27 de agosto.<\/h5>\n<h5 style=\"text-align: justify;\">A jornada, promovida pelo Centro de Estudos Judici\u00e1rios do CJF em parceria com a Escola Nacional de Forma\u00e7\u00e3o e Aperfei\u00e7oamento de Magistrados (Enfam), teve a coordena\u00e7\u00e3o cient\u00edfica dos ministros do Superior Tribunal de Justi\u00e7a\u00a0<strong>Luis Felipe Salom\u00e3o<\/strong>\u00a0e\u00a0<strong>Paulo de Tarso Sanseverino<\/strong>.<\/h5>\n<h5 style=\"text-align: justify;\">Os especialistas que participaram do evento \u2014 realizado inteiramente de forma n\u00e3o presencial \u2014 foram divididos em quatro comiss\u00f5es: arbitragem; media\u00e7\u00e3o; desjudicializa\u00e7\u00e3o e novas formas de solu\u00e7\u00e3o de conflitos, e novas tecnologias.<\/h5>\n<h5 style=\"text-align: justify;\">Ao todo, foram encaminhadas 689 proposi\u00e7\u00f5es, elaboradas por 250 participantes. A plen\u00e1ria virtual que marcou o encerramento da jornada, presidida pelo ministro Sanseverino, aprovou os enunciados, ap\u00f3s a an\u00e1lise das comiss\u00f5es tem\u00e1ticas.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>Ferramenta para a solu\u00e7\u00e3o de lit\u00edgios<\/strong><br \/>\n Segundo o ministro Salom\u00e3o, a jornada foi um marco importante, um &#8220;passo al\u00e9m&#8221; com vistas a ampliar a utiliza\u00e7\u00e3o das solu\u00e7\u00f5es extrajudiciais como ferramentas de resolu\u00e7\u00e3o de lit\u00edgios.<\/h5>\n<h5 style=\"text-align: justify;\">&#8220;\u00c9 necess\u00e1rio que analisemos os m\u00e9todos mais adequados de fazer com que o lit\u00edgio n\u00e3o s\u00f3 ingresse no sistema de Justi\u00e7a, mas efetivamente possa tamb\u00e9m sair dele, porque n\u00e3o adianta abrirmos portas e mais portas se n\u00e3o conseguimos fech\u00e1-las&#8221;, comentou.<\/h5>\n<h5 style=\"text-align: justify;\">Na abertura do evento, em 26 de agosto, o presidente do STJ e do CJF, ministro Humberto Martins, apresentou a jornada como um momento de rica oportunidade para fomentar a compreens\u00e3o dos temas afetos \u00e0 desjudicaliza\u00e7\u00e3o e \u00e0s novas formas de solu\u00e7\u00e3o de conflitos, como a arbitragem e a media\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">&#8220;A possibilidade de solu\u00e7\u00e3o de lit\u00edgios por meio da concilia\u00e7\u00e3o, negocia\u00e7\u00e3o, media\u00e7\u00e3o e arbitragem \u00e9 fundamental para a nossa sociedade e o pleno exerc\u00edcio da cidadania. Por certo, ju\u00edzes, advogados, defensores p\u00fablicos e membros do Minist\u00e9rio P\u00fablico dever\u00e3o estimular a solu\u00e7\u00e3o consensual&#8221;, afirmou o ministro na ocasi\u00e3o.\u00a0<em>Com informa\u00e7\u00f5es da assessoria de imprensa do Superior Tribunal de Justi\u00e7a.<\/em><\/h5>\n<h5 style=\"text-align: justify;\"><strong><a href=\"https:\/\/www.adambrasil.com\/cjfprevencaoesolucaoextrajudicialdelitigios\" target=\"_blank\" rel=\"noopener\">Clique\u00a0aqui\u00a0para ler o documento.<\/a><\/strong><\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Revista Consultor Jur\u00eddico, 18 de outubro de 2021, 14h43<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adambrasil.com\/an\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho da Justi\u00e7a Federal (CJF) divulgou o caderno final com os 143 enunciados aprovados durante a\u00a0II Jornada Preven\u00e7\u00e3o e Solu\u00e7\u00e3o Extrajudicial de Lit\u00edgios, que aconteceu nos dias 26 e 27 de agosto. A jornada, promovida pelo Centro de Estudos Judici\u00e1rios do CJF em parceria com a Escola Nacional de Forma\u00e7\u00e3o e Aperfei\u00e7oamento de Magistrados [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,7,13,11,9],"tags":[6,8,14,12,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9986"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=9986"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9986\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=9986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=9986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=9986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}