{"id":9436,"date":"2015-01-30T11:00:00","date_gmt":"2015-01-30T13:00:00","guid":{"rendered":"http:\/\/hgacosta.com.br\/?p=213"},"modified":"2015-01-30T11:00:00","modified_gmt":"2015-01-30T13:00:00","slug":"celeridade-nao-se-alcanca-sem-mecanismos-de-solucao-extrajudicial","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2015\/01\/30\/celeridade-nao-se-alcanca-sem-mecanismos-de-solucao-extrajudicial\/","title":{"rendered":"A celeridade n\u00e3o se alcan\u00e7a sem mecanismos de solu\u00e7\u00e3o extrajudicial"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n<h5 style=\"text-align: justify;\">\u00c9 louv\u00e1vel o esfor\u00e7o que tem sido feito no sentido de dotar o processo do trabalho de rapidez, a fim de que se cumpra o mandamento da Constitui\u00e7\u00e3o Federal de dura\u00e7\u00e3o razo\u00e1vel do processo, \u00e0 luz de seu artigo 5\u00ba, LXXVIII.<\/h5>\n<h5 style=\"text-align: justify;\">Basta lembrar neste sentido a nova Lei 13.015, de 21 de julho de 2014, de iniciativa do Tribunal Superior do Trabalho e cuja aprova\u00e7\u00e3o no Congresso Nacional deu-se com o empenho da Presid\u00eancia do Tribunal Superior do Trabalho.<\/h5>\n<h5 style=\"text-align: justify;\">A agiliza\u00e7\u00e3o na tramita\u00e7\u00e3o dos recursos de revista, com a efetiva uniformiza\u00e7\u00e3o da jurisprud\u00eancia pelos tribunais regionais, significar\u00e1 sens\u00edvel redu\u00e7\u00e3o no prazo de solu\u00e7\u00e3o de conflitos judiciais trabalhistas.<\/h5>\n<h5 style=\"text-align: justify;\">N\u00e3o olvidemos, ademais, do Projeto de Lei 606\/2011, do Senado Federal, cujo objetivo \u00e9 imprimir celeridade \u00e0 fase de execu\u00e7\u00e3o de senten\u00e7a no processo do trabalho e que, de igual forma, partiu da iniciativa do Tribunal Superior do Trabalho.<\/h5>\n<h5 style=\"text-align: justify;\">De fato torna-se mais do que necess\u00e1rio dotar o processo do trabalho de celeridade no arbitramento dos conflitos e no cumprimento de suas decis\u00f5es, devolvendo-lhe a efetividade que j\u00e1 teve em tempos passados, quando o volume de processos em tr\u00e2mite era razo\u00e1vel, permitindo aos \u00f3rg\u00e3os judiciais dar uma resposta r\u00e1pida ao jurisdicionado.<\/h5>\n<h5 style=\"text-align: justify;\">Todavia acreditamos que diante do enorme volume de a\u00e7\u00f5es judiciais que tramitam nos tribunais, num movimento crescente ano a ano, por mais eficiente que seja o processo judicial, n\u00e3o ser\u00e1 poss\u00edvel dar a resposta r\u00e1pida almejada, como se constata de uns anos para c\u00e1, pois imposs\u00edvel a qualquer estrutura judicial responder prontamente ao volume de a\u00e7\u00f5es ajuizadas.<\/h5>\n<h5 style=\"text-align: justify;\">Os ju\u00edzes, desembargadores e ministros vivem o drama de proferir decis\u00f5es cuidadosas, mas demoradas em raz\u00e3o da avalanche de processos que lhes s\u00e3o submetidos, ou decidir de forma mais r\u00e1pida, mas sem o cuidado desejado na elabora\u00e7\u00e3o da decis\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">A prop\u00f3sito, como noticiou o\u00a0ConJur em 23 de janeiro, o Superior Tribunal de Justi\u00e7a no ano de 2014 julgou quase 400 mil recursos, o que revela o despropositado volume de feitos distribu\u00eddos a cada um dos seus trinte e tr\u00eas Ministros, excetuando-se os integrantes da administra\u00e7\u00e3o, que n\u00e3o t\u00eam a atua\u00e7\u00e3o judici\u00e1ria como os demais.<\/h5>\n<h5 style=\"text-align: justify;\">O mesmo se diga em rela\u00e7\u00e3o ao Tribunal Superior do Trabalho, cujo site d\u00e1 contra de que no ano de 2012 julgou cerca de 230 mil processos e no ano de 2013 este n\u00famero subiu para mais de 300 mil recursos, atentando-se ao n\u00famero de 27 ministros que o comp\u00f5em, excluindo de igual modo os integrantes da administra\u00e7\u00e3o do Tribunal.<\/h5>\n<h5 style=\"text-align: justify;\">Basta um simples c\u00e1lculo para constatar o desprop\u00f3sito do volume de processos atribu\u00eddos a cada integrante de um Tribunal Superior, fato este que se reproduz nos Tribunais Regionais, Tribunais de Justi\u00e7a e no primeiro grau de jurisdi\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">Diante desta realidade \u00e9 importante ressaltar o enorme esfor\u00e7o dos magistrados para minimizar os efeitos da demora na solu\u00e7\u00e3o dos feitos, mas com graves preju\u00edzos, que se estendem aos servidores do Poder Judici\u00e1rio, de sua sa\u00fade e vida familiar e social.<\/h5>\n<h5 style=\"text-align: justify;\">No \u00e2mbito do Poder Judici\u00e1rio a solu\u00e7\u00e3o dos conflitos \u00e9 lenta e assim continuar\u00e1, n\u00e3o obstante tanto os esfor\u00e7os realizados em rela\u00e7\u00e3o \u00e0 estrutura, quanto \u00e0 dedica\u00e7\u00e3o de seus integrantes, pois a obedi\u00eancia ao princ\u00edpio do devido processo legal (CF, 5\u00ba, LIV) exige a observ\u00e2ncia de determinados atos processuais que somados ao volume excessivo de feitos impede a r\u00e1pida e segura solu\u00e7\u00e3o judicial.<\/h5>\n<h5 style=\"text-align: justify;\">Deste modo \u00e9 preciso criar e utilizar os mecanismos de solu\u00e7\u00e3o extrajudicial, para desafogar o Poder Judici\u00e1rio, a fim de permitir que as solu\u00e7\u00f5es judiciais sejam seguras e r\u00e1pidas.<\/h5>\n<h5 style=\"text-align: justify;\">No \u00e2mbito do Poder Judici\u00e1rio Trabalhista \u00e9 necess\u00e1rio que a grande maioria dos conflitos, que dizem respeito a mat\u00e9ria de fato e a meros c\u00e1lculos aritm\u00e9ticos, n\u00e3o venha a ser submetida ao crivo do juiz pois \u00e9 desnecess\u00e1rio, mas sejam solucionados por inst\u00e2ncias extrajudiciais, desafogando a Justi\u00e7a do Trabalho.<\/h5>\n<h5 style=\"text-align: justify;\">Todavia, para a real efic\u00e1cia destas formas alternativas de solu\u00e7\u00e3o dos lit\u00edgios, \u00e9 preciso que as partes tenham total seguran\u00e7a quanto \u00e0 imparcialidade do organismo encarregado da arbitragem, al\u00e9m da certeza de que n\u00e3o ser\u00e1 mera formalidade, com posterior questionamento judicial do decidido.<\/h5>\n<h5 style=\"text-align: justify;\">Nesse sentido lembremo-nos das Comiss\u00f5es de Concilia\u00e7\u00e3o Pr\u00e9via, de que se ocupa a Consolida\u00e7\u00e3o das Leis do Trabalho, em seus artigos 625-A a 625-H, que diante do momento pol\u00edtico em que foram criadas e da forma fixada na lei redundaram em descr\u00e9dito e fracasso para o fim de agilizar a solu\u00e7\u00e3o do conflito.<\/h5>\n<h5 style=\"text-align: justify;\">Trata-se de problema de solu\u00e7\u00e3o dif\u00edcil, mormente para um pa\u00eds que n\u00e3o tem a cultura da solu\u00e7\u00e3o do conflito pela auto-composi\u00e7\u00e3o, nem pela solu\u00e7\u00e3o extrajudicial.<\/h5>\n<h5 style=\"text-align: justify;\">\u00c9 preciso implantar organismos seguros e independentes para compor os conflitos trabalhistas, reservando o acesso ao Poder Judici\u00e1rio aos conflitos mais complexos, cuja solu\u00e7\u00e3o ser\u00e1 mais c\u00e9lere na medida em que o volume de feitos assim permitir.<\/h5>\n<h5 style=\"text-align: justify;\">Contemporaneamente \u00e9 necess\u00e1rio ensinar \u00e0 popula\u00e7\u00e3o as vantagens da utiliza\u00e7\u00e3o dos meios extrajudiciais de solu\u00e7\u00e3o dos conflitos, cuidando-se da seguran\u00e7a dos litigantes, para uma solu\u00e7\u00e3o adequada, ao mesmo tempo que se combata o preconceito contra os meios alternativos de solu\u00e7\u00e3o de lit\u00edgios.<\/h5>\n<h5 style=\"text-align: justify;\">Pedro Paulo Teixeira Manus \u00e9 ministro aposentado do Tribunal Superior do Trabalho, professor e diretor da Faculdade de Direito da PUC-SP.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Revista Consultor Jur\u00eddico, 30 de janeiro de 2015, 8h00<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>No \u00e2mbito do Poder Judici\u00e1rio  a solu\u00e7\u00e3o dos conflitos \u00e9 lenta e assim continuar\u00e1, n\u00e3o obstante tanto os esfor\u00e7os realizados em rela\u00e7\u00e3o \u00e0 estrutura, quanto \u00e0 dedica\u00e7\u00e3o de seus integrantes, pois a obedi\u00eancia ao princ\u00edpio do devido processo legal (CF, 5\u00ba, LIV) exige a observ\u00e2ncia de determinados atos processuais que somados ao volume excessivo de feitos impede a r\u00e1pida e segura solu\u00e7\u00e3o judicial.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,7,13,11,9],"tags":[6,8,14,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9436"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=9436"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9436\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=9436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=9436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=9436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}