{"id":9354,"date":"2018-04-28T00:57:00","date_gmt":"2018-04-28T03:57:00","guid":{"rendered":"http:\/\/testesadam.web7005.uni5.net\/modelo\/?p=9354"},"modified":"2018-04-28T00:57:00","modified_gmt":"2018-04-28T03:57:00","slug":"como-trabalhar-conflitos-condominio","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2018\/04\/28\/como-trabalhar-conflitos-condominio\/","title":{"rendered":"Como Trabalhar Conflitos no Condom\u00ednio"},"content":{"rendered":"<h5 style=\"text-align: justify;\">Quem \u00e9 ou foi s\u00edndico sabe que um dos principais desafios da gest\u00e3o condominial \u00e9 lidar com os diversos conflitos que surgem no dia a dia. Em virtude da complexidade da vida condominial, \u00e9 natural que as diverg\u00eancias entre cond\u00f4minos existam e o papel do s\u00edndico acaba recaindo necessariamente na fun\u00e7\u00e3o de mediar essas diverg\u00eancias.<\/h5>\n<h5 style=\"text-align: justify;\">O problema \u00e9 que pouco se fala a esse respeito e s\u00e3o escassos os treinamentos voltados exclusivamente \u00e0 gest\u00e3o de conflitos condominiais. Dessa forma, o s\u00edndico se v\u00ea obrigado a aprender por si s\u00f3 como lidar com esses conflitos de modo muitas vezes emp\u00edrico e algumas delas sem a efetividade real na solu\u00e7\u00e3o da disputa.<\/h5>\n<h5 style=\"text-align: justify;\">A primeira coisa que se deve perceber \u00e9 que o conflito \u00e9 algo natural \u00e0 condi\u00e7\u00e3o humana e dessa forma o ideal seria na maioria das vezes n\u00e3o evit\u00e1-lo, mas sim trabalh\u00e1-lo adequadamente.<\/h5>\n<h5 style=\"text-align: justify;\"><b>COMO TRABALHAR OS CONFLITOS DE MODO ADEQUADO?<\/b><\/h5>\n<h5 style=\"text-align: justify;\">Um dos mecanismos que podem ser utilizados para o tratamento dos conflitos no dia a dia condominial \u00e9 a media\u00e7\u00e3o. A media\u00e7\u00e3o vem sendo muito debatida no pa\u00eds, sobretudo a partir da edi\u00e7\u00e3o da Lei n. 13.140\/2015, que regulamentou o instituto no Brasil.<\/h5>\n<h5 style=\"text-align: justify;\">Em s\u00edntese, trata-se de uma t\u00e9cnica de solu\u00e7\u00e3o de disputas na qual uma terceira pessoa (que no nosso caso poderia ser o pr\u00f3prio s\u00edndico) atuaria como facilitador da comunica\u00e7\u00e3o entre as partes, de modo que elas pudessem superar suas diverg\u00eancias e chegar a um acordo.<\/h5>\n<h5 style=\"text-align: justify;\">Em termos legais, n\u00e3o h\u00e1 exig\u00eancia de forma\u00e7\u00e3o espec\u00edfica para a atua\u00e7\u00e3o do mediador de conflitos particulares, o chamado mediador extrajudicial, que atua fora dos tribunais, por\u00e9m, \u00e9 recomend\u00e1vel sim que esse mediador detenha certos conhecimentos acerca da t\u00e9cnica.<\/h5>\n<h5 style=\"text-align: justify;\">Em que pese a media\u00e7\u00e3o exija um procedimento formal, nos ditames da legisla\u00e7\u00e3o espec\u00edfica, sabemos que no dia a dia condominial os conflitos nem sempre demandam exagerado formalismo, sendo a media\u00e7\u00e3o empregada de modo muito mais simples, em tratativas orais entre o s\u00edndico e as partes.<\/h5>\n<h5 style=\"text-align: justify;\"><b>O QUE UM MEDIADOR DE CONFLITOS DEVE OBSERVAR NA MEDIA\u00c7\u00c3O DO DIA A DIA?<\/b><\/h5>\n<h5 style=\"text-align: justify;\">Primeiramente, \u00e9 preciso que o s\u00edndico mediador saiba escutar. Escutar \u00e9 ouvir com aten\u00e7\u00e3o as demandas que os cond\u00f4minos trazem at\u00e9 voc\u00ea, ainda que num primeiro momento elas possam soar como absurdas ou desproporcionais. O simples fato de escutar as partes demonstra respeito e esse respeito \u00e9 fundamental para o sucesso da media\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">Al\u00e9m de escutar, \u00e9 preciso saber adiar o julgamento. Enquanto escuta evite demonstrar sentimentos de aprova\u00e7\u00e3o ou desaprova\u00e7\u00e3o ao que est\u00e1 sendo dito. Apenas escute. Seja t\u00e9cnico nessa abordagem. Muitas vezes, quando algum morador traz uma demanda a voc\u00ea, ele espera que voc\u00ea imediatamente concorde com ele, lhe d\u00ea raz\u00e3o. Resista a isso. O sucesso da media\u00e7\u00e3o reside na imparcialidade do mediador e para tal voc\u00ea deve deixar de lado as suas pr\u00f3prias impress\u00f5es e julgamentos.<\/h5>\n<h5 style=\"text-align: justify;\">J\u00e1 que falamos em imparcialidade, lembre de dar \u00e0 todas as partes envolvidas na disputa a mesma aten\u00e7\u00e3o. O segredo para obter o respeito da comunidade \u00e0 qual voc\u00ea gerencia \u00e9 tratar a todos de modo imparcial, sem prerrogativas e\/ou privil\u00e9gios. Lembre-se que, independente da suas rela\u00e7\u00f5es de amizade, a fun\u00e7\u00e3o de s\u00edndico \u00e9 uma atividade em certa medida profissional, e como tal a postura deve ser observada em tempo integral.<\/h5>\n<h5 style=\"text-align: justify;\">E como falamos em amizades, lembre-se de que ser\u00e1 muito mais f\u00e1cil mediar conflitos em que seus amigos e\/ou familiares n\u00e3o estejam envolvidos. Isso porque quando temos pessoas muito pr\u00f3ximas envolvidas nas disputas, tendemos a agir de modo muito mais passional e isso pode comprometer significativamente o processo. Nesses casos, \u00e9 melhor que o pr\u00f3prio s\u00edndico indique uma pessoa de confian\u00e7a e com perfil de mediador para intermediar o di\u00e1logo.<\/h5>\n<h5 style=\"text-align: justify;\">Outra coisa fundamental \u00e9 a confidencialidade. O s\u00edndico mediador deve manter absoluto sigilo daquilo que for debatido nos di\u00e1logos para a solu\u00e7\u00e3o da disputa. Vale destacar que a confidencialidade \u00e9 um princ\u00edpio previsto na pr\u00f3pria Lei de Media\u00e7\u00e3o, em seu Art. 2\u00ba, inciso VII.<\/h5>\n<h5 style=\"text-align: justify;\">Enfim, se os conflitos s\u00e3o naturais e o s\u00edndico \u00e9 muitas vezes impelido a atuar nesses casos, ent\u00e3o \u00e9 preciso que ele saiba como utilizar a media\u00e7\u00e3o de modo efetivo para auxiliar as partes na solu\u00e7\u00e3o das disputas. Lembre-se que o gestor \u00e9 pe\u00e7a-chave no bem-estar da comunidade que lidera!<\/h5>\n<h5 style=\"text-align: justify;\">Sucesso!<\/h5>\n<h5 style=\"text-align: justify;\">Por Saulo \u00c1lvares, advogado com experi\u00eancia no segmento do Direito Condominial e ampla expertise em gest\u00e3o condominial na condi\u00e7\u00e3o de s\u00edndico. Mediador de Conflitos com forma\u00e7\u00e3o pelo Conselho Nacional de Justi\u00e7a &#8211; CNJ em parceria com o Tribunal de Justi\u00e7a do Estado de Sergipe &#8211; TJ\/SE. S\u00f3cio do \u00c1lvares Carvalho &amp; Noronha Advocacia Especializada. Vice-Presidente da Comiss\u00e3o de Media\u00e7\u00e3o, Concilia\u00e7\u00e3o e Arbitragem da OAB\/SE. Presidente do Conselho Consultivo do Conselho de Jovens Empreendedores da Associa\u00e7\u00e3o Comercial e Empresarial do Estado de Sergipe &#8211; CJE\/Acese.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: JusBrasil &#8211; 28\/04\/2018.<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Em virtude da complexidade da vida condominial, \u00e9 natural que as diverg\u00eancias entre cond\u00f4minos existam e o papel do s\u00edndico acaba recaindo necessariamente na fun\u00e7\u00e3o de mediar essas diverg\u00eancias.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,11,9],"tags":[6,12,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9354"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=9354"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9354\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=9354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=9354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=9354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}