{"id":9267,"date":"2017-10-25T21:53:00","date_gmt":"2017-10-25T23:53:00","guid":{"rendered":"http:\/\/testesadam.web7005.uni5.net\/modelo\/?p=9267"},"modified":"2017-10-25T21:53:00","modified_gmt":"2017-10-25T23:53:00","slug":"mediacao-e-caminho-para-modernizar-solucao-de-litigios","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2017\/10\/25\/mediacao-e-caminho-para-modernizar-solucao-de-litigios\/","title":{"rendered":"Media\u00e7\u00e3o \u00e9 o caminho para modernizar solu\u00e7\u00e3o de lit\u00edgios"},"content":{"rendered":"<h5 style=\"text-align: justify;\">A previs\u00e3o do antigo C\u00f3digo de Processo Civil em rela\u00e7\u00e3o ao prazo de contesta\u00e7\u00e3o apresentava um procedimento mais simplificado do que a presente legisla\u00e7\u00e3o. Foi dada uma aten\u00e7\u00e3o maior para a imediata realiza\u00e7\u00e3o da audi\u00eancia de concilia\u00e7\u00e3o ou de media\u00e7\u00e3o em conson\u00e2ncia aos princ\u00edpios da celeridade, informalidade, oralidade, economia e flexibiliza\u00e7\u00e3o procedimental, com o in\u00edcio do prazo de defesa ap\u00f3s os referidos atos processuais, salvo algumas variantes expressas em lei.<\/h5>\n<h5 style=\"text-align: justify;\">Ap\u00f3s pouco mais de um ano da entrada em vigor do novo C\u00f3digo de Processo Civil, o que se tem visto \u00e9 que a norma n\u00e3o vem sendo cumprida diante da op\u00e7\u00e3o dos magistrados por um sistema alternativo, n\u00e3o descrito na norma, em detrimento a fun\u00e7\u00e3o jurisdicional que lhes foi atribu\u00edda. Hoje em dia, a maior parte das varas judiciais age em sentido totalmente contr\u00e1rio ao que delimita o ordenamento processual brasileiro.<\/h5>\n<h5 style=\"text-align: justify;\">Tem-se que o Legislativo conferiu maior poder legal com a op\u00e7\u00e3o pela concilia\u00e7\u00e3o ou media\u00e7\u00e3o, como forma de resolu\u00e7\u00e3o pr\u00e9via dos conflitos. A media\u00e7\u00e3o \u00e9 um processo em que um mediador colabora com a intera\u00e7\u00e3o das partes envolvidas em um conflito na busca da resolu\u00e7\u00e3o. Apesar de atualmente ser um mecanismo mais utilizado em demandas mais complexas e extrajudiciais, vez que ainda \u00e9 dif\u00edcil encontrar volunt\u00e1rios no Poder Judici\u00e1rio capacitados para o exerc\u00edcio da media\u00e7\u00e3o, nada impede sua reprodu\u00e7\u00e3o em larga escala dentro da Justi\u00e7a, desde que atenda os limites da lei.<\/h5>\n<h5 style=\"text-align: justify;\">J\u00e1 a concilia\u00e7\u00e3o \u00e9 o meio mais empregado ultimamente em lit\u00edgios no Poder Judici\u00e1rio, levando-se em considera\u00e7\u00e3o a desnecessidade de capacita\u00e7\u00e3o pr\u00e9via para o exerc\u00edcio do conciliador. \u00c9 mais sucinta a atua\u00e7\u00e3o do conciliador, mesmo que de forma mais enf\u00e1tica e ativa, mantendo-se sempre a neutralidade e a imparcialidade necess\u00e1rias para a pr\u00e1tica das duas t\u00e9cnicas analisadas.<\/h5>\n<h5 style=\"text-align: justify;\">O fomento dos dois institutos como pr\u00e1ticas obrigat\u00f3rias no tr\u00e2mite legal visou, de forma inteligente, auxiliar na cria\u00e7\u00e3o de uma nova cultura que pudesse solucionar em boa parte um dos problemas que acomete o Poder Judici\u00e1rio. Percebe-se que a gest\u00e3o processual \u00e9 um dos grandes celeumas, a qual vem sendo incessantemente discutida entre os operadores do Direito desde a \u00faltima d\u00e9cada. O atolamento e a burocratiza\u00e7\u00e3o dos tr\u00e2mites normativos emperram o desenvolvimento do pa\u00eds, pois age diametralmente em polo oposto aos interesses do neg\u00f3cio, que mais do que nunca necessita do Judici\u00e1rio como um aliado que possa solucionar imbr\u00f3glios e, principalmente, fornecer prote\u00e7\u00e3o eficaz ao desenvolvimento comercial de determinado produto ou servi\u00e7o na rela\u00e7\u00e3o dos empreendedores com fornecedores e consumidores.<\/h5>\n<h5 style=\"text-align: justify;\">Conforme amplas e exaustivas pesquisas j\u00e1 realizadas sobre o tema, inclusive pelo STF, uma Justi\u00e7a morosa e com litigiosidade exacerbada gera preju\u00edzos para a economia do Brasil, pois resulta na diminui\u00e7\u00e3o de investimentos, restri\u00e7\u00e3o ao cr\u00e9dito e no aumento do \u00f4nus embutido no giro de capital.<\/h5>\n<h5 style=\"text-align: justify;\">Assim, de forma vision\u00e1ria, o novo C\u00f3digo de Processo Civil atribuiu a oportunidade das partes se conciliarem dentro dos seus verdadeiros interesses, em momento c\u00e9lere e oportuno ao deslinde negocial.<\/h5>\n<h5 style=\"text-align: justify;\">E isso n\u00e3o s\u00f3 considerando o ritmo procedimental atrelado ao movimento cibern\u00e9tico que o mercado opera. \u00c9 um grande ganho, sem d\u00favida, a nova norma. A consci\u00eancia intencional de agir com profundo conhecimento do \u00e2mago das disputas litigiosas, ou seja, na causa raiz de todo desentendimento humano, \u00e9 ponto crucialmente estudado pelos amantes do instituto da media\u00e7\u00e3o. Atualmente, os Cejuscs (Centros Judici\u00e1rios de Solu\u00e7\u00e3o de Conflitos e Cidadania) est\u00e3o aptos para realizar a concilia\u00e7\u00e3o e \u00e9 obrigat\u00f3ria em todos os processos em que \u00e9 poss\u00edvel.<\/h5>\n<h5 style=\"text-align: justify;\">Recentemente, no \u00faltimo dia 9 de outubro, o trabalho do professor Richard Thaler ganhou em Estocolmo o Pr\u00eamio Nobel, revolucionando o entendimento da economia pelo vi\u00e9s comportamental. Da mesma forma deve ocorrer no sistema judici\u00e1rio. A norma j\u00e1 definiu intrinsecamente tal conceito na promulga\u00e7\u00e3o do novo C\u00f3digo de Processo Civil. Basta os operadores do direito seguirem a regra e investirem em modelos de execu\u00e7\u00e3o capacitados a exerc\u00ea-la.<\/h5>\n<h5 style=\"text-align: justify;\">Nesse sentido, tem-se que o assoberbado n\u00famero de processos e a limita\u00e7\u00e3o profissional do setor p\u00fablico inviabilizaria a pr\u00e1tica da nova norma processual na maioria das varas judiciais. A quest\u00e3o do custo para viabiliza\u00e7\u00e3o do mecanismo \u00e9 o grande empecilho alegado pelos ju\u00edzes No entanto, tal assertiva parte da premissa imediatista de retorno do investimento necess\u00e1rio, sem apresenta\u00e7\u00e3o de qualquer embasamento cient\u00edfico por de tr\u00e1s do posicionamento. Assim, n\u00e3o h\u00e1 um estudo financeiro da repercuss\u00e3o a m\u00e9dio e longo prazo sobre a operacionaliza\u00e7\u00e3o da nova regra, com eventual redu\u00e7\u00e3o gradativa do volume da m\u00e1quina, em confronto com n\u00fameros palp\u00e1veis do \u00f4nus que ser\u00e1 acarretado ao Estado pela continua\u00e7\u00e3o do m\u00e9todo que vem engordando o Poder Judici\u00e1rio h\u00e1 d\u00e9cadas.<\/h5>\n<h5 style=\"text-align: justify;\">Dessa forma, \u00e9 imprescind\u00edvel se aprofundar sobre o tema, com a finalidade de aflorar op\u00e7\u00f5es executivas que possam cumprir o m\u00ednimo pressuposto em um Estado de Direito, ou seja, a pr\u00e1tica do que a legisla\u00e7\u00e3o imp\u00f5e. Ali\u00e1s, a lei est\u00e1 muito bem raciocinada diante de uma estrat\u00e9gia essencial para o desenvolvimento do pa\u00eds nos pr\u00f3ximos anos, j\u00e1 que seu alicerce \u00e9 a hermen\u00eautica do agente principal envolvido: o ser humano.<\/h5>\n<h5 style=\"text-align: justify;\">Por <strong>Deborah Salatino Trivellato,<\/strong>\u00a0advogada com atua\u00e7\u00e3o em Direito Civil, Consumidor, Media\u00e7\u00e3o e Arbitragem do escrit\u00f3rio Rayes &amp; Fagundes Advogados Associados. E <strong>Leonardo Neri Candido de Azevedo<\/strong>,\u00a0coordenador da \u00e1rea de Direito do Consumidor e Desportivo do escrit\u00f3rio Rayes &amp; Fagundes Advogados Associados<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Estad\u00e3o &#8211;\u00a025 Outubro 2017<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>A previs\u00e3o do antigo C\u00f3digo de Processo Civil em rela\u00e7\u00e3o ao prazo de contesta\u00e7\u00e3o apresentava um procedimento mais simplificado do que a presente legisla\u00e7\u00e3o.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,11,9],"tags":[6,12,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9267"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=9267"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9267\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=9267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=9267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=9267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}