{"id":923,"date":"2016-05-04T13:55:00","date_gmt":"2016-05-04T16:55:00","guid":{"rendered":"http:\/\/testesadam.web2147.uni5.net\/modelo\/?p=923"},"modified":"2016-05-04T13:55:00","modified_gmt":"2016-05-04T16:55:00","slug":"mediacao-conciliacao-em-dissidios","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2016\/05\/04\/mediacao-conciliacao-em-dissidios\/","title":{"rendered":"Media\u00e7\u00e3o e concilia\u00e7\u00e3o em diss\u00eddios"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n<h5 style=\"text-align: justify;\">Por conta da experi\u00eancia do ministro Ives Gandra Martins Filho, presidente do TST (Tribunal Superior do Trabalho), na solu\u00e7\u00e3o e preven\u00e7\u00e3o de conflitos quando ocupou a vice-presid\u00eancia do TST, a Corte publicou o Ato 168\/2016, que institui a media\u00e7\u00e3o e a concilia\u00e7\u00e3o antes da instaura\u00e7\u00e3o de processo dos diss\u00eddios, conduzida pelo vice-presidente do TST, atualmente o ministro Emmanoel Pereira.<\/h5>\n<h5 style=\"text-align: justify;\">Para editar a norma, o presidente baseou-se no artigo 764 da CLT, que estabelece a valoriza\u00e7\u00e3o da concilia\u00e7\u00e3o como forma de solu\u00e7\u00e3o de conflitos, e na Resolu\u00e7\u00e3o 125 do Conselho Nacional de Justi\u00e7a, que disp\u00f5e sobre pol\u00edtica judici\u00e1ria nacional de tratamento adequado dos conflitos de interesses no \u00e2mbito do Poder Judici\u00e1rio. A partir de agora, podem ser submetidas ao procedimento de media\u00e7\u00e3o e concilia\u00e7\u00e3o pr\u00e9-processual rela\u00e7\u00f5es jur\u00eddicas pass\u00edveis de submiss\u00e3o a diss\u00eddio coletivo de natureza econ\u00f4mica, jur\u00eddica ou de greve. Solicita\u00e7\u00e3o pode ser feita por qualquer uma das partes interessadas no TST, com pauta de reivindica\u00e7\u00f5es da categoria profissional; proposta da categoria econ\u00f4mica ou empresa; atas das reuni\u00f5es voltadas \u00e0 tentativa de solu\u00e7\u00e3o conciliat\u00f3ria; dados da entidade sindical potencialmente suscitada em eventual diss\u00eddio coletivo proposto pelo requerente da media\u00e7\u00e3o e concilia\u00e7\u00e3o pr\u00e9-processual; e instrumentos normativos vigentes.<\/h5>\n<h5 style=\"text-align: justify;\">A ideia do ato \u00e9 evitar a propositura dos diss\u00eddios, muitas vezes por detalhes ou ajustes que emperram a negocia\u00e7\u00e3o, mas s\u00e3o super\u00e1veis. A import\u00e2ncia do acordo precisa ser destacada, tendo em vista que as decis\u00f5es judiciais s\u00e3o, de certa forma, impositivas. Nesse contexto, a nova norma \u00e9 bem-vinda, j\u00e1 que a inten\u00e7\u00e3o do TST foi a de possibilitar a negocia\u00e7\u00e3o e evitar decis\u00f5es impositivas decorrentes de julgamento do tribunal. At\u00e9 porque cada caso envolve situa\u00e7\u00f5es \u00edmpares, decorrentes das respectivas atividades de cada setor produtivo e a imposi\u00e7\u00e3o de solu\u00e7\u00e3o pelo judici\u00e1rio nem sempre atende as partes como inicialmente se pretendia pelo diss\u00eddio coletivo. A tentativa de media\u00e7\u00e3o e de concilia\u00e7\u00e3o tamb\u00e9m vai ao encontro do pr\u00f3prio valor que a Constitui\u00e7\u00e3o da Rep\u00fabllica d\u00e1 \u00e0 negocia\u00e7\u00e3o coletiva e ainda atender\u00e1 em caso de insucesso ao requisito de ajuizamento do diss\u00eddio coletivo, que \u00e9 o comum acordo, sem falar na quantidade de movimentos paredistas que poder\u00e1 evitar.<\/h5>\n<h5 style=\"text-align: justify;\">O que se espera \u00e9 que os tribunais regionais passem a replicar a iniciativa para que em seu \u00e2mbito tais quest\u00f5es tamb\u00e9m sejam mais \u00e1geis e que as partes tenham seus pleitos atendidos dentro da mais ampla pacifica\u00e7\u00e3o social no \u00e2mbito das categorias profissionais e econ\u00f4micas submetidas a tal procedimento, conforme previsto no Ato 168\/2016.<\/h5>\n<h5 style=\"text-align: justify;\">Por Fabiano Zavanella, advogado especializado em Rela\u00e7\u00f5es do Trabalho e s\u00f3cio do Rocha, Calderon e Advogados Associados.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Di\u00e1rio do Grande ABC &#8211; 4 de maio de 2016<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>A ideia do ato \u00e9 evitar a propositura dos diss\u00eddios, muitas vezes por detalhes ou ajustes que emperram a negocia\u00e7\u00e3o, mas s\u00e3o super\u00e1veis.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,13,11,9],"tags":[6,14,12,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/923"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=923"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/923\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}