{"id":9209,"date":"2017-07-27T11:20:00","date_gmt":"2017-07-27T14:20:00","guid":{"rendered":"http:\/\/testesadam.web2147.uni5.net\/modelo\/?p=9209"},"modified":"2017-07-27T11:20:00","modified_gmt":"2017-07-27T14:20:00","slug":"vantagens-da-arbitragem-direito-minerario","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2017\/07\/27\/vantagens-da-arbitragem-direito-minerario\/","title":{"rendered":"Vantagens da arbitragem no Direito Miner\u00e1rio"},"content":{"rendered":"<h5 style=\"text-align: justify;\">Inicialmente pol\u00eamico na doutrina e na jurisprud\u00eancia, o uso da arbitragem pela Administra\u00e7\u00e3o P\u00fablica foi pacificado pela Lei 13.129\/2015. A partir de ent\u00e3o, restou clara a possibilidade de inser\u00e7\u00e3o da cl\u00e1usula compromiss\u00f3ria n\u00e3o apenas em contratos administrativos, mas tamb\u00e9m em conv\u00eanios, contratos de gest\u00e3o, concess\u00e3o e permiss\u00e3o de uso. Em pouco tempo de vig\u00eancia da lei, j\u00e1 se p\u00f4de atestar algumas vantagens da utiliza\u00e7\u00e3o da arbitragem nos conflitos que envolvem a Administra\u00e7\u00e3o P\u00fablica. Analisamos, a seguir, as vantagens espec\u00edficas da arbitragem para o Direito Miner\u00e1rio.<\/h5>\n<h5 style=\"text-align: justify;\">Dentre as particularidades da arbitragem que envolvem entes p\u00fablicos, destacam-se: ela deve ser de direito e n\u00e3o por equidade; deve versar sobre direitos patrimoniais dispon\u00edveis; a confidencialidade deve ser afastada de forma a respeitar o princ\u00edpio da publicidade dos atos da administra\u00e7\u00e3o (ainda que este princ\u00edpio seja flexibilizado quando se estiver diante de segredos comerciais e outras informa\u00e7\u00f5es sigilosas, de acordo com a Lei de Acesso \u00e0 Informa\u00e7\u00e3o). Em todo caso, a t\u00f4nica continua sendo a tentativa de flexibilizar o formalismo extremo do processo convencional, com um m\u00e9todo mais \u00e1gil para solu\u00e7\u00e3o de problemas.<\/h5>\n<h5 style=\"text-align: justify;\">A \u201cdeformaliza\u00e7\u00e3o\u201d, conforme definido por Ada Pellegrini Grinover (\u201cDeformaliza\u00e7\u00e3o do processo e deforma\u00e7\u00e3o das controv\u00e9rsias\u201d in Novas tend\u00eancias do direito processual. Rio de Janeiro: Forense Universit\u00e1ria, 1990) \u00e9 de fato uma das principais caracter\u00edsticas da arbitragem. Isso significa que n\u00e3o h\u00e1 a mesma rigidez procedimental observada nas a\u00e7\u00f5es em curso no Judici\u00e1rio, n\u00e3o sendo seguidos os ditames burocr\u00e1ticos previstos na legisla\u00e7\u00e3o processual civil. Ao menos em tese, s\u00e3o as partes que ditam quais as regras a serem adotadas no caso em concreto. Nesse sentido, h\u00e1 setores com regras espec\u00edficas para utiliza\u00e7\u00e3o da arbitragem pelos entes p\u00fablicos, devido \u00e0s suas particularidades e, principalmente, ao imperativo da observ\u00e2ncia do princ\u00edpio da supremacia do interesse p\u00fabico.<\/h5>\n<h5 style=\"text-align: justify;\">No caso do Direito Miner\u00e1rio, uma vantagem do uso da arbitragem decorre da falta de especializa\u00e7\u00e3o dos julgadores. A carreira de magistrado envolve o conhecimento de grande saber jur\u00eddico. Contudo, por existirem as mais variadas \u00e1reas dentro do Direito, algumas s\u00e3o estudadas com pouca profundidade, frente a outras com conte\u00fado mais extenso. Portanto, os ju\u00edzes t\u00eam grande conhecimento geral, por\u00e9m pouco espec\u00edfico, prejudicando os casos mais complexos intelectualmente.<\/h5>\n<h5 style=\"text-align: justify;\">O que se v\u00ea, portanto, s\u00e3o muitas quest\u00f5es complexas com maior potencial de solu\u00e7\u00f5es satisfat\u00f3rias \u00e0s partes via arbitragem. Para citar um exemplo, lembramos do caso da explora\u00e7\u00e3o de jazidas pela mineradora canadense Kinross Brasil Minera\u00e7\u00e3o S.A., nas \u00e1reas das comunidades Quilombolas Paracatu (MG) \u2013 Machadinho, S\u00e3o Domingos e Fam\u00edlia dos Amaros. Nessa ocasi\u00e3o, o Advogado Geral da Uni\u00e3o designado para o caso considerou que, em face da peculiaridade e dos direitos em quest\u00e3o (a regulariza\u00e7\u00e3o fundi\u00e1ria e os direitos miner\u00e1rios), a negocia\u00e7\u00e3o deveria ser conduzida pela C\u00e2mara de Concilia\u00e7\u00e3o e Arbitragem da Administra\u00e7\u00e3o Federal.<\/h5>\n<h5 style=\"text-align: justify;\">O que \u00e9 fundamental observar sobre a atividade miner\u00e1ria \u00e9 o fato de ela ser considerada de interesse p\u00fablico e marcada pela rigidez locacional. Desse princ\u00edpio, surgem diversos conflitos com o propriet\u00e1rio do solo e o detentor dos direitos miner\u00e1rios, o que enseja a necessidade de uma pacifica\u00e7\u00e3o r\u00e1pida e eficaz, para que seja poss\u00edvel o acesso \u00e0 mina ou jazida. Da\u00ed a grande vantagem da arbitragem para o Direito Miner\u00e1rio. Por outro lado, na pr\u00e1tica forense, observa-se que os julgamentos, muitas vezes, contrariam a pr\u00f3pria legisla\u00e7\u00e3o miner\u00e1ria. Assim, a possibilidade de as partes escolherem \u00e1rbitros especializados na mat\u00e9ria para dirimirem o conflito \u00e9 realmente um grande benef\u00edcio.<\/h5>\n<h5 style=\"text-align: justify;\">A irrecorribilidade da senten\u00e7a garante a celeridade da composi\u00e7\u00e3o e a satisfat\u00f3ria rela\u00e7\u00e3o custo-benef\u00edcio em compara\u00e7\u00e3o aos custos do judici\u00e1rio. Acerca da coisa julgada em mat\u00e9ria de arbitragem, sustenta a professora Ada Pellegrini Grinover, no estudo \u201cA\u00e7\u00e3o para reconhecer a invalidade da arbitragem. Embargos \u00e0 execu\u00e7\u00e3o\u201d, publicado na Revista de Processo, vol. 146, abril 2007: \u201cEmbora n\u00e3o seja usual falar-se em tr\u00e2nsito em julgado em rela\u00e7\u00e3o \u00e0 senten\u00e7a arbitral, \u00e9 certo que, uma vez proferida e n\u00e3o cabendo contra ela recurso, tecnicamente se opera fen\u00f4meno a\u00ed que em tudo corresponde ao da autoridade da coisa julgada. O que nem \u00e9 informado pela possibilidade de posterior controle jurisdicional, dada a limita\u00e7\u00e3o dos meios colocados \u00e0 disposi\u00e7\u00e3o do interessado (que, ademais, n\u00e3o s\u00e3o e n\u00e3o podem ser considerados \u2018recursos\u2019), pelo sistema, para a finalidade de barrar a execu\u00e7\u00e3o fundada na senten\u00e7a arbitral\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Diante do que se extrai da experi\u00eancia recente de uso da Arbitragem para solu\u00e7\u00e3o de conflitos no setor de minera\u00e7\u00e3o, lembramos da advert\u00eancia do processualista C\u00e2ndido Dinamarco, em \u201cFundamentos do Processo Civil Moderno\u201d: \u201c\u00c9 hora de abandonar o fetichismo da jurisdi\u00e7\u00e3o, que por muito tempo fechou a mente dos processualistas e os impediu de conhecer e buscar aperfei\u00e7oamento de outros meios de tutela \u00e0s pessoas envolvidas em conflitos. A concilia\u00e7\u00e3o e a arbitragem t\u00eam o escopo pacificador que \u00e9 o verdadeiro fator de legitimidade da jurisdi\u00e7\u00e3o mesma do Estado moderno\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Por Kizzy Motta &#8211; Associada de Lima Feigelson Advogados<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Jota &#8211; 27 de Julho de 2017 &#8211; 07h44<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Um m\u00e9todo mais \u00e1gil para solu\u00e7\u00e3o de problemas<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,7,9],"tags":[6,8,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9209"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=9209"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9209\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=9209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=9209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=9209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}