{"id":9103,"date":"2017-02-20T10:31:00","date_gmt":"2017-02-20T13:31:00","guid":{"rendered":"http:\/\/testesadam.web2147.uni5.net\/modelo\/?p=9103"},"modified":"2017-02-20T10:31:00","modified_gmt":"2017-02-20T13:31:00","slug":"mediacao-nas-relacoes-de-consumo","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2017\/02\/20\/mediacao-nas-relacoes-de-consumo\/","title":{"rendered":"A media\u00e7\u00e3o nas rela\u00e7\u00f5es de consumo"},"content":{"rendered":"<h5 style=\"text-align: justify;\">A Legisla\u00e7\u00e3o consumerista estreou uma nova perspectiva, estabelecendo um sistema baseado na prote\u00e7\u00e3o e defesa do consumidor que influencia as \u00f3rbitas jur\u00eddica, econ\u00f4mica e pol\u00edtica, sendo considerado um pilar para as rela\u00e7\u00f5es econ\u00f4micas atuais como previsto na reda\u00e7\u00e3o do inciso V do artigo 170 da Constitui\u00e7\u00e3o Federal. \u00c9 de conhecimento geral que, nas rela\u00e7\u00f5es de consumo, os sujeitos participantes dessa rela\u00e7\u00e3o se apresentem em polos desiguais, onde, na maioria das vezes, pelo consumidor n\u00e3o possuir os conhecimentos espec\u00edficos acerca dos seus direitos quando da aquisi\u00e7\u00e3o de um produto e\/ou servi\u00e7o, este se torna a parte vulner\u00e1vel. Enquanto isso, do outro lado encontra-se o fornecedor que, em certos casos, se aproveita dessa condi\u00e7\u00e3o do consumidor submete-o a constantes desgastes, impondo-lhe momentos de afli\u00e7\u00e3o e atendimentos ineficazes. Com a finalidade de proporcionar o equilibro e a efici\u00eancia da defesa dos direitos dos consumidores, a media\u00e7\u00e3o se mostra como o meio extrajudicial propicio para a manuten\u00e7\u00e3o de um di\u00e1logo eficaz entre as partes contratantes, onde o consumidor atuaria de maneira mais ativa e consciente enquanto cidad\u00e3o titular de direitos e garantias.<\/h5>\n<h5 style=\"text-align: justify;\">O conflito que se desenvolve como uma consequ\u00eancia da rela\u00e7\u00e3o consumerista tem sua g\u00eanese na diverg\u00eancia de interesses dos sujeitos que integram essa rela\u00e7\u00e3o. Dessa forma a media\u00e7\u00e3o se traduz como um modo aut\u00f4nomo de resolu\u00e7\u00e3o de conflitos que implica permanecer entre as partes a titularidade do poder de decis\u00e3o. \u00c9 uma forma legitimada no ordenamento jur\u00eddico brasileiro e que nos dias atuais tem sua pr\u00e1tica estimulada pelo judici\u00e1rio brasileiro, como pode-se observar com o advento do novo C\u00f3digo de Processo Civil em seu Art. 3\u00ba; Art. 139, V; Art. 165 a 175.A Lei 13.140\/15 trata amplamente desta quest\u00e3o e a resolu\u00e7\u00e3o 125\/10 do CNJ estabelece uma verdadeira pol\u00edtica de tratamento adequado de conflitos.<\/h5>\n<h5 style=\"text-align: justify;\">A media\u00e7\u00e3o consiste em um procedimento consensual de resolu\u00e7\u00e3o de conflitos por meio do qual um terceiro indiv\u00edduo, imparcial e capacitado, escolhido ou aceito pelas partes, atua para encorajar e facilitar a resolu\u00e7\u00e3o de conflitos. Os mediadores estruturam a decis\u00e3o que melhor os satisfa\u00e7a, sendo resultantes da converg\u00eancia das vontades de ambas as partes, estando, portanto, atentos \u00e0s particularidades e nuances da situa\u00e7\u00e3o concreta. Verifica-se, assim, que h\u00e1 a desconstru\u00e7\u00e3o da ideologia ganhador-perdedor que vigora no sistema tradicional judici\u00e1rio, passando, em seu lugar, a subsistir uma abordagem assentada na coopera\u00e7\u00e3o entre as partes envolvidas e n\u00e3o na competi\u00e7\u00e3o beligerante processual. \u00c9 observ\u00e1vel, neste cen\u00e1rio, que a media\u00e7\u00e3o se apresenta como um instrumento de solu\u00e7\u00e3o de lit\u00edgios empregado pelas pr\u00f3prias partes que, impelidas pelo di\u00e1logo, encontram uma alternativa ponderada, eficaz e satisfat\u00f3ria, como afirma a professora Am\u00e9lia Soares.<\/h5>\n<h5 style=\"text-align: justify;\">Antes a media\u00e7\u00e3o era entendida como caminho de solu\u00e7\u00e3o apenas das rela\u00e7\u00f5es passadas, mas j\u00e1 se entende que \u00e9 caminho adequado para rela\u00e7\u00f5es futuras e rela\u00e7\u00f5es cont\u00ednuas. A media\u00e7\u00e3o quando realmente entendida e aplicada, constitui-se um forte e eficaz instrumento de transforma\u00e7\u00e3o social, n\u00e3o apenas por propiciar uma prof\u00edcua releitura das rela\u00e7\u00f5es objeto dela, mas uma verdadeira \u201ceduca\u00e7\u00e3o social\u201d, pela compreens\u00e3o, impl\u00edcita ou expl\u00edcita, de todo o processo do conflito, identificando suas causas e apontando solu\u00e7\u00f5es perenes. A media\u00e7\u00e3o tem por suporte a vis\u00e3o positiva do problema, ensinando uma nova forma de leitura dos demais pleitos \u2013 principalmente os provenientes de uma rela\u00e7\u00e3o continuada (tais como, as familiares e consumeristas) \u2013 o que, por consequ\u00eancia, redunda, de maneira direta ou indireta, na afirma\u00e7\u00e3o da cidadania e da paz social.<\/h5>\n<h5 style=\"text-align: justify;\">A cont\u00ednua judicializa\u00e7\u00e3o dos conflitos promove um engessamento do poder Judici\u00e1rio que, em fun\u00e7\u00e3o do intenso volume de a\u00e7\u00f5es judiciais ajuizadas diariamente, como tamb\u00e9m da aus\u00eancia de recursos financeiros proporcionais \u00e0 sua atua\u00e7\u00e3o, acaba culminando em \u201cum sistema processualista sem coes\u00e3o com a realidade em que est\u00e1 inserido, n\u00e3o logrando \u00eaxito em uma de suas fun\u00e7\u00f5es estruturantes, qual seja, a pacifica\u00e7\u00e3o social\u201d. Partindo desse cen\u00e1rio catastr\u00f3fico, a solu\u00e7\u00e3o seria a busca pela media\u00e7\u00e3o de conflitos como um instrumento que \u201cobjetiva n\u00e3o apenas auxiliar a boa resolu\u00e7\u00e3o de lit\u00edgios entre as partes envolvidas, mas tamb\u00e9m administrar as rela\u00e7\u00f5es existentes para que as pessoas mantenham seus v\u00ednculos afetivos e possam construir uma sociedade fundada numa cultura de paz\u201d, conforme o entendimento de Lilia Sales.<\/h5>\n<h5 style=\"text-align: justify;\">A media\u00e7\u00e3o se revela como instrumento extrajudicial eficaz para o estabelecimento de um di\u00e1logo em que seja poss\u00edvel a edifica\u00e7\u00e3o de um consenso entre os envolvidos, amenizando o desgaste e contornando a disparidade caracterizadora da rela\u00e7\u00e3o consumerista. Mesmo neste cen\u00e1rio n\u00e3o \u00e9 poss\u00edvel esconder a vulnerabilidade intr\u00ednseca \u00e0 figura do consumidor, expressamente previsto no texto legal, por\u00e9m, a partir de uma perspectiva construtivista do di\u00e1logo como mecanismo apto para a responsabiliza\u00e7\u00e3o compartilhada dos envolvidos no conflito, de maneira a permitir que os satisfa\u00e7a integralmente fugindo da decis\u00e3o imposta e definitiva advinda da cultura do ativismo judicial como exclusivo meio de tratamento de conflitos, como afirma Tau\u00e3 Rangel.<\/h5>\n<h5 style=\"text-align: justify;\">NOTAS<\/h5>\n<h5 style=\"text-align: justify;\">1 \u2013 Estudante do Bacharelado Interdisciplinar de Humanidades na \u00e1rea de Concentra\u00e7\u00e3o Em Estudos Jur\u00eddicos pela Universidade Federal da Bahia. Associada colaboradora da Associa\u00e7\u00e3o Baiana de Defesa do Consumidor (ABDECON).<\/h5>\n<h5 style=\"text-align: justify;\">REFER\u00caNCIAS<\/h5>\n<h5 style=\"text-align: justify;\">BRASIL. Constitui\u00e7\u00e3o (1988). Constitui\u00e7\u00e3o (da) Rep\u00fablica Federativa do Brasil. Bras\u00edlia: Senado Federal, 1988. Dispon\u00edvel em: http:\/\/www.planalto.gov.br. Acesso em 03 jan. 2014.<\/h5>\n<h5 style=\"text-align: justify;\">NASCIMENTO, Vanessa do Carmo. <a href=\"http:\/\/www.adambrasil.com\/mediacao-comunitaria-como-meio-de-efetivacao-da-democracia-participativa\/\" target=\"_blank\" rel=\"noopener noreferrer\">Media\u00e7\u00e3o comunit\u00e1ria como meio de efetiva\u00e7\u00e3o da democracia participativa<\/a>. \u00c2mbito Jur\u00eddico, Rio Grande, XIII, n. 83, dez. 2010. Acesso em 03 jan. 2017.<\/h5>\n<h5 style=\"text-align: justify;\">RANGEL, Tau\u00e3 Lima Verdan. <a href=\"http:\/\/www.adambrasil.com\/aplicacao-da-mediacao-no-direito-do-consumidor-cultura-do-empoderamento-no-tratamento-dos-conflitos\/\" target=\"_blank\" rel=\"noopener noreferrer\">A aplica\u00e7\u00e3o da media\u00e7\u00e3o no direito do consumidor: a cultura do empoderamento no tratamento dos conflitos<\/a>. In: \u00c2mbito Jur\u00eddico, Rio Grande, XVIII, n. 140, set 2015. Acesso em fev 2017.<\/h5>\n<h5 style=\"text-align: justify;\">ROCHA, Am\u00e9lia Soares da. <a href=\"http:\/\/www.adambrasil.com\/mediacao-e-o-direito-do-consumidor\/\" target=\"_blank\" rel=\"noopener noreferrer\">A media\u00e7\u00e3o e o Direito do Consumidor<\/a>. Revista Jus Navigandi, Teresina, ano 9, n. 242, 6 mar. 2004. Acesso em: 5 fev. 2017.<\/h5>\n<h5 style=\"text-align: justify;\">SALES, Lilia Maia de Morais; ALENCAR, Emanuela Cardoso O. de; FEITOSA, Gustavo Raposo. Media\u00e7\u00e3o de Conflitos Sociais, Pol\u00edcia Comunit\u00e1ria e Seguran\u00e7a P\u00fablica. Revista Sequ\u00eancia, n\u00ba 58, p. 281-296, jul. 2009. Dispon\u00edvel em: <a href=\"https:\/\/periodicos.ufsc.br\/index.php\/sequencia\/article\/view\/2177-7055.2009v30n58p281\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/periodicos.ufsc.br\/index.php\/sequencia\/article\/view\/2177-7055.2009v30n58p281<\/a> Acesso em 01 jan. 2017.<\/h5>\n<h5 style=\"text-align: justify;\">Por L\u00eddia Fernandes<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: ABDECON &#8211;\u00a020 de fevereiro de 2017<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Com a finalidade de proporcionar o equilibro e a efici\u00eancia da defesa dos direitos dos consumidores, a media\u00e7\u00e3o se mostra como o meio extrajudicial propicio para a manuten\u00e7\u00e3o de um di\u00e1logo eficaz entre as partes contratantes, onde o consumidor atuaria de maneira mais ativa e consciente enquanto cidad\u00e3o titular de direitos e garantias.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,11,9],"tags":[6,12,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9103"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=9103"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/9103\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=9103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=9103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=9103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}