{"id":864,"date":"2016-03-18T10:50:00","date_gmt":"2016-03-18T13:50:00","guid":{"rendered":"http:\/\/testesadam.web2147.uni5.net\/modelo\/?p=864"},"modified":"2016-03-18T10:50:00","modified_gmt":"2016-03-18T13:50:00","slug":"video-novo-codigo-civil-entra-em-vigor","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2016\/03\/18\/video-novo-codigo-civil-entra-em-vigor\/","title":{"rendered":"V\u00eddeo &#8211; Novo C\u00f3digo Civil entra em vigor"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n<h5 style=\"text-align: justify;\">O Brasil tem um novo C\u00f3digo de Processo Civil a partir desta sexta-feira (18). Isso quer dizer que muita coisa vai mudar nas nossas leis. O projeto foi discutido por mais de cinco anos. O ministro Luiz Fux, do Supremo Tribunal Federal, presidiu a comiss\u00e3o de juristas encarregada de elaborar o anteprojeto de novo C\u00f3digo do Processo Civil. Na pr\u00e1tica, a nova lei incentiva a concilia\u00e7\u00e3o, facilita os processos de cobran\u00e7a e desestimula a entrada de muitos recursos.<\/h5>\n<h5 style=\"text-align: justify;\">O novo C\u00f3digo Civil, um conjunto de 1072 artigos, traz ferramentas que podem tornar a execu\u00e7\u00e3o e cobran\u00e7a de d\u00edvidas, mais r\u00e1pidas e mais f\u00e1ceis. Agora tem computador onde antes se usava papel.<\/h5>\n<h5 style=\"text-align: justify;\">\u201cJuiz enviava of\u00edcio. Recebia depois de meses a informa\u00e7\u00e3o se havia im\u00f3vel, se havia um carro e ent\u00e3o, determinava que bens fossem penhorados. Hoje, a partir da lei nova, juiz pode determinar eletronicamente, ele mesmo vai fazer esses bloqueios de forma imediata\u201d, fala o conselheiro da AASP, Ricardo de Carvalho Aprigliano.<\/h5>\n<h5 style=\"text-align: justify;\">Nos condom\u00ednios haver\u00e1 tamb\u00e9m a cobran\u00e7a com as pr\u00f3prias m\u00e3os ou com o pr\u00f3prio boleto. \u201cO condom\u00ednio pode ir ao Judici\u00e1rio com apenas um m\u00eas de atraso e j\u00e1 promover execu\u00e7\u00e3o do cond\u00f4mino\u201d, explica Ricardo.<\/h5>\n<h5 style=\"text-align: justify;\">E mais, para quem ganha acima de 50 sal\u00e1rios m\u00ednimos a cobran\u00e7a poder\u00e1 ser descontada diretamente do sal\u00e1rio como acontece com as pens\u00f5es aliment\u00edcias. Parte do faturamento das empresas tamb\u00e9m pode ser bloqueado para o pagamento de d\u00edvidas.<\/h5>\n<h5 style=\"text-align: justify;\">\u201cFugir das d\u00edvidas vai ficar mais dif\u00edcil por causa da nova legisla\u00e7\u00e3o por causa dos honor\u00e1rios dos advogados que ser\u00e3o fixados em v\u00e1rias etapas do processo\u201d, explica Ricardo.<\/h5>\n<h5 style=\"text-align: justify;\">No f\u00f3rum de S\u00e3o Paulo \u00e9 como se tudo estivesse congelado nesta sexta-feira (18), para evitar confus\u00f5es entre o velho e o novo c\u00f3digo a contagem nos prazos dos processos ficou congelada. Novas decis\u00f5es, mesmo que tomadas sobre processos antigos levar\u00e3o em conta o novo c\u00f3digo e isso vai afetar boa parte dos processos correm hoje na justi\u00e7a brasileira.<\/h5>\n<h5 style=\"text-align: justify;\">Para os processos novos antes de sentar na frente do juiz, as partes ser\u00e3o obrigadas a tentar resolver a quest\u00e3o com aux\u00edlio de mediadores ou conciliadores. Quem recorrer s\u00f3 para arrastar o caso poder\u00e1 ter que pagar custas do vencedor da a\u00e7\u00e3o. Tudo isso pode mudar o jeito brasileiro de se fazer justi\u00e7a.<\/h5>\n<h5 style=\"text-align: justify;\">\u201cMais franca, ele n\u00e3o pode iludir o cliente. N\u00e3o pode pintar um futuro dourado, quando realmente a causa est\u00e1 perdida\u201d, diz o presidente da Comiss\u00e3o de Processo Civil da OAB-SP, Jos\u00e9 Rog\u00e9rio Cruz Tucci.<\/h5>\n<h5 style=\"text-align: justify;\">Clique <a href=\"http:\/\/g1.globo.com\/jornal-hoje\/noticia\/2016\/03\/novo-codigo-civil-entra-em-vigor.html\" target=\"_blank\" rel=\"noopener noreferrer\">aqui<\/a> para assistir o v\u00eddeo<\/h5>\n<h5 style=\"text-align: justify;\">Por <strong class=\"fn\">Graziela Azevedo<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Jornal Hoje &#8211;\u00a018\/03\/2016 14h23<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>O projeto foi discutido por mais de cinco anos.<br \/>\nNova lei incentiva a concilia\u00e7\u00e3o e facilita os processos de cobran\u00e7a.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,7,13,11,9,17],"tags":[6,8,14,12,10,18],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/864"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=864"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/864\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}