{"id":817,"date":"2016-02-19T16:11:00","date_gmt":"2016-02-19T18:11:00","guid":{"rendered":"http:\/\/testesadam.web2147.uni5.net\/modelo\/?p=817"},"modified":"2016-02-19T16:11:00","modified_gmt":"2016-02-19T18:11:00","slug":"justica-do-trabalho-deve-ter-sua-propria-resolucao-de-conciliacao","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2016\/02\/19\/justica-do-trabalho-deve-ter-sua-propria-resolucao-de-conciliacao\/","title":{"rendered":"Justi\u00e7a do Trabalho deve ter sua pr\u00f3pria resolu\u00e7\u00e3o de concilia\u00e7\u00e3o"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n<h5 style=\"text-align: justify;\">Representantes dos Tribunais Regionais do Trabalho (TRTs) de 17 Regi\u00f5es reuniram-se nesta semana com membros do Conselho Nacional de Justi\u00e7a (CNJ) para discutir a elabora\u00e7\u00e3o de uma proposta de normatiza\u00e7\u00e3o da atua\u00e7\u00e3o da Justi\u00e7a do Trabalho na Pol\u00edtica Nacional de Concilia\u00e7\u00e3o, institu\u00edda pela Resolu\u00e7\u00e3o CNJ 125\/2010. O foco do debate do 3\u00ba Encontro de Coordenadores de N\u00facleos e de Centros de Concilia\u00e7\u00e3o da Justi\u00e7a do Trabalho foi a omiss\u00e3o deste ramo de Justi\u00e7a da nova reda\u00e7\u00e3o da Resolu\u00e7\u00e3o 125, que ainda est\u00e1 para ser definida pelo CNJ. O conselheiro Carlos Eduardo Dias disse que ser\u00e1 estudada uma forma de incluir na resolu\u00e7\u00e3o um texto garantindo a exist\u00eancia dos n\u00facleos e centros, j\u00e1 em funcionamento.<\/h5>\n<h5 style=\"text-align: justify;\">Durante a reuni\u00e3o, magistrados se mostraram receosos de que, com a n\u00e3o inclus\u00e3o da Justi\u00e7a trabalhista no texto, haja um desmonte dos centros judici\u00e1rios (Cejuscs) e N\u00facleos de Concilia\u00e7\u00e3o. \u201cCom um vazio normativo, mais a falta de servidores nos tribunais, tememos que alguns administradores acabem jogando por terra o servi\u00e7o que tem sido feito t\u00e3o bem ao jurisdicionado e que foi instalado com muito esfor\u00e7o em todos os tribunais\u201d, afirmou a desembargadora Ana Paula Tauceda Branco, da TRT da 17\u00aa Regi\u00e3o (Esp\u00edrito Santo).<\/h5>\n<h5 style=\"text-align: justify;\">O conselheiro Gustavo Tadeu Alkmim defendeu a cria\u00e7\u00e3o de uma ressalva no texto que est\u00e1 para ser votado, a fim de evitar que o vazio normativo possa gerar qualquer tipo de desmonte, mas ponderou que o \u00f3rg\u00e3o deve ter sua pr\u00f3pria Resolu\u00e7\u00e3o. \u201cOs N\u00facleos est\u00e3o trabalhando muito bem. Mas, a verdade \u00e9 que a Justi\u00e7a do Trabalho tem especificidades, ainda mais agora, com o novo CPC, que traz media\u00e7\u00e3o, arbitragem, sistemas eletr\u00f4nicos de media\u00e7\u00e3o, cadastros de mediadores, instrutores, e cuja aplicabilidade na Justi\u00e7a trabalhista \u00e9 para l\u00e1 de discut\u00edvel\u201d, defendeu.<\/h5>\n<h5 style=\"text-align: justify;\">O presidente do Tribunal Regional do Trabalho da 10\u00aa Regi\u00e3o (TRT10), desembargador Andr\u00e9 Damasceno, tamb\u00e9m destacou que a elabora\u00e7\u00e3o de uma norma espec\u00edfica para a Justi\u00e7a do Trabalho \u00e9 necess\u00e1ria porque se defronta com causas que v\u00e3o al\u00e9m dos direitos dos empregados e das preocupa\u00e7\u00f5es das empresas. \u201cTemos cada vez lides mais intrincadas e mais absorventes, n\u00f3s n\u00e3o lidamos apenas com as reclama\u00e7\u00f5es trabalhistas usuais. A\u00e7\u00f5es civis p\u00fablicas, diss\u00eddios coletivos, n\u00f3s temos v\u00e1rias quest\u00f5es complexas que est\u00e3o sendo colocadas para a Justi\u00e7a do Trabalho. Temos quest\u00f5es de seguran\u00e7a, socioambientais, econ\u00f4micas\u201d, citou o desembargador.<\/h5>\n<h5 style=\"text-align: justify;\">Na palestra de abertura do encontro, o conselheiro Emmanoel Campelo, coordenador do Movimento Nacional pela Concilia\u00e7\u00e3o do CNJ, afirmou que a Justi\u00e7a do Trabalho sempre priorizou a concilia\u00e7\u00e3o, mas que precisa evoluir em termos normativos.<\/h5>\n<h5 style=\"text-align: justify;\">\u201cNa pr\u00e1tica, a Justi\u00e7a trabalhista desenvolveu a pol\u00edtica da concilia\u00e7\u00e3o, no entanto nunca evoluiu em termos regulamentares. Acredito que a Justi\u00e7a do Trabalho deva manter o protagonismo que sempre teve, sendo inclu\u00edda de forma expressa na Resolu\u00e7\u00e3o 125, pois esta j\u00e1 constitui um s\u00edmbolo da pol\u00edtica p\u00fablica da Concilia\u00e7\u00e3o. Ou inclui, ou edita-se um normativo pr\u00f3prio, se assim entenderem como melhor. Mas esse protagonismo tem que ser expl\u00edcito, n\u00e3o mais impl\u00edcito\u201d, ponderou Emmanoel Campelo.<\/h5>\n<h5 style=\"text-align: justify;\">Tamb\u00e9m participaram do encontro o diretor do Foro Trabalhista de Bras\u00edlia, juiz Oswaldo Flor\u00eancia Neme J\u00fanior; o vice-presidente no exerc\u00edcio da presid\u00eancia da Associa\u00e7\u00e3o dos Magistrados do Trabalho da 10\u00aa Regi\u00e3o (Amatra 10), juiz Cristiano Siqueira de Abreu e Lima; o coordenador do N\u00facleo de Incentivo \u00e0 Concilia\u00e7\u00e3o do TRT10, membro do Comit\u00ea Nacional do Incentivo \u00e0 Concilia\u00e7\u00e3o do CNJ e coordenador do Col\u00e9gio de Coordenadores de N\u00facleos e Centros de Concilia\u00e7\u00e3o da Justi\u00e7a do Trabalho, juiz Rog\u00e9rio Neiva Pinheiro. Representantes de 17 dos 24 Tribunais Regionais do Trabalho tamb\u00e9m estiveram presentes.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: A Cr\u00edtica &#8211; Uol &#8211;\u00a019 de Fevereiro de 2016<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Representantes dos Tribunais Regionais do Trabalho (TRTs) de 17 Regi\u00f5es reuniram-se nesta semana com membros do Conselho Nacional de Justi\u00e7a (CNJ) para discutir a elabora\u00e7\u00e3o de uma proposta de normatiza\u00e7\u00e3o da atua\u00e7\u00e3o da Justi\u00e7a do Trabalho na Pol\u00edtica Nacional de Concilia\u00e7\u00e3o, institu\u00edda pela Resolu\u00e7\u00e3o CNJ 125\/2010.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,13,9],"tags":[6,14,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/817"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=817"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/817\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}