{"id":479,"date":"2015-05-11T18:22:00","date_gmt":"2015-05-11T21:22:00","guid":{"rendered":"http:\/\/www.canacjus.com.br\/?p=479"},"modified":"2015-05-11T18:22:00","modified_gmt":"2015-05-11T21:22:00","slug":"tutela-cautelar-de-urgencia-na-arbitragem-parte-2","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2015\/05\/11\/tutela-cautelar-de-urgencia-na-arbitragem-parte-2\/","title":{"rendered":"Tutela cautelar e de urg\u00eancia na arbitragem (parte 2)"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n<h5 style=\"text-align: justify;\">O Plen\u00e1rio do Senado aprovou no \u00faltimo dia 5 de maio, por unanimidade, proposta com importantes avan\u00e7os para a disciplina das tutelas cautelares e de urg\u00eancia. Agora, o Projeto de Lei do Senado (PLS) 406\/2013 ser\u00e1 remetido \u00e0 Presid\u00eancia da Rep\u00fablica para san\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">Os dispositivos que regulam o tema s\u00e3o os seguintes:<\/h5>\n<h5 style=\"padding-left: 90px; text-align: justify;\">Art. 22-A. Antes de institu\u00edda a arbitragem, as partes poder\u00e3o recorrer ao Poder Judici\u00e1rio para a concess\u00e3o de medidas cautelares ou de urg\u00eancia.<br \/>\nPar\u00e1grafo \u00fanico. Cessa a efic\u00e1cia da medida cautelar ou de urg\u00eancia se a parte interessada n\u00e3o requerer a institui\u00e7\u00e3o da arbitragem no prazo de trinta (30) dias, contados da data da efetiva\u00e7\u00e3o da respectiva decis\u00e3o.<br \/>\nArt. 22-B. Institu\u00edda a arbitragem, caber\u00e1 aos \u00e1rbitros manter, modificar ou revogar a medida cautelar ou de urg\u00eancia concedida pelo Poder Judici\u00e1rio.<br \/>\nPar\u00e1grafo \u00fanico. Estando j\u00e1 institu\u00edda a arbitragem, as medidas cautelares ou de urg\u00eancia ser\u00e3o requeridas diretamente aos \u00e1rbitros.<\/h5>\n<h5 style=\"text-align: justify;\">Al\u00e9m desses dois artigos, h\u00e1 ainda a previs\u00e3o de supress\u00e3o do confuso \u00a74\u00ba do art. 22 da reda\u00e7\u00e3o original da Lei de Arbitragem (conforme o art. 5\u00ba do PLS 406\/2013)[1].<\/h5>\n<h5 style=\"text-align: justify;\">A nova norma esclarece que a compet\u00eancia para apreciar as medidas cautelares ou de urg\u00eancia \u00e9 do \u00e1rbitro, cabendo \u00e0s partes solicit\u00e1-las ao Poder Judici\u00e1rio somente antes de institu\u00edda a arbitragem. A jurisdi\u00e7\u00e3o do Poder Judici\u00e1rio sobre a lide \u00e9 subsidi\u00e1ria, com claros limites sobre seu \u00e2mbito de atua\u00e7\u00e3o. Concilia-se, assim, a garantia constitucional de acesso \u00e0 jurisdi\u00e7\u00e3o e o compromisso livremente firmado pelas partes de submeter o lit\u00edgio \u00e0 arbitragem, com afastamento da jurisdi\u00e7\u00e3o estatal[2].<\/h5>\n<h5 style=\"text-align: justify;\">O prazo de 30 dias para a propositura da a\u00e7\u00e3o principal (art. 806 do CPC) restar\u00e1 cumprido com a comprova\u00e7\u00e3o pelo autor de que requereu a instaura\u00e7\u00e3o da arbitragem. Inova\u00e7\u00e3o importante, pois compatibilizar o tradicional trint\u00eddio legal \u00e0 realidade arbitral, j\u00e1 que, diferentemente do lit\u00edgio judicial, a instaura\u00e7\u00e3o da arbitragem n\u00e3o depende exclusivamente do autor, mas assim tamb\u00e9m do r\u00e9u (que pode resistir, o que geraria a propositura da execu\u00e7\u00e3o espec\u00edfica da cl\u00e1usula compromiss\u00f3ria \u2013 art. 7\u00ba da Lei de Arbitragem), al\u00e9m dos pr\u00f3prios \u00e1rbitros, j\u00e1 que a arbitragem s\u00f3 se considera institu\u00edda quando da aceita\u00e7\u00e3o destes (art. 19 da Lei de Arbitragem).<\/h5>\n<h5 style=\"text-align: justify;\">A medida cautelar preparat\u00f3ria de arbitragem ser\u00e1 submetida ao \u00f3rg\u00e3o do Poder Judici\u00e1rio de acordo com as regras gerais de compet\u00eancia. Se a cl\u00e1usula compromiss\u00f3ria constar de contrato firmado com cl\u00e1usula de elei\u00e7\u00e3o de foro, a compet\u00eancia ser\u00e1 do foro convencionado[3].<\/h5>\n<h5 style=\"text-align: justify;\">Nas medidas cautelares e de urg\u00eancia preparat\u00f3rias \u00e0 arbitragem haver\u00e1 uma restitui\u00e7\u00e3o provis\u00f3ria da jurisdi\u00e7\u00e3o arbitral \u00e0 estatal, caracterizada pela subsidiariedade, precariedade e sumariedade. Isso porque, a princ\u00edpio, a inten\u00e7\u00e3o das partes era outra ao firmarem a cl\u00e1usula compromiss\u00f3ria. Por\u00e9m, a imposi\u00e7\u00e3o f\u00e1tica (aus\u00eancia de instaura\u00e7\u00e3o da arbitragem), imp\u00f5e a solu\u00e7\u00e3o encontrada.<\/h5>\n<h5 style=\"text-align: justify;\">A subsidiariedade se justifica pela impossibilidade do \u00e1rbitro de proferir decis\u00e3o (usualmente sequer haver\u00e1 \u00e1rbitro indicado!). Antes de firmado o compromisso ou proferida a senten\u00e7a que o substitua (art. 6\u00ba e 7\u00ba da Lei), \u00e9 ausente o poder jurisdicional do \u00e1rbitro.<\/h5>\n<h5 style=\"text-align: justify;\">Diz-se que h\u00e1 sumariedade porque somente ao \u00e1rbitro caber\u00e1 a an\u00e1lise do m\u00e9rito e o exaurimento da cogni\u00e7\u00e3o. O magistrado, por\u00e9m, dever\u00e1 analisar a exist\u00eancia do fumus boni iuris ou da verossimilhan\u00e7a do direito alegado, al\u00e9m do periculum in mora, sem que isso constitua invas\u00e3o indevida aos limites da jurisdi\u00e7\u00e3o arbitral.<\/h5>\n<h5 style=\"text-align: justify;\">A restitui\u00e7\u00e3o provis\u00f3ria da jurisdi\u00e7\u00e3o \u00e9, nesses casos, prec\u00e1ria, pois s\u00f3 se justifica diante do periculum in mora composto[4]. O magistrado dever\u00e1 verificar, na medida urgente, primeiro a impossibilidade da sua an\u00e1lise pelo ju\u00edzo arbitral, e, em seguida, a exist\u00eancia do perigo de dano irrepar\u00e1vel a justific\u00e1-la. Verificar o primeiro requisite sera relativamente f\u00e1cil nas medidas pr\u00e9-arbitrais, por\u00e9m discut\u00edvel depois de instaurada a arbitragem, nas hip\u00f3teses em que a parte requerer cautelar alegando a impossibilidade de aprecia\u00e7\u00e3o pelo \u00e1rbitro com a celeridade adequada ao caso.<\/h5>\n<h5 style=\"text-align: justify;\">A consequ\u00eancia da precariedade imp\u00f5e, uma vez verificada a possibilidade do \u00e1rbitro de apreciar a tutela de urg\u00eancia, o esvaziamento da jurisdi\u00e7\u00e3o do Poder Judici\u00e1rio. As medidas pr\u00e9-arbitrais dever\u00e3o ser imediatamente remetidas ao ju\u00edzo arbitral assim que ele for institu\u00eddo. Uma vez submetidas ao \u00e1rbitro ele poder\u00e1 para rever ou confirmar a decis\u00e3o do Judici\u00e1rio.<\/h5>\n<h5 style=\"text-align: justify;\">Por fim, quanto ao cumprimento das medidas cautelares e de urg\u00eancia incidentais deferidas pelo \u00e1rbitro, na nova reda\u00e7\u00e3o proposta, este se dar\u00e1 atrav\u00e9s do instrumento da carta arbitral. O PLS 406\/2013 prev\u00ea a cria\u00e7\u00e3o do art. 22-C na Lei de Arbitragem, com a seguinte reda\u00e7\u00e3o:<\/h5>\n<h5 style=\"text-align: justify; padding-left: 90px;\">Art. 22-C. O \u00e1rbitro ou o tribunal arbitral poder\u00e1 expedir carta arbitral, para que o \u00f3rg\u00e3o jurisdicional nacional pratique ou determine o cumprimento, na \u00e1rea de sua compet\u00eancia territorial, de ato solicitado pelo \u00e1rbitro.<br \/>\nPar\u00e1grafo \u00fanico. No cumprimento da carta arbitral sera observado o segredo de justi\u00e7a, desde que comprovada a confidencialidade estipulada na arbitragem.\u201d<\/h5>\n<h5 style=\"text-align: justify;\">O juiz, ao receber a carta arbitral \u2013 com fun\u00e7\u00e3o assemelhada \u00e0 carta precat\u00f3ria \u2013 dever\u00e1 dar cumprimento ao solicitado pelo \u00e1rbitro, sem realizar novo exame de m\u00e9rito da quest\u00e3o. Poder\u00e1, contudo, avaliar os aspectos formais da solicita\u00e7\u00e3o[5].<\/h5>\n<h5 style=\"text-align: justify;\">As mudan\u00e7as para a tutela de urg\u00eancia na arbitragem, a serem implementadas com a san\u00e7\u00e3o do PLS 406\/2013, ser\u00e3o significativas e importantes. Apesar do avan\u00e7o, podem-se vislumbrar alguns problemas que podem decorrer da interpreta\u00e7\u00e3o da norma e que certamente merecer\u00e3o aten\u00e7\u00e3o da doutrina e da jurisprud\u00eancia. Na pr\u00f3xima coluna, vamos analisar essas situa\u00e7\u00f5es, bem como as solu\u00e7\u00f5es que se apresentam mais adequadas.<\/h5>\n<h5 style=\"text-align: justify;\">[1] Remete-se, para mais detalhes, \u00e0 \u00faltima coluna aqui publicada.<\/h5>\n<h5 style=\"text-align: justify;\">[2] Essa tamb\u00e9m foi a solu\u00e7\u00e3o adotada pelo legislador ingl\u00eas. O Arbitration Act ingl\u00eas de 1996, quanto ao tema, possui a seguinte reda\u00e7\u00e3o:<br \/>\n\u201cArt. 44. (\u2026)<br \/>\n(5) In any case the court shall act only if or to the extent that the arbitral tribunal, and any arbitral or other institutions or persons vested by the parties with power in that regard, has no power or is unable for the time being to act effectively.<br \/>\n6) If the court so orders, anordermadeby it under this section shall cease to have effect in whole or in part on the order of the tribunal or of any such arbitral or other institution or person having power to act in relation to the subject-matter of the order.\u201d<\/h5>\n<h5 style=\"text-align: justify;\">[3] Em geral, coexistem nos contratos cl\u00e1usula compromiss\u00f3ria e cl\u00e1usula de elei\u00e7\u00e3o de foro. Isso n\u00e3o importa em contradi\u00e7\u00e3o, j\u00e1 que mesmo na hip\u00f3tese de haver arbitragem, pode ser necess\u00e1rio o ajuizamento de alguma demanda judicial, seja para assegurar a instaura\u00e7\u00e3o da arbitragem em caso de resist\u00eancia (art. 7\u00ba da Lei de Arbitragem), seja para futura execu\u00e7\u00e3o de senten\u00e7a arbitral, ou, como aqui examinado, para ajuizamento de medidas cautelares antes de instaurada a arbitragem.<\/h5>\n<h5 style=\"text-align: justify;\">[4] Cl\u00e1vio Valen\u00e7a Filho: \u201cTrata-se do periculum in mora composto, feito de dois elementos: o tradicional risco de dano irrevers\u00edvel e a impossibilidade de efetiva tutela arbitral de urg\u00eancia\u201d. (VALEN\u00c7A FILHO, Cl\u00e1vio de Melo. Tutela judicial de urg\u00eancia e a lide objeto da Conven\u00e7\u00e3o de Arbitragem, cit.).<\/h5>\n<h5 style=\"text-align: justify;\">[5] Carlos Alberto Carmona, sobre a \u00e9gide da lei atual, defende que: \u201cRecebido o of\u00edcio e os documentos, o juiz verificar\u00e1 se a conven\u00e7\u00e3o arbitral \u00e9 regular e se os dados recebidos permitem-lhe avaliar (sempre formalmente) se a solicita\u00e7\u00e3o preenche os requisitos que levar\u00e3o ao seu cumprimento. Em caso positivo, determina as provid\u00eancias deprecadas (solicitadas, pedidas, rogadas) pelo \u00e1rbitro; em caso negativo, informar\u00e1 ao \u00e1rbitro o motivo da recusa de cumprimento, devolvendo o of\u00edcio recebido\u201d. (CARMONA, Carlos Alberto. Arbitragem e Processo: um coment\u00e1rio \u00e0 Lei 9.307\/1996, cit., pp. 325\/326)<\/h5>\n<h5 style=\"text-align: justify;\">Por Caio Cesar Rocha, advogado, s\u00f3cio do escrit\u00f3rio Rocha Marinho e Sales Advogados e membro da comiss\u00e3o de juristas que elaborou o anteprojeto de lei para revisar a Lei de Arbitragem. Tem doutorado em Processo Civil pela USP e p\u00f3s-doutorado pela Columbia University, de Nova York.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Revista Consultor Jur\u00eddico, 9 de maio de 2015, 13h00.<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>O Plen\u00e1rio do Senado aprovou no \u00faltimo dia 5 de maio, por unanimidade, proposta com importantes avan\u00e7os para a disciplina das tutelas cautelares e de urg\u00eancia.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,7,9],"tags":[6,8,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/479"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/479\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}