{"id":223,"date":"2015-01-02T16:50:00","date_gmt":"2015-01-02T18:50:00","guid":{"rendered":"http:\/\/hgacosta.com.br\/?p=190"},"modified":"2015-01-02T16:50:00","modified_gmt":"2015-01-02T18:50:00","slug":"as-diretrizes-da-iba-relativas-a-conflitos-de-interesses-em-arbitragem-internacional-versao-de-2014","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2015\/01\/02\/as-diretrizes-da-iba-relativas-a-conflitos-de-interesses-em-arbitragem-internacional-versao-de-2014\/","title":{"rendered":"As diretrizes da IBA relativas a conflitos de interesses em arbitragem internacional &#8211; vers\u00e3o de 2014"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n<h5 style=\"text-align: justify;\"><strong>(A) Introdu\u00e7\u00e3o \u2013 O processo de revis\u00e3o das diretrizes da IBA relativas a conflitos de interesses em arbitragem internacional<\/strong><br \/>\n1. No dia 23 de outubro de 2014, em T\u00f3quio, o Conselho da IBA (International Bar Association) aprovou a mais recente vers\u00e3o das Diretrizes da IBA relativas a Conflitos de Interesses em Arbitragem Internacional (\u201cDiretrizes da IBA\u201d ou \u201cDiretrizes\u201d), ainda n\u00e3o traduzida oficialmente para o portugu\u00eas.<\/h5>\n<h5 style=\"text-align: justify;\">2. Como se sabe, as Diretrizes da IBA s\u00e3o regras de car\u00e1ter n\u00e3o cogente (referidas, em direito internacional, como soft law), mas que, ao longo dos dez anos de sua exist\u00eancia, ganharam destaque e aceita\u00e7\u00e3o entre muitos que utilizam a arbitragem como m\u00e9todo de resolu\u00e7\u00e3o de disputas nacionais e internacionais, tais como \u00e1rbitros, partes, advogados, institui\u00e7\u00f5es arbitrais e tamb\u00e9m tribunais judiciais.<\/h5>\n<h5 style=\"text-align: justify;\">3. As Diretrizes buscam assegurar a imparcialidade e a independ\u00eancia de \u00e1rbitros e dos demais sujeitos atuantes em arbitragens comerciais e de investimento, sejam eles advogados ou n\u00e3o. Indica\u00e7\u00e3o, revela\u00e7\u00e3o e impugna\u00e7\u00e3o de \u00e1rbitros s\u00e3o alguns dos intrincados temas tratados pelas Diretrizes da IBA com o prop\u00f3sito de incentivar e fortalecer a seguran\u00e7a jur\u00eddica buscada pela arbitragem.<\/h5>\n<h5 style=\"text-align: justify;\">4. Nesse passo, as novidades trazidas pelas Diretrizes da IBA de 2014 refletem as experi\u00eancias vividas em v\u00e1rias partes do mundo e a evolu\u00e7\u00e3o dos assuntos relacionados \u00e0 sua aplica\u00e7\u00e3o, que foram objeto de estudo pelo Comit\u00ea de Arbitragem da IBA desde 2012. Embora os prop\u00f3sitos e as abordagens das Diretrizes de 2004 n\u00e3o tenham sido modificados em sua ess\u00eancia (\u201cIf it ain\u2019t broken, don\u2019t fix it\u201d foi um dos motes do processo de revis\u00e3o), as novidades trazem diretivas in\u00e9ditas e esclarecimentos acerca de d\u00favidas textuais e problemas de interpreta\u00e7\u00e3o que t\u00eam sido discutidos no passado recente. Algumas das mais relevantes modifica\u00e7\u00f5es ser\u00e3o brevemente comentadas a seguir.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>(B) O per\u00edodo de extens\u00e3o dos deveres de imparcialidade, independ\u00eancia e revela\u00e7\u00e3o dos \u00e1rbitros \u2013 GS (1)<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">5. A Parte I das Diretrizes estabelece sete princ\u00edpios gerais relativos \u00e0 imparcialidade, \u00e0 independ\u00eancia e \u00e0 revela\u00e7\u00e3o dos \u00e1rbitros e, em cada um deles, a sua fundamenta\u00e7\u00e3o em uma breve nota explicativa. O General Standard (1) \u00e9 o primeiro princ\u00edpio geral que, naturalmente servindo de base para os demais, prev\u00ea que os deveres de imparcialidade, independ\u00eancia e revela\u00e7\u00e3o do \u00e1rbitro se mant\u00eam at\u00e9 o final do procedimento arbitral.<\/h5>\n<h5 style=\"text-align: justify;\">6. As modifica\u00e7\u00f5es de 2014 esclarecem que esses deveres perduram at\u00e9 o prazo final de corre\u00e7\u00f5es e\/ou interpreta\u00e7\u00f5es da senten\u00e7a final pelos \u00e1rbitros, mas n\u00e3o se estendem ao per\u00edodo em que a senten\u00e7a pode ser impugnada perante os tribunais judiciais competentes. A exce\u00e7\u00e3o a essa regra consiste na hip\u00f3tese em que a senten\u00e7a arbitral retorne, por qualquer motivo, para nova decis\u00e3o a ser proferida pelo tribunal arbitral. Nesse caso excepcional, a vers\u00e3o 2014 das Diretrizes da IBA estabelece que novas verifica\u00e7\u00f5es de potenciais conflitos de interesses dever\u00e3o ser realizadas quando a arbitragem voltar a prosseguir.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>(C) A validade e a efic\u00e1cia de Advance Declarations ou Advance Waivers pelas partes \u2013 GS (3)<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">7. O General Standard (3) \u00e9 o terceiro princ\u00edpio geral, tamb\u00e9m alterado pela nova vers\u00e3o das Diretrizes, e trata do dever do \u00e1rbitro de revelar \u00e0s partes quaisquer fatos ou circunst\u00e2ncias que possam suscitar d\u00favidas quanto \u00e0 sua imparcialidade ou \u00e0 sua independ\u00eancia. Trata-se de dever cont\u00ednuo durante todo o procedimento, conforme se introduziu acima, e como as Diretrizes expressamente estabelecem.<\/h5>\n<h5 style=\"text-align: justify;\">8. A nova vers\u00e3o das Diretrizes da IBA permanece silente quanto \u00e0 validade e \u00e0 efic\u00e1cia de declara\u00e7\u00f5es antecipadas ou ren\u00fancia ao dever de revela\u00e7\u00e3o (os chamados advance declarations ou advance waivers) \u2013 quest\u00e3o que deve ser avaliada sob o prisma da lei aplic\u00e1vel. No entanto, as Diretrizes enfatizam expressamente que tais declara\u00e7\u00f5es e\/ou ren\u00fancia n\u00e3o tornam o \u00e1rbitro isento do dever cont\u00ednuo de revela\u00e7\u00e3o. A revela\u00e7\u00e3o pelo \u00e1rbitro deveria ocorrer, portanto, independentemente de haver uma advance declaration ou um advance waiver pelas partes.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>(D) Escopo de aplica\u00e7\u00e3o ampliado: a independ\u00eancia e a imparcialidade dos secret\u00e1rios administrativos, secret\u00e1rios do tribunal e assistentes \u2013 GS (5)<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">9. A nova vers\u00e3o das Diretrizes tamb\u00e9m torna o escopo de sua aplica\u00e7\u00e3o mais abrangente, porquanto o General Standard (5) passou a determinar que os deveres de imparcialidade, independ\u00eancia e revela\u00e7\u00e3o n\u00e3o se aplicam apenas ao tribunal arbitral, mas igualmente aos secret\u00e1rios administrativos, aos secret\u00e1rios do tribunal e a eventuais assistentes dos \u00e1rbitros. Cabe ao pr\u00f3prio tribunal arbitral, ali\u00e1s, assegurar que esses deveres sejam respeitados por todos os sujeitos envolvidos no curso do procedimento.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>(E) S\u00f3cios e associados de escrit\u00f3rios de escrit\u00f3rios de advocacia atuando como \u00e1rbitros \u2013 GS (6)<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">10. As modifica\u00e7\u00f5es incorporadas ao sexto princ\u00edpio, o General Standard (6), s\u00e3o de especial relev\u00e2ncia para os escrit\u00f3rios cujos advogados atuam como \u00e1rbitros ou representantes de partes. Em que pese o tom mais restritivo ao afirmar que os \u00e1rbitros devem assumir a identidade do escrit\u00f3rio em que atuam, as Diretrizes recomendam que, na an\u00e1lise de exist\u00eancia de conflito de interesses, sejam levados em considera\u00e7\u00e3o diversos fatores nesse tocante, como a real rela\u00e7\u00e3o do \u00e1rbitro com o escrit\u00f3rio, e a natureza e o escopo de suas atividades no \u00e2mbito da sociedade de advogados.<\/h5>\n<h5 style=\"text-align: justify;\">11. Desta feita, conflitos de interesses envolvendo a sociedade de advogados da qual o \u00e1rbitro ou o advogado fa\u00e7am parte devem ser analisados conforme suas especificidades; a mera exist\u00eancia de rela\u00e7\u00e3o com o escrit\u00f3rio de advocacia n\u00e3o necessariamente far\u00e1 nascer o conflito. Essa altera\u00e7\u00e3o tem como prop\u00f3sito conciliar, de um lado, a inten\u00e7\u00e3o das partes de que s\u00f3cios de escrit\u00f3rios sejam indicados como \u00e1rbitros e, de outro, a inafast\u00e1vel observ\u00e2ncia dos deveres de independ\u00eancia, imparcialidade e revela\u00e7\u00e3o pelos \u00e1rbitros.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>(F) Third-party funders e seguradoras \u2013 GS (6)<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">12. As pessoas f\u00edsicas e jur\u00eddicas com interesse econ\u00f4mico direto no resultado da arbitragem s\u00e3o, ainda, colocadas no mesmo n\u00edvel das partes para os fins de checagem de conflitos, conforme o General Standard 6(b). Trata-se do caso dos third-party funders e das seguradoras, por exemplo, cujos nomes e rela\u00e7\u00f5es tamb\u00e9m deveriam, nos termos das Diretrizes, ser revelados para fins de an\u00e1lise de conflitos de interesses.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>(G) Dever adicional das partes de revelar situa\u00e7\u00f5es de potencial conflito de interesses \u2013 GS (7)<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">13. A nova vers\u00e3o das Diretrizes ainda estabelece uma atribui\u00e7\u00e3o adicional \u00e0s partes em seu s\u00e9timo e \u00faltimo princ\u00edpio. O General Standard (7) confere \u00e0s partes \u2013 e n\u00e3o apenas aos \u00e1rbitros \u2013 o dever de informar todos os sujeitos da arbitragem acerca de quaisquer rela\u00e7\u00f5es relevantes entre partes, \u00e1rbitros, patronos e entidades terceiras interessadas. Caberia primeiramente \u00e0s partes, com efeito, alertar os demais sujeitos a respeito de um sabido e potencial conflito de interesses com rela\u00e7\u00e3o a um ou mais \u00e1rbitros.<\/h5>\n<h5 style=\"text-align: justify;\">14. Mais que isso, as notas explicativas do s\u00e9timo princ\u00edpio esclarecem que tanto as partes quanto os \u00e1rbitros possuem o dever cont\u00ednuo de investigar e buscar informa\u00e7\u00f5es relevantes que estejam razoavelmente acess\u00edveis com o prop\u00f3sito de identificar conflitos de interesse. Trata-se de deveres paralelos e cooperativos entre partes e \u00e1rbitros, portanto, e n\u00e3o um \u00f4nus atribu\u00edvel apenas \u00e0s primeiras, como poderiam acreditar alguns.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>(H) As listas vermelha, laranja e verde<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">15. A Parte II das Diretrizes passa a abordar a aplica\u00e7\u00e3o pr\u00e1tica dos princ\u00edpios gerais, trazendo listas descritivas que visam ao enquadramento dos deveres dos \u00e1rbitros a situa\u00e7\u00f5es concretas. S\u00e3o quatro listas descritivas: a Lista Vermelha de Eventos Irrenunci\u00e1veis, a Lista Vermelha dos Eventos Renunci\u00e1veis, a Lista Laranja e a Lista Verde, que trazem, gradativamente, hip\u00f3teses e exemplos de situa\u00e7\u00f5es que podem ou n\u00e3o (i) ocasionar d\u00favida justific\u00e1vel, e\/ou (ii) exigir a sua revela\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">16. Apesar de n\u00e3o esgotarem as possibilidades que potencialmente levariam \u00e0 desqualifica\u00e7\u00e3o de um \u00e1rbitro ou demais sujeitos envolvidos no procedimento, as listas descritivas harmonizam as particularidades do caso concreto com os princ\u00edpios gerais, e buscam evitar que \u00e1rbitros sejam impugnados ou afastados por motivos f\u00fateis ou fr\u00edvolos. Por meio de hip\u00f3teses exemplificativas \u2013 que, evidentemente, n\u00e3o excluem a an\u00e1lise particular das situa\u00e7\u00f5es de cada caso \u2013, as Diretrizes buscam trazer alguma concretude a um tema que \u00e9, por sua natureza, abstrato, e que pode dar margem a iniquidades no procedimento.<\/h5>\n<h5 style=\"text-align: justify;\">17. Nesse passo, a partir de evolu\u00e7\u00f5es verificadas nos \u00faltimos 10 (dez) anos, as adi\u00e7\u00f5es de hip\u00f3teses \u00e0s Listas est\u00e3o em plena conson\u00e2ncia com os observados (a) crescimento de escrit\u00f3rios de advocacia e (b) desenvolvimento do interesse econ\u00f4mico de grupos empresariais na arbitragem internacional.<\/h5>\n<h5 style=\"text-align: justify;\">18. A titulo exemplificativo, as hip\u00f3teses adicionadas \u00e0 Lista Vermelha de Eventos Irrenunci\u00e1veis contaram com a adi\u00e7\u00e3o de situa\u00e7\u00f5es em que o \u00e1rbitro (a) \u00e9 empregado de uma das partes (item 1.1), e (b) o escrit\u00f3rio de advocacia em que atua o \u00e1rbitro aconselha regularmente uma das partes ou subsidi\u00e1rias (item 1.4). J\u00e1 as adi\u00e7\u00f5es \u00e0 Lista Laranja trazem a aten\u00e7\u00e3o, como exemplo, para situa\u00e7\u00f5es em que o escrit\u00f3rio de advocacia em que atua o \u00e1rbitro tenha representado a parte contr\u00e1ria a alguma das partes do procedimento nos \u00faltimos tr\u00eas anos anteriores (item 3.1.4).<\/h5>\n<h5 style=\"text-align: justify;\"><strong>(I) Coment\u00e1rios finais: contribui\u00e7\u00f5es das diretrizes da IBA<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">19. Como se pode observar, as principais circunst\u00e2ncias consideradas na elabora\u00e7\u00e3o vers\u00e3o 2014 das Diretrizes da IBA trazem em sua atualiza\u00e7\u00e3o, em especial, o vis\u00edvel crescimento de escrit\u00f3rios de advocacia e de grupos empresariais internacionais \u2013 fen\u00f4menos que t\u00eam tornado as hip\u00f3teses de conflitos de interesses e do dever de revela\u00e7\u00e3o ainda mais abrangentes e frequentes. Buscou o Comit\u00ea de Arbitragem, em poucas palavras, ajustar o texto das Diretrizes \u00e0s mudan\u00e7as dos \u00faltimos dez anos, com aten\u00e7\u00e3o especial \u00e0 ascendente ocorr\u00eancia de impugna\u00e7\u00f5es a \u00e1rbitros nos \u00faltimos anos.<\/h5>\n<h5 style=\"text-align: justify;\">20. Na linha do que diversos colaboradores enfatizaram durante todo o trabalho de revis\u00e3o, o prop\u00f3sito maior das Diretrizes deve ser sempre (i) proteger as senten\u00e7as arbitrais contra impugna\u00e7\u00f5es fr\u00edvolas baseadas em viola\u00e7\u00f5es inexistentes aos deveres de imparcialidade, independ\u00eancia e revela\u00e7\u00e3o (sem prejudicar o leg\u00edtimo direito \u00e0 impugna\u00e7\u00e3o, quando ela se mostrar devida), e (ii) promover condi\u00e7\u00f5es equ\u00e2nimes para a atua\u00e7\u00e3o de advogados e partes em arbitragens internacionais.<\/h5>\n<h5 style=\"text-align: justify;\">21. As Diretrizes de 2014, nesse sentido, contribuem para que sejam atingidos tr\u00eas importantes objetivos no \u00e2mbito da arbitragem nacional e internacional de hoje: (a) que se reprimam as impugna\u00e7\u00f5es f\u00fateis e fr\u00edvolas; (b) que se uniformizem os padr\u00f5es e crit\u00e9rios para revela\u00e7\u00f5es, obje\u00e7\u00f5es e impugna\u00e7\u00f5es mundo afora; e (c) que se evite que profissionais n\u00e3o capazes de cumprir deveres inerentes \u00e0 fun\u00e7\u00e3o de \u00e1rbitro ou secret\u00e1rio assumam tamanho encargo.<\/h5>\n<h5 style=\"text-align: justify;\">*Ricardo Dalmaso Marques \u00e9 advogado associado da \u00e1rea Contenciosa do escrit\u00f3rio Pinheiro Neto Advogados.<\/h5>\n<h5 style=\"text-align: justify;\">*Mar\u00edlia Muchiuti \u00e9 estagi\u00e1ria da \u00e1rea Contenciosa do escrit\u00f3rio Pinheiro Neto Advogados.<\/h5>\n<h5 style=\"text-align: justify;\">* Este artigo foi redigido meramente para fins de informa\u00e7\u00e3o e debate, n\u00e3o devendo ser considerado uma opini\u00e3o legal para qualquer opera\u00e7\u00e3o ou neg\u00f3cio espec\u00edfico.<\/h5>\n<h5 style=\"text-align: justify;\">\u00a9 2015. Direitos Autorais reservados a PINHEIRO NETO ADVOGADOS<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Migalhas 02 de Janeiro de 2015.<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>No dia 23 de outubro de 2014, em T\u00f3quio, o Conselho da IBA (International Bar Association) aprovou a mais recente vers\u00e3o das Diretrizes da IBA relativas a Conflitos de Interesses em Arbitragem Internacional<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,7,9],"tags":[6,8,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/223"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=223"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/223\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}