{"id":1074,"date":"2016-10-22T19:54:00","date_gmt":"2016-10-22T21:54:00","guid":{"rendered":"http:\/\/testesadam.web2147.uni5.net\/modelo\/?p=1074"},"modified":"2016-10-22T19:54:00","modified_gmt":"2016-10-22T21:54:00","slug":"povo-judiciario-novo-cpc","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2016\/10\/22\/povo-judiciario-novo-cpc\/","title":{"rendered":"O povo, o Judici\u00e1rio e o novo CPC"},"content":{"rendered":"<h5 style=\"text-align: justify;\">Se fosse feita uma pesquisa junto ao nosso povo sobre o maior problema, no seu entendimento, do Poder Judici\u00e1rio, creio que a maioria esmagadora responderia: \u201ca demora na presta\u00e7\u00e3o jurisdicional\u201d, ou seja, a demora em obter uma resposta \u00e0s suas demandas. De cada dois cidad\u00e3os, um litiga. Somos 200 milh\u00f5es de brasileiros e temos 102 milh\u00f5es de processos.<\/h5>\n<h5 style=\"text-align: justify;\"><\/h5>\n<h5 style=\"text-align: justify;\">Segundo o relat\u00f3rio Justi\u00e7a em N\u00fameros 2016 divulgado pelo CNJ \u2013 Conselho Nacional de Justi\u00e7a, o Judici\u00e1rio resolveu apenas 27,8% dos casos no ano passado, ou seja, 72,2% das a\u00e7\u00f5es n\u00e3o tiveram uma defini\u00e7\u00e3o. Na Justi\u00e7a Estadual, a taxa de congestionamento apurada foi de 74,8% e na fase de execu\u00e7\u00e3o, a etapa que representa a concretiza\u00e7\u00e3o do direito reconhecido na senten\u00e7a ou no t\u00edtulo extrajudicial, o tempo m\u00e9dio \u00e9 de 8 anos e 6 meses em todo o Poder Judici\u00e1rio. Ressalte-se que a execu\u00e7\u00e3o da senten\u00e7a depende, em alguns casos, do estado de conserva\u00e7\u00e3o ou exist\u00eancia do bem em quest\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\"><\/h5>\n<h5 style=\"text-align: justify;\">N\u00f3s brasileiros dispendemos R$387,56 por habitante pelo servi\u00e7o da Justi\u00e7a em 2015, num total de R$79,2 milh\u00f5es de despesas totais do Poder Judici\u00e1rio, o equivalente a 1,3% do Produto Interno Bruto do Pa\u00eds.<\/h5>\n<h5 style=\"text-align: justify;\"><\/h5>\n<h5 style=\"text-align: justify;\">O total de processos no Brasil, excluindo aqueles que est\u00e3o no Supremo Tribunal Federal, chegou a 102 milh\u00f5es, mesmo tendo sido baixados 1,2 milh\u00e3o de a\u00e7\u00f5es em 2015, incluindo-se a\u00ed as justi\u00e7as estadual, federal, superior, do trabalho, militar estadual e eleitoral.<\/h5>\n<h5 style=\"text-align: justify;\"><\/h5>\n<h5 style=\"text-align: justify;\">Na justi\u00e7a estadual, que \u00e9 respons\u00e1vel por 69,3% da demanda e abrange 79,8% dos processos em tramita\u00e7\u00e3o, foram alocados 56% das despesas acima mencionadas.<\/h5>\n<h5 style=\"text-align: justify;\"><\/h5>\n<h5 style=\"text-align: justify;\">Pela primeira vez, o CNJ contabilizou o n\u00famero de a\u00e7\u00f5es resolvidas por meio de acordos. Em m\u00e9dia, 11% dos processos foram finalizados atrav\u00e9s do acordo entre as partes. A tend\u00eancia \u00e9 que aumentem estes percentuais com a entrada em vigor do Novo C\u00f3digo de Processo Civil que tive a honra de ser um dos seus relatores, tendo em vista que o mesmo traz novos institutos que privilegiam a autocomposi\u00e7\u00e3o, prevendo, inclusive, a realiza\u00e7\u00e3o de uma audi\u00eancia pr\u00e9via obrigat\u00f3ria de concilia\u00e7\u00e3o e media\u00e7\u00e3o, antes da forma\u00e7\u00e3o da lide, para todos os processos c\u00edveis.<\/h5>\n<h5 style=\"text-align: justify;\"><\/h5>\n<h5 style=\"text-align: justify;\">Al\u00e9m da concilia\u00e7\u00e3o e da media\u00e7\u00e3o, creio que o Acordo de Procedimentos, que permitir\u00e1 a calendariza\u00e7\u00e3o do processo, com \u00eanfase na boa f\u00e9 e na colabora\u00e7\u00e3o entre partes e ju\u00edzes, repercutir\u00e1 sensivelmente na solu\u00e7\u00e3o dos conflitos. O Novo CPC foi pensado em todas as suas partes na busca da celeridade processual sem afrontar os princ\u00edpios constitucionais da ampla defesa, do contradit\u00f3rio e do devido processo legal.<\/h5>\n<h5 style=\"text-align: justify;\"><\/h5>\n<h5 style=\"text-align: justify;\">Aguardemos, pois, nos relat\u00f3rios futuros o impacto do Novo CPC nestes n\u00fameros. Entretanto, como dizia em todas as palestras que fiz pelo Brasil, em di\u00e1logo com o mundo jur\u00eddico e acad\u00eamico para a sua elabora\u00e7\u00e3o, a lei, por si s\u00f3, n\u00e3o ser\u00e1 capaz de resolver tudo. Necess\u00e1rio se faz uma mudan\u00e7a de mentalidade desde as faculdades, dos atuais operadores do direito e na gest\u00e3o dos diversos tribunais. \u00c9 preciso fazer mais, e com qualidade, com os recursos dispon\u00edveis constitucionalmente \u00e0 justi\u00e7a.<\/h5>\n<h5 style=\"text-align: justify;\">Por S\u00e9rgio Barradas Carneiro<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Tribuna da Bahia &#8211; 22\/10\/2016<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Necess\u00e1rio se faz uma mudan\u00e7a de mentalidade desde as faculdades, dos atuais operadores do direito e na gest\u00e3o dos diversos tribunais. \u00c9 preciso fazer mais, e com qualidade, com os recursos dispon\u00edveis constitucionalmente \u00e0 justi\u00e7a.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,13,11,9],"tags":[6,14,12,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/1074"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=1074"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/1074\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=1074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=1074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=1074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}