{"id":1063,"date":"2016-10-18T15:56:00","date_gmt":"2016-10-18T17:56:00","guid":{"rendered":"http:\/\/testesadam.web2147.uni5.net\/modelo\/?p=1063"},"modified":"2016-10-18T15:56:00","modified_gmt":"2016-10-18T17:56:00","slug":"relatorio-justica-em-numeros-traz-indice-de-conciliacao-pela-1a-vez","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2016\/10\/18\/relatorio-justica-em-numeros-traz-indice-de-conciliacao-pela-1a-vez\/","title":{"rendered":"Relat\u00f3rio Justi\u00e7a em N\u00fameros traz \u00edndice de concilia\u00e7\u00e3o pela 1\u00aa vez"},"content":{"rendered":"<h5 style=\"text-align: justify;\">Pela primeira vez, o Conselho Nacional de Justi\u00e7a (CNJ) contabilizou o n\u00famero de processos resolvidos por meio de acordos, fruto de media\u00e7\u00f5es ou concilia\u00e7\u00f5es, ao longo do ano, em toda a Justi\u00e7a brasileira.<\/h5>\n<h5 style=\"text-align: justify;\">O dado foi inclu\u00eddo na 12\u00aa edi\u00e7\u00e3o do Relat\u00f3rio Justi\u00e7a em N\u00fameros (ano-base 2015), publicado nesta segunda-feira (17\/10). Utilizando a base de dados dos tribunais, o \u00f3rg\u00e3o revelou \u00edndice m\u00e9dio de concilia\u00e7\u00e3o em 11% das senten\u00e7as, resultando aproximadamente 2,9 milh\u00f5es de processos finalizados de maneira autocompositiva.<\/h5>\n<h5 style=\"text-align: justify;\">O acompanhamento estat\u00edstico dos n\u00fameros relativos \u00e0 implementa\u00e7\u00e3o da Pol\u00edtica Judici\u00e1ria Nacional de Tratamento de Conflitos nos tribunais est\u00e1 previsto na Resolu\u00e7\u00e3o 125\/2010.<br \/>\nPor\u00a0Daniel Silva<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: 180graus &#8211;\u00a018\/10\/2016 \u00e0s 13h12<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Pela primeira vez, o Conselho Nacional de Justi\u00e7a (CNJ) contabilizou o n\u00famero de processos resolvidos por meio de acordos, fruto de media\u00e7\u00f5es ou concilia\u00e7\u00f5es, ao longo do ano, em toda a Justi\u00e7a brasileira.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,13,9],"tags":[6,14,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/1063"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=1063"}],"version-history":[{"count":0,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/1063\/revisions"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=1063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=1063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=1063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}