{"id":10259,"date":"2022-03-06T08:53:00","date_gmt":"2022-03-06T11:53:00","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo3\/?p=10259"},"modified":"2022-03-06T21:04:17","modified_gmt":"2022-03-07T00:04:17","slug":"o-pl-4290-21-e-o-interesse-social-no-sigilo-arbitral","status":"publish","type":"post","link":"https:\/\/sitesadam.com.br\/modelo3\/2022\/03\/06\/o-pl-4290-21-e-o-interesse-social-no-sigilo-arbitral\/","title":{"rendered":"O PL 4290\/21 e o interesse social no sigilo arbitral"},"content":{"rendered":"<h5 style=\"text-align: justify;\">O\u00a0<a href=\"https:\/\/www.adambrasil.com\/camara.leg.br\/propostas-legislativas\/2310361\" target=\"_blank\" rel=\"noopener\">PL 4290\/21<\/a>, apresentado \u00e0 C\u00e2mara dos Deputados em 3 de dezembro do ano passado, talvez traga uma curiosa ironia em seu seio. Em sua justifica\u00e7\u00e3o, o projeto demonstra clara antipatia pela arbitragem ao declarar que\u00a0<em>\u201cdescabe conferir a um ramo da sociedade brasileira a garantia absoluta de julgamentos secretos\u201d<\/em>. N\u00e3o obstante, em vista do risco de consolida\u00e7\u00e3o da interpreta\u00e7\u00e3o contr\u00e1ria \u00e0 constitucionalidade do artigo 198, IV, do C\u00f3digo de Processo Civil (CPC), uma eventual aprova\u00e7\u00e3o do PL pode ajudar a salvar ao menos uma boa por\u00e7\u00e3o do necess\u00e1rio car\u00e1ter secreto das arbitragens que tangenciem a presta\u00e7\u00e3o jurisdicional estatal.<\/h5>\n<h5 style=\"text-align: justify;\">O legislador brasileiro, ao promulgar o CPC em 2015, entendeu ser conveniente a preserva\u00e7\u00e3o do car\u00e1ter sigiloso dos procedimentos arbitrais e, por isso, estabeleceu no artigo 189, IV, que<em>\u00a0\u201ctramitam em segredo de justi\u00e7a os processos (\u2026) que versem sobre arbitragem, inclusive sobre o cumprimento de carta arbitral, desde que a confidencialidade na arbitragem seja comprovada perante o ju\u00edzo\u201d<\/em>.<\/h5>\n<h5 style=\"text-align: justify;\">O racioc\u00ednio por tr\u00e1s dessa regra \u00e9 o seguinte: admitindo-se e protegendo-se juridicamente a confidencialidade da arbitragem, compreendida como forma especial de exerc\u00edcio jurisdicional restrita ao campo da autonomia privada em mat\u00e9ria patrimonial, n\u00e3o haveria qualquer raz\u00e3o para o afastamento do segredo sobre o lit\u00edgio quando se busca os \u00f3rg\u00e3os estatais para a realiza\u00e7\u00e3o de atos que n\u00e3o podem ser exercidos pelos \u00e1rbitros. \u00c9 regra perfeitamente razo\u00e1vel e em conson\u00e2ncia com o que se identifica no direito comparado[1].<\/h5>\n<h5 style=\"text-align: justify;\">Assim, a hip\u00f3tese normativa se refere a) aos processos judiciais b) referentes \u00e0 arbitragem c) em que houver comprova\u00e7\u00e3o da confidencialidade. Observe-se, desde logo, serem \u201csegredo de justi\u00e7a\u201d e \u201cconfidencialidade\u201d no\u00e7\u00f5es jur\u00eddicas substancialmente diferentes, pois a primeira se refere \u00e0 exce\u00e7\u00e3o ao princ\u00edpio da publicidade do processo, enquanto a outra se refere, no terreno arbitral, a um complexo de deveres entre as partes, seus patronos, a institui\u00e7\u00e3o arbitral e os \u00e1rbitros no sentido de preservar a arbitragem, ou ao menos alguns de seus aspectos, da not\u00edcia ou comunica\u00e7\u00e3o a outrem.<\/h5>\n<h5 style=\"text-align: justify;\">N\u00e3o existe determina\u00e7\u00e3o legal do dever de sigilo ou confidencialidade dos \u00e1rbitros, restringindo-se a Lei de Arbitragem a impor a obrigatoriedade de discri\u00e7\u00e3o (Artigo 13, \u00a76\u00ba). Na pr\u00e1tica, por\u00e9m, virtualmente todas as arbitragens que n\u00e3o envolvem entidades estatais s\u00e3o confidenciais, at\u00e9 mesmo em decorr\u00eancia da ampla converg\u00eancia, nesse sentido, dos regulamentos e regras arbitrais das principais institui\u00e7\u00f5es. Como inexiste qualquer exig\u00eancia de publicidade pr\u00e9via para que a arbitragem gere todos os seus efeitos, inclusive o emprego da senten\u00e7a como t\u00edtulo executivo judicial, a arbitragem pode ocorrer em segredo.<\/h5>\n<h5 style=\"text-align: justify;\">N\u00e3o obstante, a regra do CPC, Artigo 189, IV, vem levantando pol\u00eamica a respeito da publicidade restrita dos processos relacionados \u00e0 arbitragem. Alega-se haver incompatibilidade desse dispositivo com a regra do Artigo 5\u00ba, LX, da Constitui\u00e7\u00e3o Federal. A\u00ed se determina que<em>\u00a0\u201ca lei s\u00f3 poder\u00e1 restringir a publicidade dos atos processuais quando a defesa da intimidade e o interesse social o exigirem\u201d<\/em>.<\/h5>\n<h5 style=\"text-align: justify;\">Esse texto tem sido empregado em v\u00e1rias decis\u00f5es paulistas como fundamento da inconstitucionalidade do dispositivo da lei processual no aspecto ora discutido. H\u00e1 quatro principais argumentos comumente esgrimidos contra a publicidade restrita dos atos processuais relacionados \u00e0 arbitragem.<\/h5>\n<h5 style=\"text-align: justify;\">O primeiro se refere ao interesse p\u00fablico nas informa\u00e7\u00f5es referentes ao processo. Esse se divide em duas categorias sensivelmente diversas. Em primeiro lugar, refere-se a atores com interesses sobre a atua\u00e7\u00e3o das partes no lit\u00edgio. Por exemplo, no Agravo de Instrumento n\u00ba 2263639-76.2020.8.26.0000 se l\u00ea o seguinte:<\/h5>\n<h5 style=\"text-align: justify;\">\u201cTal restri\u00e7\u00e3o \u00e0 publicidade obsta o conhecimento e o controle social sobre temas relevant\u00edssimos, inclusive por pessoas relacionadas de forma direta ou indireta com o lit\u00edgio (como, por exemplo, os acionistas de companhias abertas), em raz\u00e3o da absoluta falta de acesso aos processos e aos provimentos jurisdicionais, seguido pela absoluta falta de acesso aos procedimentos arbitrais\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Al\u00e9m disso, haveria o interesse geral no conhecimento da \u201cforma pela qual as normas abstratas s\u00e3o concretizadas\u201d, pois\u00a0<em>\u201cos jurisdicionados t\u00eam o direito de conhecer a jurisprud\u00eancia; os empres\u00e1rios, especificamente, o de antever, pela coer\u00eancia que sempre se espera dos que t\u00eam a nobre miss\u00e3o de julgar, o prov\u00e1vel resultado dos veredictos, levando-o em considera\u00e7\u00e3o ao celebrar os neg\u00f3cios mercantis\u201d<\/em>\u00a0(Agravo de Instrumento n. 2263639-76.2020.8.26.0000).<\/h5>\n<h5 style=\"text-align: justify;\">O segundo elemento argumentativo se refere \u00e0 cria\u00e7\u00e3o de privil\u00e9gios para os profissionais que atuam em uma arbitragem espec\u00edfica. Nesse sentido, por exemplo, afirma-se que a publicidade restrita<em>\u00a0\u201csem razoabilidade, gera situa\u00e7\u00e3o favor\u00e1vel aos pouqu\u00edssimos que t\u00eam acesso \u00e0s informa\u00e7\u00f5es socialmente t\u00e3o relevantes\u201d<\/em>\u00a0(Agravo de Instrumento n\u00ba 2263639-76.2020.8.26.0000).<\/h5>\n<h5 style=\"text-align: justify;\">O terceiro aspecto seria a da cria\u00e7\u00e3o de um regime especial para a arbitragem, diferente do judicial, j\u00e1 que \u201cdiante do mesmo lit\u00edgio, sem previs\u00e3o de arbitragem, eventual cl\u00e1usula de confidencialidade provavelmente seria insuficiente para que fosse determinado segredo de justi\u00e7a\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Por fim, o quarto argumento se refere \u00e0 falta da presen\u00e7a de \u201cintimidade\u201d ou \u201cinteresse social\u201d nas causas arbitrais comerciais, nas quais os interesses em jogo s\u00e3o particulares, bem como as pr\u00f3prias vantagens da confidencialidade. Deste modo, a hip\u00f3tese restritiva posta pela Constitui\u00e7\u00e3o Federal seria desrespeitada, impedindo a pr\u00f3pria validade do inciso IV do Artigo 189 do CPC.<\/h5>\n<h5 style=\"text-align: justify;\">Al\u00e9m do \u00f3bvio peso da pena dos desembargadores paulistas, trata-se de linha argumentativa interessante e sofisticada e, como tal, merece an\u00e1lise cuidadosa. Para tanto \u00e9 preciso, de in\u00edcio, compreender o sentido normativo da disposi\u00e7\u00e3o constitucional para, ent\u00e3o, discutir a sem\u00e2ntica das hip\u00f3teses que aventa, particularmente a \u201cintimidade\u201d e o \u201cinteresse social\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Trata-se de norma primariamente direcionada ao legislador, cuja atividade deve ser norteada pelo car\u00e1ter excepcional da publicidade restrita e promulgar leis em conformidade com as restri\u00e7\u00f5es constitucionais. Em termos l\u00f3gicos, o dispositivo 1) estabelece a publicidade do processo como regra para, ent\u00e3o, 2) admitir que a lei possa restringir a publicidade, o que,\u00a0<em>i. a.<\/em>\u00a0estabelece um padr\u00e3o de legalidade estrita, n\u00e3o cabendo tal cond\u00e3o a qualquer outro tipo de norma e 3) fixar um limite teleol\u00f3gico \u00e0 atua\u00e7\u00e3o do pr\u00f3prio legislador, pois a restri\u00e7\u00e3o \u00e0 publicidade deve ser necess\u00e1ria \u00e0 prote\u00e7\u00e3o da intimidade ou do interesse p\u00fablico. A discuss\u00e3o sobre a constitucionalidade Artigo 189, IV, do CPC se d\u00e1 nesse \u00faltimo aspecto, caso em que a intimidade n\u00e3o desempenha um papel relevante.<\/h5>\n<h5 style=\"text-align: justify;\">Desse modo, a aplica\u00e7\u00e3o judicial do ditame constitucional em face da regra do CPC pode ocorrer por duas vias: 1) a verifica\u00e7\u00e3o, concentrada ou difusa, da constitucionalidade do dispositivo em raz\u00e3o da falta de adequa\u00e7\u00e3o aos objetivos de prote\u00e7\u00e3o do interesse p\u00fablico e 2) a pondera\u00e7\u00e3o na aplica\u00e7\u00e3o caso a caso da norma legal em raz\u00e3o das exig\u00eancias da CF, inclusive no sentido de, eventualmente, denegar o segredo de justi\u00e7a.<\/h5>\n<h5 style=\"text-align: justify;\">A op\u00e7\u00e3o do Judici\u00e1rio paulista, ao menos no Agravo de Instrumento n\u00ba 2263639-76.2020.8.26.0000, foi pela primeira alternativa. Em vez de realizar uma pondera\u00e7\u00e3o casu\u00edstica, os magistrados optaram por estender um campo de tens\u00e3o entre o interesse p\u00fablico no segredo e na publicidade, oferecendo argumentos em favor do segundo: formar e difundir a jurisprud\u00eancia arbitral, evitar o favorecimento de um conjunto restrito de advogados e \u00e1rbitros, equiparar o processo arbitral ao judicial e a inexist\u00eancia de interesse p\u00fablico a ser protegido nas causas arbitrais, pois essas seriam precipuamente privadas.<\/h5>\n<h5 style=\"text-align: justify;\">N\u00e3o \u00e9 o caso, aqui, de tratar isoladamente cada um dos aspectos aventados, apesar das eventuais fragilidades pass\u00edveis de serem apontadas. Importa, por\u00e9m, destacar a exist\u00eancia de um sofisma no \u00faltimo argumento: o texto constitucional n\u00e3o fala do \u201cinteresse p\u00fablico\u201d como objeto do processo, mas da sua exist\u00eancia como fundamento teleol\u00f3gico da escolha do legislador e, nesse caso, este tem o apoio em justificativas perfeitamente razo\u00e1veis. O interesse p\u00fablico, nesse contexto, \u00e9 o de favorecer a utiliza\u00e7\u00e3o da arbitragem para os lit\u00edgios referentes a quest\u00f5es patrimoniais e dispon\u00edveis. Em particular, o legislador busca n\u00e3o comprometer o sigilo da arbitragem sempre que se necessite do apoio jurisdicional para a realiza\u00e7\u00e3o de um ato que n\u00e3o possa ser ordenado pelos \u00e1rbitros.<\/h5>\n<h5 style=\"text-align: justify;\">Considerando haver vantagens econ\u00f4micas e pr\u00e1ticas, as quais favorecem o desenvolvimento dos neg\u00f3cios privados, a op\u00e7\u00e3o do Legislador se sustenta na busca da efici\u00eancia em uma ordem econ\u00f4mica orientada, ainda que n\u00e3o de modo exclusivo, por um princ\u00edpio de livre iniciativa. N\u00e3o se imagina, obviamente, a possibilidade de manter segredo de justi\u00e7a em arbitragens envolvendo a Administra\u00e7\u00e3o (Lei de Arbitragem, artigo 2\u00ba, \u00a73\u00ba).<\/h5>\n<h5 style=\"text-align: justify;\">\u00c9 evidente que a decis\u00e3o do Tribunal de Justi\u00e7a de S\u00e3o Paulo (TJSP) pode estar correta, como defende Jos\u00e9 Rog\u00e9rio Cruz e Tucci em an\u00e1lise do voto condutor do desembargador Cesar Ciampolini, pois seria\u00a0<em>\u201cefetivado o necess\u00e1rio ju\u00edzo de pondera\u00e7\u00e3o para justificar o decreto de inconstitucionalidade do (\u2026) inciso IV do artigo 189<\/em>[2]<em>\u201d.<\/em>\u00a0N\u00e3o obstante, est\u00e1 longe de ser uma certeza a sua definitiva confirma\u00e7\u00e3o em tribunais superiores.<\/h5>\n<h5 style=\"text-align: justify;\">\u00c9 nesse contexto que o PL 4290\/21 pode ensejar uma boa solu\u00e7\u00e3o, de modo a preservar o interesse p\u00fablico no desenvolvimento da arbitragem como forma de solu\u00e7\u00e3o de lit\u00edgios e, ao mesmo tempo, deixar clara a necessidade da an\u00e1lise\u00a0<em>in casu<\/em>\u00a0para a atribui\u00e7\u00e3o da publicidade limitada. Observe-se a reda\u00e7\u00e3o proposta para o inciso IV:\u00a0<em>\u201cque versem sobre arbitragem inclusive sobre o cumprimento de carta arbitral, desde que a necessidade de confidencialidade estipulada na arbitragem seja comprovada perante o ju\u00edzo, consideradas a privacidade das partes e a prote\u00e7\u00e3o de segredos empresariais\u201d.<\/em><\/h5>\n<h5 style=\"text-align: justify;\">Essa reda\u00e7\u00e3o deixa claro objetivos leg\u00edtimos e de interesse p\u00fablico para a conserva\u00e7\u00e3o da regra de publicidade restrita: a privacidade e os segredos empresariais, sem preju\u00edzo de outras eventuais causas suficientes para delinear a \u201cnecessidade de confidencialidade\u201d. Cabe relembrar: h\u00e1, aqui, interesse p\u00fablico na prote\u00e7\u00e3o de situa\u00e7\u00f5es jur\u00eddicas privadas, o que, ali\u00e1s, \u00e9 pr\u00f3prio de imensas parcelas dos Direitos contempor\u00e2neos.<\/h5>\n<h5 style=\"text-align: justify;\">A interpreta\u00e7\u00e3o desse texto apresenta algumas complexidades, mas ele certamente matiza a concess\u00e3o do segredo de justi\u00e7a. Em especial, \u00e9, pelo menos, muito mais dif\u00edcil argumentar em favor da inconstitucionalidade a uma regra que deixa claramente vinculada a uma aprecia\u00e7\u00e3o judicial circunstanciada a possibilidade de restringir a publicidade do que a de um artigo que, pelo menos hipoteticamente, a exigiria sempre que houvesse prova de acordo de confidencialidade entre as partes. A\u00ed, portanto, a manifesta\u00e7\u00e3o de uma daquelas ironias por meio das quais a realidade tantas vezes nos desafia.<\/h5>\n<h5 style=\"text-align: justify;\">O PL 4290\/21 se encontra, hoje, na Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a da C\u00e2mara dos Deputados. Tem muito ch\u00e3o pela frente, mas talvez valha a pena dedicar alguma aten\u00e7\u00e3o a seu tr\u00e2mite e, at\u00e9 mesmo, a eventuais emendas e modifica\u00e7\u00f5es capazes de promover o interesse p\u00fablico, o qual \u00e9 plenamente consistente com a exist\u00eancia de um regime especial de publicidade restrita para as causas privadas levadas \u00e0 arbitragem.<\/h5>\n<h5 style=\"text-align: justify;\">[1] Veja-se, por exemplo, artigo recente no JOTA: Agravo de Instrumento n. 2263639-76.2020.8.26.0000. Em particular, \u201cNo common law ingl\u00eas atual \u00e9 reconhecido um dever impl\u00edcito de confidencialidade e, em face da din\u00e2mica dos procedimentos e do interesse das partes na arbitragem, ocupa uma posi\u00e7\u00e3o de destaque, inclusive gozando de preced\u00eancia sobre o dever de revela\u00e7\u00e3o (disclosure).\u201d<\/h5>\n<h5 style=\"text-align: justify;\">[2] TUCCI, J. R. C. Inconstitucionalidade do sigilo de processo judicial sobre arbitragem. Consultor Jur\u00eddico, 13 de abril de 2021. Dispon\u00edvel em <a href=\"https:\/\/www.adambrasil.com\/conjur.com.br\/2021-abr-13\/paradoxo-corte-inconstitucionalidade-sigilo-processo-judicial-arbitragem\" target=\"_blank\" rel=\"noopener\">https:\/\/www.conjur.com.br\/2021-abr-13\/paradoxo-corte-inconstitucionalidade-sigilo-processo-judicial-arbitragem<\/a><\/h5>\n<h5 style=\"text-align: justify;\">Por JOS\u00c9 AUGUSTO FONTOURA COSTA \u2013 Professor de Direito do Com\u00e9rcio Internacional da Faculdade de Direito da USP, professor da UniCEUMA (S\u00e3o Lu\u00eds) e da Faculdade de Direito de Sorocaba. Bolsista produtividade CNPq. Advogado. Consultor em Barral, Parente e Pinheiro Advogados.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Jota &#8211; 06\/03\/2022 05:40.<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adambrasil.com\/an\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 interesse p\u00fablico na prote\u00e7\u00e3o de situa\u00e7\u00f5es jur\u00eddicas privadas.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,7,9],"tags":[6,8,10],"_links":{"self":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/10259"}],"collection":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/comments?post=10259"}],"version-history":[{"count":1,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/10259\/revisions"}],"predecessor-version":[{"id":10260,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/posts\/10259\/revisions\/10260"}],"wp:attachment":[{"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/media?parent=10259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/categories?post=10259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sitesadam.com.br\/modelo3\/wp-json\/wp\/v2\/tags?post=10259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}