﻿{"id":9855,"date":"2021-04-26T04:32:00","date_gmt":"2021-04-26T01:32:00","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo\/?p=9855"},"modified":"2021-04-26T04:36:25","modified_gmt":"2021-04-26T01:36:25","slug":"os-dispute-boards-na-nova-lei-de-licitacoes-e-contratos-administrativos","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/os-dispute-boards-na-nova-lei-de-licitacoes-e-contratos-administrativos\/","title":{"rendered":"Os dispute boards na nova Lei de Licita\u00e7\u00f5es e Contratos Administrativos"},"content":{"rendered":"<h5 style=\"text-align: justify;\">No \u00faltimo dia 1\u00ba, foi publicada a nova Lei de Licita\u00e7\u00f5es e Contratos Administrativos, a Lei n\u00ba 14.133\/21, que revoga, na forma prevista do artigo 193 do referido diploma, a Lei de Licita\u00e7\u00f5es anterior (Lei n\u00ba 8.666\/93), a Lei do Preg\u00e3o (Lei 10.520\/02) e parcela da Lei do Regime Diferenciado de Contrata\u00e7\u00f5es P\u00fablicas (Lei n\u00ba 12.462\/11).<\/h5>\n<h5 style=\"text-align: justify;\">O novo texto legal, que entrou em vigor na data de sua publica\u00e7\u00e3o (artigo 194 da Lei n\u00ba 14.133\/21), estabelece normas gerais de licita\u00e7\u00e3o e contrata\u00e7\u00e3o para as Administra\u00e7\u00f5es P\u00fablicas diretas, aut\u00e1rquicas e fundacionais da Uni\u00e3o, dos estados, do Distrito Federal e dos munic\u00edpios, incluindo\u00a0ainda\u00a0os entes descritos nos incisos do artigo 1\u00ba da Lei 14.133\/21. As empresas p\u00fablicas e sociedades de economia mista e suas subsidi\u00e1rias, por sua vez, continuam a ser regidas pela Lei 13.303\/16, n\u00e3o sendo abrangidas pela nova lei (artigo 1\u00ba, \u00a71\u00ba, da Lei 14.133\/21).<\/h5>\n<h5 style=\"text-align: justify;\">Nos seus artigos 151 a 154, a Lei n\u00ba 14.133\/21 disciplina a utiliza\u00e7\u00e3o da concilia\u00e7\u00e3o, media\u00e7\u00e3o, comit\u00ea de resolu\u00e7\u00e3o de disputas (<em>dispute board<\/em>) e arbitragem como meios\u00a0<em>alternativos<\/em>\u00a0de preven\u00e7\u00e3o e resolu\u00e7\u00e3o de controv\u00e9rsias decorrentes de contratos administrativos \u2014 m\u00e9todos esses cuja qualifica\u00e7\u00e3o como alternativos merece questionamento, como adiante se mencionar\u00e1.<\/h5>\n<h5 style=\"text-align: justify;\">Embora se trate de uma novidade na legisla\u00e7\u00e3o de licita\u00e7\u00f5es e contratos administrativos, a utiliza\u00e7\u00e3o dos m\u00e9todos adequados de resolu\u00e7\u00e3o de conflitos nas contrata\u00e7\u00f5es p\u00fablicas j\u00e1 se encontrava positivada em diversas leis especiais, a exemplo do artigo 23-A da Lei de Concess\u00f5es (Lei n\u00ba 8.987\/95); do artigo 11, III, da Lei de Parcerias P\u00fablico Privadas (Lei n\u00ba 11.079\/04); da Lei de Media\u00e7\u00e3o e de Solu\u00e7\u00e3o Alternativa de Disputas na Administra\u00e7\u00e3o P\u00fablica (Lei n\u00ba 13.140\/15); do artigo 1\u00ba, \u00a71\u00ba, da Lei de Arbitragem (Lei n\u00ba 9.307\/96 alterada pela Lei n\u00ba 13.129\/15); entre outras.<\/h5>\n<h5 style=\"text-align: justify;\">O \u00fanico meio de resolu\u00e7\u00e3o de controv\u00e9rsias para contrata\u00e7\u00f5es administrativas citado na Lei n\u00ba 14.133\/21 que n\u00e3o possu\u00eda tratamento normativo no Brasil em n\u00edvel federal\u00a0[1]\u00a0eram os\u00a0<em>dispute boards<\/em>, motivo pelo qual \u2014 considerando a entrada em vigor da Lei n\u00ba 14.133\/21 e sua previs\u00e3o expressa \u2014 decidimos tecer, neste texto, breves coment\u00e1rios acerca do instituto e sua relev\u00e2ncia para a nova lei em vigor.<\/h5>\n<h5 style=\"text-align: justify;\">A doutrina comumente aponta que as primeiras utiliza\u00e7\u00f5es bem-sucedidas do\u00a0<em>dispute board<\/em>\u00a0ocorreram nos Estados Unidos, na d\u00e9cada de 70 do s\u00e9culo 20, especificamente\u00a0no projeto de constru\u00e7\u00e3o do\u00a0<em>Eisenhower Tunnel<\/em>\u00a0(Colorado), do\u00a0<em>Mount Baker Ridge Highway Tunnel<\/em>\u00a0(Seattle, Washington), e do\u00a0<em>Chambers Creek Tunnel<\/em>\u00a0(Tacoma, Washington)[2]\u00a0[3].\u00a0Desde ent\u00e3o, o \u00eaxito na utiliza\u00e7\u00e3o do referido m\u00e9todo de solu\u00e7\u00e3o de conflitos contribuiu para a sua propaga\u00e7\u00e3o nos anos seguintes, principalmente\u00a0em projetos de constru\u00e7\u00e3o nos Estados Unidos e no mundo afora.<\/h5>\n<h5 style=\"text-align: justify;\">No Brasil, o\u00a0<em>dispute board<\/em>\u00a0\u00e9 uma experi\u00eancia jur\u00eddica ainda embrion\u00e1ria. Historicamente, nosso sistema jur\u00eddico sempre priorizou a jurisdi\u00e7\u00e3o estatal em detrimento dos m\u00e9todos ent\u00e3o chamados alternativos de resolu\u00e7\u00e3o de conflitos. Existe um certo apre\u00e7o e uma cultura ainda voltada \u00e0 judicializa\u00e7\u00e3o dos conflitos. Sabe-se, contudo, que esse cen\u00e1rio vem sendo alterado paulatinamente. Assim como a arbitragem superou, ao longo das \u00faltimas d\u00e9cadas, as desconfian\u00e7as existentes desde sua regulamenta\u00e7\u00e3o pela Lei n\u00ba 9.307\/96, \u00e9 poss\u00edvel \u2014 como se ver\u00e1 \u00e0 frente \u2014 trilharmos caminho similar para os\u00a0<em>dispute boards<\/em>\u00a0no Brasil.<\/h5>\n<h5 style=\"text-align: justify;\">Com efeito, o direito fundamental de acesso \u00e0 Justi\u00e7a, consagrado no artigo 5\u00ba, XXXV, da Constitui\u00e7\u00e3o da Rep\u00fablica, assim como positivado entre as normas fundamentais do processo civil no artigo 3\u00ba do C\u00f3digo de Processo Civil, representa n\u00e3o mais unicamente um direito de acesso \u00e0 presta\u00e7\u00e3o jurisdicional justa, mas de acesso \u00e0 solu\u00e7\u00e3o justa para o conflito de interesses. Tanto assim\u00a0que os par\u00e1grafos do mesmo artigo 3\u00ba consagram e estimulam o uso de diversos m\u00e9todos mencionados nos artigos 151 a 154 da Lei n\u00ba 14.133\/21.<\/h5>\n<h5 style=\"text-align: justify;\">Em \u00e2mbito nacional, ainda que de forma t\u00edmida, o\u00a0<em>dispute board<\/em>\u00a0j\u00e1 vem sendo utilizado em alguns projetos de grande magnitude, destacando-se, aqui, para citar alguns exemplos: os contratos para a constru\u00e7\u00e3o da Linha 4 (Amarela) do metr\u00f4 da cidade de S\u00e3o Paulo, os contratos celebrados para reforma dos est\u00e1dios para a Copa do Mundo de 2014, os contratos internacionais relativos aos Jogos Ol\u00edmpicos e Paraol\u00edmpicos de 2016, a parceria p\u00fablico-privada da Rodovia MG-050 e os contratos do trecho Norte do Rodoanel de S\u00e3o Paulo.<\/h5>\n<h5 style=\"text-align: justify;\">Na sua acep\u00e7\u00e3o b\u00e1sica, o\u00a0<em>dispute board<\/em>\u00a0\u00e9 considerado um mecanismo extrajudicial de solu\u00e7\u00e3o e preven\u00e7\u00e3o de conflitos por meio do qual as partes instituem, em geral, na ocasi\u00e3o da celebra\u00e7\u00e3o do contrato, um especialista ou comit\u00ea de especialistas para acompanhar sua execu\u00e7\u00e3o, prevenindo e solucionando eventuais lit\u00edgios decorrentes do referido contrato.<\/h5>\n<h5 style=\"text-align: justify;\">As esp\u00e9cies de\u00a0<em>dispute board<\/em>\u00a0adotadas podem variar, a depender, principalmente, de tr\u00eas fatores: 1) o momento em que o comit\u00ea \u00e9 formado; 2) o grau de vincula\u00e7\u00e3o das decis\u00f5es proferidas pelo comit\u00ea; e 3) a quantidade de membros do comit\u00ea.<\/h5>\n<h5 style=\"text-align: justify;\">No que diz respeito ao momento de forma\u00e7\u00e3o do comit\u00ea, existem duas modalidades. Na primeira, denominada\u00a0<em>standing<\/em>\u00a0<em>dispute board<\/em>, o comit\u00ea \u00e9 formado contemporaneamente \u00e0 celebra\u00e7\u00e3o do contrato e permanece vigente ao longo de toda rela\u00e7\u00e3o contratual. Na segunda, denominada\u00a0<em>dispute board ad hoc<\/em>, o comit\u00ea \u00e9 institu\u00eddo apenas quando surgem controv\u00e9rsias espec\u00edficas no curso do contrato, sendo geralmente extinto ap\u00f3s a prola\u00e7\u00e3o da decis\u00e3o final.<\/h5>\n<h5 style=\"text-align: justify;\">Em rela\u00e7\u00e3o ao grau de vincula\u00e7\u00e3o das decis\u00f5es, h\u00e1 tr\u00eas modalidades. Na primeira, o\u00a0<em>dispute review board,<\/em>\u00a0o comit\u00ea emite recomenda\u00e7\u00f5es n\u00e3o vinculantes \u00e0s partes acerca da controv\u00e9rsia, as quais poder\u00e3o ser revistas por a\u00e7\u00e3o judicial ou arbitragem. Na segunda, o\u00a0<em>dispute adjudication board,<\/em>\u00a0o comit\u00ea emite decis\u00e3o obrigat\u00f3ria \u00e0s partes sobre a controv\u00e9rsia, que se mant\u00e9m vinculante at\u00e9 que obtida eventual decis\u00e3o judicial ou arbitral em sentido contr\u00e1rio. Na terceira, o\u00a0<em>combined dispute board,<\/em>\u00a0h\u00e1 uma combina\u00e7\u00e3o dos dois modelos anteriores, podendo o comit\u00ea emitir tanto recomenda\u00e7\u00f5es n\u00e3o vinculantes como decis\u00f5es vinculantes, a depender do caso.<\/h5>\n<h5 style=\"text-align: justify;\">No que diz respeito \u00e0 quantidade de membros do comit\u00ea, o usual \u00e9 que seja composto por tr\u00eas\u00a0<em>experts<\/em>, mas nada impede a forma\u00e7\u00e3o de um comit\u00ea com apenas um\u00a0<em>expert<\/em>\u00a0\u2014 na realidade, um\u00a0<em>dispute review expert \u2014<\/em>, ou que se acorde um outro n\u00famero de membros, embora a pr\u00e1tica seja incomum.<\/h5>\n<h5 style=\"text-align: justify;\">\u00c9 preciso registrar, contudo, que tais classifica\u00e7\u00f5es \u2014 aqui exaltadas, principalmente, para fins did\u00e1ticos \u2014, n\u00e3o esgotam, de forma alguma, todos os poss\u00edveis modelos de\u00a0<em>dispute board<\/em>, tendo em vista que o referido meio de solu\u00e7\u00e3o de conflitos \u00e9 uma constru\u00e7\u00e3o te\u00f3rica originada, sobretudo, no princ\u00edpio da autonomia da vontade das partes. Com efeito, as peculiaridades de cada\u00a0<em>dispute board<\/em>\u00a0\u2014 composi\u00e7\u00e3o do comit\u00ea, forma de acompanhamento da execu\u00e7\u00e3o do contrato, formato das decis\u00f5es proferidas etc. \u2014 depender\u00e3o, ao cabo, do modo como as partes decidirem disciplinar o instituto em sede contratual, e estas poder\u00e3o customizar o\u00a0<em>dispute board<\/em>\u00a0de acordo com as especificidades da rela\u00e7\u00e3o jur\u00eddica.<\/h5>\n<h5 style=\"text-align: justify;\">De toda forma, atualmente \u00e9 frequente que as partes submetam a regulamenta\u00e7\u00e3o do\u00a0<em>dispute board<\/em>\u00a0previsto em seu contrato a c\u00e2maras especializadas, que j\u00e1 possuem regras preestabelecidas e padronizadas sobre o procedimento. A t\u00edtulo de exemplo, em \u00e2mbito internacional, temos a\u00a0<em>Internacional Chamber of Commerce<\/em>, a\u00a0<em>American Arbitration Association<\/em>\u00a0e a\u00a0<em>Chartered Institute of Arbitrators<\/em>, e, no Brasil, a C\u00e2mara de Com\u00e9rcio Brasil-Canad\u00e1 e a C\u00e2mara de Arbitragem Empresarial &#8211;\u00a0Brasil.<\/h5>\n<h5 style=\"text-align: justify;\">O sucesso mundial do\u00a0<em>dispute board<\/em>\u00a0pode ser atestado por diversas estat\u00edsticas j\u00e1 produzidas sobre o tema. Mencionam-se, aqui, os dados coletados pela\u00a0<em>Dispute Resolution Board Foundation<\/em>\u00a0\u2014 funda\u00e7\u00e3o norte-americana que fomenta e difunde a utiliza\u00e7\u00e3o dos\u00a0<em>dispute boards.<\/em>\u00a0Segundo a funda\u00e7\u00e3o, dos 2.813 casos que possui catalogados, datados de 1975 a 2017, cujo valor das obras somadas perfazem aproximadamente US$ 277 bilh\u00f5es, h\u00e1 um percentual de sucesso dos lit\u00edgios \u2014 medido pela n\u00e3o recorribilidade \u00e0s vias externas, como arbitragem ou Poder Judici\u00e1rio \u2014 de mais de 90{23150cbf97a59fadc191e6718a7d18c5ddd7ea825d2151cbc27fca75900c00db}\u00a0[4].<\/h5>\n<h5 style=\"text-align: justify;\">Como j\u00e1 dito, o\u00a0<em>dispute board<\/em>\u00a0foi concebido e desenvolvido essencialmente em contratos de constru\u00e7\u00e3o. Conforme afirma Gilberto Vaz\u00a0[5], o fato de se tratar de acordos de trato sucessivo, com tempos de execu\u00e7\u00e3o especialmente dilatados, torna esses contratos prop\u00edcios para o surgimento de controv\u00e9rsias. H\u00e1, ainda, segundo o autor, a complexidade e a multiplicidade de saberes t\u00e9cnicos envolvidos numa obra, aliado \u00e0 influ\u00eancia de fatores naturais de previsibilidade problem\u00e1ticos, os quais igualmente contribuem para o aparecimento recorrente de conflitos. Da\u00ed a frequente ado\u00e7\u00e3o, em \u00e2mbito internacional, do\u00a0<em>dispute board,<\/em>\u00a0que, de forma \u00e1gil, especializada e imparcial, resolve e previne diverg\u00eancias decorrentes do contrato.<\/h5>\n<h5 style=\"text-align: justify;\">Acreditamos que, igualmente para os contratos administrativos regidos pela Lei 14.133\/21, a previs\u00e3o do\u00a0<em>dispute board<\/em>\u00a0pode ser uma escolha bem-sucedida, tanto para o particular como para a Administra\u00e7\u00e3o P\u00fablica.<\/h5>\n<h5 style=\"text-align: justify;\">O instituto tem uma s\u00e9rie de vantagens em rela\u00e7\u00e3o aos demais mecanismos alternativos de resolu\u00e7\u00e3o e preven\u00e7\u00e3o de conflitos.<\/h5>\n<h5 style=\"text-align: justify;\">A primeira \u00e9 que o comit\u00ea, geralmente institu\u00eddo no in\u00edcio da rela\u00e7\u00e3o contratual, acompanha toda a execu\u00e7\u00e3o do contrato, permitindo-o solucionar as quest\u00f5es que surgem agilmente, a tempo dos fatos. Essa circunst\u00e2ncia evita o escalonamento do conflito, e, consequentemente, a interrup\u00e7\u00e3o ou inviabilidade de execu\u00e7\u00e3o do projeto, muitas vezes geradas por diverg\u00eancias n\u00e3o resolvidas.<\/h5>\n<h5 style=\"text-align: justify;\">O objetivo do comit\u00ea, vale frisar, \u00e9 resolver qualquer tipo de diverg\u00eancia, de modo c\u00e9lere e visando \u00e0 continuidade do cumprimento do contrato. O\u00a0<em>dispute board<\/em>, portanto, acaba por manter a rela\u00e7\u00e3o das partes mais harm\u00f4nica e construtiva, ao menos ao longo do contrato, poupando-as, em princ\u00edpio, de desgastes e preju\u00edzos financeiros decorrentes, direta ou indiretamente, de lit\u00edgios levados ao Poder Judici\u00e1rio e arbitragem.<\/h5>\n<h5 style=\"text-align: justify;\">A segunda vantagem \u00e9 que os integrantes do comit\u00ea \u2014 pela experi\u00eancia internacional, comumente formado por dois engenheiros e um advogado \u2014 s\u00e3o especialistas na mat\u00e9ria objeto do contrato, tanto o aspecto t\u00e9cnico como o jur\u00eddico, al\u00e9m de terem familiaridade com as condi\u00e7\u00f5es do contrato e os respons\u00e1veis por sua execu\u00e7\u00e3o, o que favorece a prola\u00e7\u00e3o de decis\u00f5es qualificadas.<\/h5>\n<h5 style=\"text-align: justify;\">A terceira vantagem s\u00e3o os custos inerentes ao\u00a0<em>dispute board<\/em>. Dados do\u00a0<em>Dispute Board Foundation<\/em>\u00a0demonstram que o custo de um conflito resolvido por\u00a0<em>dispute board<\/em>\u00a0\u00e9 em torno de 0,05{23150cbf97a59fadc191e6718a7d18c5ddd7ea825d2151cbc27fca75900c00db} a 0,25{23150cbf97a59fadc191e6718a7d18c5ddd7ea825d2151cbc27fca75900c00db} do custo final da obra\u00a0[6], o que corresponde a uma despesa baixa, caso comparado, por exemplo, \u00e0 arbitragem. Al\u00e9m disso, salienta-se que, em regra, as partes dividem igualmente os custos para pagamento do trabalho executado pelo comit\u00ea.<\/h5>\n<h5 style=\"text-align: justify;\">Uma circunst\u00e2ncia estimulante para o uso do\u00a0<em>dispute board<\/em>, especificamente para os contratos administrativos, \u00e9 o fato de que esse m\u00e9todo de solu\u00e7\u00e3o de conflitos, como antes mencionado, \u00e9 altamente recomendado para o setor de constru\u00e7\u00e3o, que, no Brasil, como se sabe, tem \u00edntima rela\u00e7\u00e3o com a esfera p\u00fablica. Por vezes, obras de infraestrutura brasileiras \u2014 constru\u00e7\u00e3o de estradas, usinas de gera\u00e7\u00e3o de energia, sistemas de saneamento etc. \u2014, possuem v\u00ednculo com o Estado, seja por meio de contrata\u00e7\u00f5es diretas, financiamentos ou esquemas de parceria, entre a Administra\u00e7\u00e3o P\u00fablica e particulares\u00a0[7]. Nesse sentido, em outras palavras, o nosso setor p\u00fablico \u00e9 um campo f\u00e9rtil e privilegiado para a utiliza\u00e7\u00e3o dos\u00a0<em>dispute boards.<\/em><\/h5>\n<h5 style=\"text-align: justify;\">Portanto, como se nota, as perspectivas para o uso dos\u00a0<em>disputes boards<\/em>\u00a0nos contratos administrativos regidos pela Lei n\u00ba 14.133\/21 s\u00e3o promissoras, seja em raz\u00e3o da nova previs\u00e3o expressa na legisla\u00e7\u00e3o \u2014 que confirma tend\u00eancia do ordenamento jur\u00eddico brasileiro em autorizar e incentivar outros m\u00e9todos de solu\u00e7\u00e3o de conflitos no \u00e2mbito p\u00fablico \u2014, seja em raz\u00e3o das vantagens, anteriormente mencionadas, oferecidas pelo instituto.<\/h5>\n<h5 style=\"text-align: justify;\">N\u00e3o custa registrar que o uso do\u00a0<em>dispute board,<\/em>\u00a0em outras esp\u00e9cies de contratos administrativos, disciplinadas ou n\u00e3o pela Lei n\u00ba 14.133\/21, tamb\u00e9m pode ser vantajoso \u00e0s partes, a exemplo dos contratos de concess\u00e3o, de presta\u00e7\u00e3o de servi\u00e7o e de fornecimento de longo prazo. Afinal, tais esp\u00e9cies de contratos podem envolver assuntos de alta complexidade t\u00e9cnica, possuir per\u00edodos longos de vig\u00eancia, bem como podem ser alvo constante de atrasos na execu\u00e7\u00e3o do contrato, que acabam por ocasionar preju\u00edzos em cadeia a uma s\u00e9rie de agentes. Todas essas caracter\u00edsticas citadas tornam a disponibilidade imediata de um comit\u00ea especialista na mat\u00e9ria tamb\u00e9m atraente para esses contratos.<\/h5>\n<h5 style=\"text-align: justify;\">No que diz respeito \u00e0 regulariza\u00e7\u00e3o do\u00a0<em>dispute<\/em>\u00a0<em>board<\/em>\u00a0na Lei 14.133\/21, veja-se que, apesar de louv\u00e1vel a sua men\u00e7\u00e3o expressa, o legislador n\u00e3o aprofundou a disciplina normativa do instituto, tendo estabelecido regras gen\u00e9ricas nos artigos 151 a 154. No entanto, isso n\u00e3o deve ser visto como um ponto negativo da lei. Assim como existem as Leis n\u00ba\u00a09.307\/96 e n\u00ba 13.140\/15, disciplinando a arbitragem e a media\u00e7\u00e3o, certamente vir\u00e1 legisla\u00e7\u00e3o pr\u00f3pria para tratar do\u00a0<em>dispute board<\/em>.<\/h5>\n<h5 style=\"text-align: justify;\">Atualmente, ali\u00e1s, existem em tr\u00e2mite dois projetos de lei sobre o assunto: o Projeto de Lei n\u00ba 9.883\/18, da C\u00e2mara dos Deputados, que disp\u00f5e do uso dos\u00a0<em>disputes boards<\/em>\u00a0em contratos administrativos em n\u00edvel nacional, e o Projeto de Lei n\u00ba 206\/18, do Senado Federal, que regulamenta a instala\u00e7\u00e3o dos\u00a0<em>dispute boards<\/em>\u00a0em contratos administrativos continuados celebrados pela Uni\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">Diante de todo o exposto, vemos com otimismo o uso do\u00a0<em>dispute board<\/em>\u00a0nos contratos administrativos disciplinados pela Lei 14.133\/21, como mecanismos de amplia\u00e7\u00e3o de efici\u00eancia, celeridade, qualidade das decis\u00f5es proferidas e seguran\u00e7a jur\u00eddica na solu\u00e7\u00e3o de lit\u00edgios no \u00e2mbito p\u00fablico.<\/h5>\n<h5 style=\"text-align: justify;\">[1]\u00a0Fez-se refer\u00eancia ao\u00a0<em>dispute board<\/em>\u00a0como novidade na esfera da legisla\u00e7\u00e3o federal, tendo em vista que, em n\u00edvel municipal, por exemplo, desde 2018, est\u00e1 em vigor, no munic\u00edpio de S\u00e3o Paulo, a Lei n\u00ba 16.873 \u2014 posteriormente regulamentada pelo Decreto n\u00ba 60.067\/21 \u2014, que regulamenta a instala\u00e7\u00e3o dos Comit\u00eas de Preven\u00e7\u00e3o e Solu\u00e7\u00e3o de Disputas em contratos administrativos continuados celebrados pela Prefeitura de S\u00e3o Paulo.<\/h5>\n<h5 style=\"text-align: justify;\">[2]\u00a0RANZOLIN, Ricardo. A efic\u00e1cia dos dispute boards no Direito brasileiro. Revista de Arbitragem e Media\u00e7\u00e3o, vol. 52, p. 197-219, jan.-mar.2017.<\/h5>\n<h5 style=\"text-align: justify;\">[3]\u00a0\u00c9 necess\u00e1rio mencionar, no entanto, que h\u00e1 autores, como Cyril Chern e Michael Kamprath, que afirmam que o\u00a0<em>dispute board<\/em>\u00a0tem origem anterior, na d\u00e9cada de 60, na constru\u00e7\u00e3o do Boundary Dam, em Washington (CHERN, Cyril.\u00a0Chern on dispute boards: practice and procedure. 3\u00aa. ed. New York: Informa Law from Routledge, 2015. p. 11).<\/h5>\n<h5 style=\"text-align: justify;\">[4]\u00a0MACHADO, Matheus Oliveira. A aplicabilidade dos dispute boards no Regime Diferenciado de Contrata\u00e7\u00f5es P\u00fablicas (RDC).\u00a0 Revista de doutrina e jurisprud\u00eancia. 54. Bras\u00edlia. p. 12-31, jul.-dez. 2018.<\/h5>\n<h5 style=\"text-align: justify;\">[5]\u00a0VAZ, Gilberto Vaz. Os dispute boards e os contratos administrativos: s\u00e3o os DBS uma boa solu\u00e7\u00e3o para disputas sujeitas a normas de ordem p\u00fablica? Revista de Arbitragem e Media\u00e7\u00e3o, vol. 38, p. 131-147, jul-set. 2013.<\/h5>\n<h5 style=\"text-align: justify;\">[6]\u00a0DOS SANTOS, Carolina Mallman Tallamani. Dispute boards: maximiza\u00e7\u00e3o da efici\u00eancia no procedimento pr\u00e9-arbitral em contratos de constru\u00e7\u00e3o.\u00a0 Revista de Arbitragem e Media\u00e7\u00e3o, vol. 56, p. 243-261, jul.-set. 2018.<\/h5>\n<h5 style=\"text-align: justify;\">[7]\u00a0VAZ, Gilberto Vaz. Os dispute boards e os contratos administrativos: s\u00e3o os DBS uma boa solu\u00e7\u00e3o para disputas sujeitas a normas de ordem p\u00fablica? Revista de Arbitragem e Media\u00e7\u00e3o, vol. 38, p. 131-147, jul.-set. 2013.<\/h5>\n<h5 style=\"text-align: justify;\">Por Marco Antonio Rodrigues \u00e9 professor adjunto de Direito Processual Civil da Uerj, procurador do Estado do Rio de Janeiro, s\u00f3cio de LDCM Advogados, p\u00f3s-doutor pela Universidade de Coimbra\/Portugal, doutor em Direito Processual e mestre em Direito P\u00fablico pela Uerj, master of Laws pela King\u2019s College London, professor de cursos de p\u00f3s-gradua\u00e7\u00e3o pelo Brasil e membro da International Association of Procedural Law, do Instituto Ibero-Americano de Direito Processual e do Instituto Brasileiro de Direito Processual. E Felipe Varela Mello, advogado e mestrando em Direito Processual na UERJ.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Revista Consultor Jur\u00eddico, 20 de abril de 2021, 15h09<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Diante de todo o exposto, vemos com otimismo o uso do\u00a0dispute board\u00a0nos contratos administrativos disciplinados pela Lei 14.133\/21, como mecanismos de amplia\u00e7\u00e3o de efici\u00eancia, celeridade, qualidade das decis\u00f5es proferidas e seguran\u00e7a jur\u00eddica na solu\u00e7\u00e3o de lit\u00edgios no \u00e2mbito p\u00fablico.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,18,16,14],"tags":[11,13,19,17,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/9855"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=9855"}],"version-history":[{"count":1,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/9855\/revisions"}],"predecessor-version":[{"id":9856,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/9855\/revisions\/9856"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=9855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=9855"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=9855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}