﻿{"id":9658,"date":"2019-09-12T14:40:00","date_gmt":"2019-09-12T14:40:00","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo\/?p=9658"},"modified":"2019-09-12T17:10:08","modified_gmt":"2019-09-12T17:10:08","slug":"rcsc-2019-revista-catarinense-de-solucao-de-conflitos","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/rcsc-2019-revista-catarinense-de-solucao-de-conflitos\/","title":{"rendered":"RCSC 2019 \u2013 Revista Catarinense de Solu\u00e7\u00e3o de Conflitos"},"content":{"rendered":"<h5><a href=\"http:\/\/www.adamsistemas.com\/wp-content\/uploads\/rcsc_2019_adam.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-full wp-image-3653\" src=\"http:\/\/www.adamsistemas.com\/wp-content\/uploads\/icone_pdf.png\" alt=\"icone_pdf\" width=\"50\" height=\"50\" \/><\/a>\u00a0<a href=\"http:\/\/www.adamsistemas.com\/wp-content\/uploads\/rcsc_2019_adam.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Clique aqui<\/a> para baixar ou visualizar o arquivo.<\/h5>\n<div style=\"left: 0px; width: 100{a50adec798dbc0f88b3eabe56cf473735b25450c039c40948cf77e66b9d395ab}; height: 0px; position: relative; padding-bottom: 75{a50adec798dbc0f88b3eabe56cf473735b25450c039c40948cf77e66b9d395ab};\">\n<div data-url=\"https:\/\/issuu.com\/adamsistemas\/docs\/rcsc_2019_adam\" style=\"top: 0px; left: 0px; width: 100{a50adec798dbc0f88b3eabe56cf473735b25450c039c40948cf77e66b9d395ab}; height: 100{a50adec798dbc0f88b3eabe56cf473735b25450c039c40948cf77e66b9d395ab}; position: absolute;\" class=\"issuuembed\"><\/div>\n<p><script type=\"text\/javascript\" src=\"\/\/e.issuu.com\/embed.js\" async=\"true\"><\/script><\/div>\n<\/p>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Essa \u00e9 a s\u00e9tima edi\u00e7\u00e3o da RCSC (Revista Catarinense de Solu\u00e7\u00e3o de Conflitos), uma publica\u00e7\u00e3o que busca trazer informa\u00e7\u00f5es e novidades para profissionais, especialistas, professores, acad\u00eamicos e entusiastas dos MASCs (M\u00e9todos Adequados de Solu\u00e7\u00e3o de Conflitos)<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,18,16,14],"tags":[11,13,19,17,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/9658"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=9658"}],"version-history":[{"count":1,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/9658\/revisions"}],"predecessor-version":[{"id":9659,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/9658\/revisions\/9659"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=9658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=9658"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=9658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}