﻿{"id":9552,"date":"2020-02-26T23:50:00","date_gmt":"2020-02-27T02:50:00","guid":{"rendered":"http:\/\/testesadam.web7005.uni5.net\/modelo\/?p=9552"},"modified":"2020-02-26T23:50:00","modified_gmt":"2020-02-27T02:50:00","slug":"conflito-de-interesses-quando-quase-tudo-e-levado-a-justica","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/conflito-de-interesses-quando-quase-tudo-e-levado-a-justica\/","title":{"rendered":"Conflito de interesses: quando quase tudo \u00e9 levado \u00e0 Justi\u00e7a!"},"content":{"rendered":"<h5 style=\"text-align: justify;\">Em plena \u00e9poca de carnaval, onde em boa parte do pa\u00eds \u00e9 s\u00f3 festa, vamos falar de outra face de nossa popula\u00e7\u00e3o, sobretudo do grande n\u00famero de pessoas que integram o mundo jur\u00eddico-processual e comp\u00f5em o crescente fluxo de processos judiciais.<\/h5>\n<h5 style=\"text-align: justify;\">\u00c9 cedi\u00e7o que nossa viv\u00eancia em sociedade \u00e9 pautada em direitos e deveres, uma vez que \u00e9 atribu\u00edda ao Estado a titularidade para nos assegurar e efetivar os direitos fundamentais postos, em primeira m\u00e3o, na Constitui\u00e7\u00e3o Federal. No bojo de tais direitos, encontramos o direito \u00e0 a\u00e7\u00e3o, o qual possibilita a busca por uma tutela jurisdicional, ou seja, a concretiza\u00e7\u00e3o do interesse que n\u00e3o foi alcan\u00e7ado pela via amig\u00e1vel, seja em uma rela\u00e7\u00e3o envolvendo pessoas f\u00edsicas ou jur\u00eddicas.<\/h5>\n<h5 style=\"text-align: justify;\">Ao tempo que se busca na justi\u00e7a pretens\u00f5es ou direitos, a efetiva\u00e7\u00e3o destes nem sempre \u00e9 c\u00e9lere, e s\u00e3o in\u00fameras as causas que permeiam tal realidade, conforme abordaremos.<\/h5>\n<h5 style=\"text-align: justify;\">Quando exercemos nosso direito de a\u00e7\u00e3o e buscamos junto ao Poder Judici\u00e1rio a solu\u00e7\u00e3o de um conflito, incumbimos ao Estado, na pessoa do Juiz, a fun\u00e7\u00e3o de dizer o direito naquele caso concreto, assim, o meio pelo qual a chamada tutela ser\u00e1 entregue \u00e9 o processo judicial, este, com o objetivo de ter uma dura\u00e7\u00e3o razo\u00e1vel, isto \u00e9, ser julgado dentro de um per\u00edodo em que tenha efetividade no direito do vencedor.<\/h5>\n<h5 style=\"text-align: justify;\">No entanto, quando o tempo se torna inimigo das partes no processo, impulsionado e julgado em ritmo mais lento que o esperado, sendo a demora um problema a mais na vida das pessoas, come\u00e7a-se ent\u00e3o elencar as in\u00fameras causas deste cen\u00e1rio.<\/h5>\n<h5 style=\"text-align: justify;\">Em primeiro lugar, importante dizer que, nos \u00faltimos tempos, o n\u00famero de demandas judiciais, de um modo geral, aumentou consideravelmente, a estrutura judicial, por outro lado, n\u00e3o acompanhou este crescimento, est\u00e1 a\u00ed um dos impasses, eis que faltam servidores para dar conta de tanto trabalho.<\/h5>\n<h5 style=\"text-align: justify;\">Outras situa\u00e7\u00f5es giram ao redor da demora no t\u00e9rmino de alguns processos, tais como in\u00fameros recursos poss\u00edveis no ordenamento, ineficiente atua\u00e7\u00e3o do executivo, ali\u00e1s, por ironia, o Estado \u00e9 um dos grandes \u201cclientes\u201d do Judici\u00e1rio, levando a busca em ju\u00edzo por direitos fundamentais dos cidad\u00e3os como sa\u00fade e educa\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">Pontualmente, imperioso expor aqui uma das grandes causas do gigantesco n\u00famero de processos judiciais, concentrada no fato de que muitas das pretens\u00f5es levadas \u00e0 justi\u00e7a n\u00e3o dependeriam da interven\u00e7\u00e3o do Estado.<\/h5>\n<h5 style=\"text-align: justify;\">O fato \u00e9 que, n\u00e3o obstante o direito de a\u00e7\u00e3o e o acesso \u00e0 justi\u00e7a, o que se presencia cotidianamente \u00e9 que as pessoas est\u00e3o tendo uma enorme dificuldade de resolverem por conta pr\u00f3pria quest\u00f5es muitas vezes simples, invocando o juiz a intervir nas rela\u00e7\u00f5es di\u00e1rias e corriqueiras.<\/h5>\n<h5 style=\"text-align: justify;\">Viver em sociedade n\u00e3o \u00e9 t\u00e3o simples, as id\u00e9ias s\u00e3o diferentes, existem conflitos de interesses e nem sempre quando ocorre um desentendimento h\u00e1 um bom senso, um equil\u00edbrio para se chegar a uma resolu\u00e7\u00e3o pac\u00edfica! Deste modo, no \u00e2mbito c\u00edvel, rela\u00e7\u00f5es di\u00e1rias entre vizinhos, parentes, clientes, credores, etc., s\u00e3o postas em ju\u00edzo, para que o juiz ent\u00e3o d\u00ea a chancela final, satisfazendo ou n\u00e3o a pretens\u00e3o do autor.<\/h5>\n<h5 style=\"text-align: justify;\">A pr\u00f3pria correria de todos os dias, o ritmo acelerado, faz com que as pessoas desenvolvam a impaci\u00eancia, a intoler\u00e2ncia nos v\u00e1rios tipos de relacionamentos, fato este que leva ao aumento de conflitos, sejam sociais, familiares, no trabalho, consumeristas, enfim, o di\u00e1logo e a busca amig\u00e1vel por ambos os lados me parece que est\u00e1 se distanciando, de maneira que o processo ainda \u00e9 visto como solu\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">Em n\u00e3o havendo entendimento pelas pr\u00f3prias partes, na busca de uma fuga da demora de um processo, a sistem\u00e1tica jur\u00eddica oferta meios alternativos para a resolu\u00e7\u00e3o de conflitos, j\u00e1 presentes em leis espec\u00edficas, mas exaltado pelo C\u00f3digo de Processo Civil atual, sendo elas a concilia\u00e7\u00e3o, media\u00e7\u00e3o e a arbitragem, institutos estes que contam com a presen\u00e7a de um terceiro, que n\u00e3o o juiz, para intermediar e buscar uma resolu\u00e7\u00e3o r\u00e1pida para o problema enfrentado, objetivando desobstruir a Justi\u00e7a.<\/h5>\n<h5 style=\"text-align: justify;\">Como dito, apesar de ser de direito de todos acessar a Justi\u00e7a, h\u00e1 que se colocar em mente que a cultura de levar \u201cquase tudo\u201d ao juiz deveria ser substitu\u00edda, sempre que poss\u00edvel, pela pacifica\u00e7\u00e3o, meios amig\u00e1veis de solucionar conflitos, pois no fim, o objetivo maior de um processo judicial \u00e9 justamente este: o alcance da paz social, assegurando a seguran\u00e7a jur\u00eddica.<\/h5>\n<h5 style=\"text-align: justify;\">Por M\u00e1rcia Ferreira Alves Pereira, graduada em Direito pela Unoesc de Xanxer\u00ea. P\u00f3s-graduada em Direito Processual Civil pela Uninter e p\u00f3s-graduanda em Direito Processual Penal pela Dam\u00e1sio Educacional. Atualmente, \u00e9 residente do Minist\u00e9rio P\u00fablico, na Promotoria de Justi\u00e7a da comarca de Ponte Serrada.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Oeste Mais &#8211;\u00a026\/02\/2020 10:57<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Como dito, apesar de ser de direito de todos acessar a Justi\u00e7a, h\u00e1 que se colocar em mente que a cultura de levar \u201cquase tudo\u201d ao juiz deveria ser substitu\u00edda, sempre que poss\u00edvel, pela pacifica\u00e7\u00e3o, meios amig\u00e1veis de solucionar conflitos, pois no fim, o objetivo maior de um processo judicial \u00e9 justamente este: o alcance da paz social, assegurando a seguran\u00e7a jur\u00eddica.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,18,16,14],"tags":[11,13,19,17,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/9552"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=9552"}],"version-history":[{"count":0,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/9552\/revisions"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=9552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=9552"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=9552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}