﻿{"id":9153,"date":"2017-04-28T16:40:00","date_gmt":"2017-04-28T19:40:00","guid":{"rendered":"http:\/\/testesadam.web2147.uni5.net\/modelo\/?p=9153"},"modified":"2017-04-28T16:40:00","modified_gmt":"2017-04-28T19:40:00","slug":"video-reforma-trabalhista-arbitragem-contrato-de-trabalho","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/video-reforma-trabalhista-arbitragem-contrato-de-trabalho\/","title":{"rendered":"V\u00eddeo &#8211; A Reforma Trabalhista e a Arbitragem no Contrato de Trabalho"},"content":{"rendered":"<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/NicriUP6LGs\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h5 style=\"text-align: justify;\">A Reforma Trabalhista e a Arbitragem. Nesta edi\u00e7\u00e3o, Asdrubal J\u00fanior comenta sobre o texto aprovado na C\u00e2mara dos Deputados da Reforma Trabalhista, na parte que contempla a possibilidade de se prever a Cl\u00e1usula da Arbitragem no Contrato Individual do Trabalho, fazendo a interpreta\u00e7\u00e3o mais adequada do texto, e analisando tamb\u00e9m a possibilidade de utiliza\u00e7\u00e3o da Arbitragem trabalhista mesmo nos casos de remunera\u00e7\u00e3o inferior ao previsto no texto proposto para cria\u00e7\u00e3o do art. 507-A na CLT.<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Nesta edi\u00e7\u00e3o, Asdrubal J\u00fanior comenta sobre o texto aprovado na C\u00e2mara dos Deputados da Reforma Trabalhista, na parte que contempla a possibilidade de se prever a Cl\u00e1usula da Arbitragem no Contrato Individual do Trabalho, fazendo a interpreta\u00e7\u00e3o mais adequada do texto, e analisando tamb\u00e9m a possibilidade de utiliza\u00e7\u00e3o da Arbitragem trabalhista mesmo nos casos de remunera\u00e7\u00e3o inferior ao previsto no texto proposto para cria\u00e7\u00e3o do art. 507-A na CLT.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,14,22],"tags":[11,13,15,23],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/9153"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=9153"}],"version-history":[{"count":0,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/9153\/revisions"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=9153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=9153"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=9153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}