﻿{"id":911,"date":"2016-04-24T23:04:00","date_gmt":"2016-04-25T02:04:00","guid":{"rendered":"http:\/\/testesadam.web2147.uni5.net\/modelo\/?p=911"},"modified":"2016-04-24T23:04:00","modified_gmt":"2016-04-25T02:04:00","slug":"justica-federal-conselho-nacional-de-justica-avaliam-impactos-novo-cpc-em-conciliacao","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/justica-federal-conselho-nacional-de-justica-avaliam-impactos-novo-cpc-em-conciliacao\/","title":{"rendered":"Justi\u00e7a Federal e Conselho Nacional de Justi\u00e7a avaliam impactos do novo CPC em concilia\u00e7\u00e3o"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n<h5 style=\"text-align: justify;\">O Conselho Nacional de Justi\u00e7a (CNJ) e o Conselho da Justi\u00e7a Federal (CJF) realizaram reuni\u00e3o em Bras\u00edlia com representantes de v\u00e1rios \u00f3rg\u00e3os do Poder Judici\u00e1rio e da Administra\u00e7\u00e3o Direta e Indireta para debater sobre as altera\u00e7\u00f5es promovidas pelo novo C\u00f3digo de Processo Civil e pela Lei de Media\u00e7\u00e3o e suas efetiva\u00e7\u00f5es.<\/h5>\n<h5 style=\"text-align: justify;\">A discuss\u00e3o permeou a atua\u00e7\u00e3o dos conciliadores e determinou que para atuar na Justi\u00e7a Federal como mediador estabelece-se a exig\u00eancia de gradua\u00e7\u00e3o em curso superior h\u00e1, pelo menos, dois anos conforme a Lei de Media\u00e7\u00e3o, mas que tal determina\u00e7\u00e3o n\u00e3o dever\u00e1 ser aplicada aos conciliadores, \u201cconsiderando a natureza objetiva dos conflitos sujeitos \u00e0 concilia\u00e7\u00e3o\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">A decis\u00e3o no que tange os conciliadores faz-se como medida a permitir que rec\u00e9m-formados possam inscrever-se nos editais p\u00fablicos para capacita\u00e7\u00e3o de conciliadores no \u00e2mbito da Justi\u00e7a Federal, permitindo o crescimento do n\u00famero desses profissionais no Pa\u00eds. O enunciado foi aprovado por unanimidade pelos participantes da reuni\u00e3o, que dever\u00e3o votar a respeito de outros enunciados sobre a tem\u00e1tica da Concilia\u00e7\u00e3o e Media\u00e7\u00e3o nas pr\u00f3ximas semanas, como, por exemplo, a utiliza\u00e7\u00e3o da concilia\u00e7\u00e3o virtual.<\/h5>\n<h5 style=\"text-align: justify;\">Conselho Nacional de Justi\u00e7a<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Emp\u00f3rio do Direito,\u00a024\/04\/2016<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Nacional de Justi\u00e7a (CNJ) e o Conselho da Justi\u00e7a Federal (CJF) realizaram reuni\u00e3o em Bras\u00edlia com representantes de v\u00e1rios \u00f3rg\u00e3os do Poder Judici\u00e1rio e da Administra\u00e7\u00e3o Direta e Indireta para debater sobre as altera\u00e7\u00f5es promovidas pelo novo C\u00f3digo de Processo Civil e pela Lei de Media\u00e7\u00e3o e suas efetiva\u00e7\u00f5es.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,18,16,14],"tags":[11,19,17,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/911"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=911"}],"version-history":[{"count":0,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/911\/revisions"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=911"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}