﻿{"id":842,"date":"2016-03-04T11:08:00","date_gmt":"2016-03-04T14:08:00","guid":{"rendered":"http:\/\/testesadam.web2147.uni5.net\/modelo\/?p=842"},"modified":"2016-03-04T11:08:00","modified_gmt":"2016-03-04T14:08:00","slug":"video-carlos-forbes-arbitragem-administracao-publica","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/video-carlos-forbes-arbitragem-administracao-publica\/","title":{"rendered":"V\u00eddeo &#8211; Carlos Forbes &#8211; Arbitragem e Administra\u00e7\u00e3o P\u00fablica"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n<p><\/br><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/S3w9FFTp3RI\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><\/br><\/p>\n<h5 style=\"text-align: justify;\">Presidente do Centro de Arbitragem e Media\u00e7\u00e3o da C\u00e2mara de Com\u00e9rcio Brasil-Canad\u00e1, Carlos Suplicy de Figueiredo Forbes, explica que cabe \u00e0s partes decidir a forma como se dar\u00e1 a publicidade do procedimento arbitral que envolver a Administra\u00e7\u00e3o P\u00fablica.<\/h5>\n<p><\/br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presidente do Centro de Arbitragem e Media\u00e7\u00e3o da C\u00e2mara de Com\u00e9rcio Brasil-Canad\u00e1, Carlos Suplicy de Figueiredo Forbes, explica que cabe \u00e0s partes decidir a forma como se dar\u00e1 a publicidade do procedimento arbitral que envolver a Administra\u00e7\u00e3o P\u00fablica.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,14,22],"tags":[11,13,15,23],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/842"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=842"}],"version-history":[{"count":0,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/842\/revisions"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=842"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}