﻿{"id":620,"date":"2014-12-05T15:06:00","date_gmt":"2014-12-05T17:06:00","guid":{"rendered":"http:\/\/www.camab.com.br\/?p=148"},"modified":"2014-12-05T15:06:00","modified_gmt":"2014-12-05T17:06:00","slug":"trabalho-aprova-arbitragem-como-unico-meio-para-resolucao-de-disputas-em-ppp","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/trabalho-aprova-arbitragem-como-unico-meio-para-resolucao-de-disputas-em-ppp\/","title":{"rendered":"Trabalho aprova arbitragem como \u00fanico meio para resolu\u00e7\u00e3o de disputas em PPP"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adamsistemas.com\/adamnews\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n<h5 style=\"text-align: justify;\">A Comiss\u00e3o de Trabalho, de Administra\u00e7\u00e3o e Servi\u00e7o P\u00fablico aprovou, na \u00faltima quarta-feira (12), o Projeto de Lei (PL <a href=\"http:\/\/www2.camara.leg.br\/camaranoticias\/noticias\/DIREITO-E-JUSTICA\/79596-PROJETO-DEFINE-ARBITRAGEM-EM-SOLUCAO-DE-CONFLITOS-NAS-PPPS.html\" target=\"_blank\" rel=\"noopener noreferrer\">5935\/05<\/a>), do ex-deputado Carlos Souza (PP-AM), que fixa a arbitragem como o \u00fanico meio privado admitido na resolu\u00e7\u00e3o de disputas.<\/h5>\n<h5 style=\"text-align: justify;\">O texto altera a Lei <a href=\"http:\/\/www2.camara.leg.br\/legin\/fed\/lei\/2004\/lei-11079-30-dezembro-2004-535279-norma-pl.html\" target=\"_blank\" rel=\"noopener noreferrer\">11079\/04<\/a>, que regulamenta a licita\u00e7\u00e3o e contrata\u00e7\u00e3o de parceria p\u00fablico-privada.<\/h5>\n<h5 style=\"text-align: justify;\">A proposta ainda obriga a ado\u00e7\u00e3o dos procedimentos de arbitragem prescritos por institui\u00e7\u00e3o arbitral ou entidade especializada, com o objetivo de facilitar a participa\u00e7\u00e3o de empresas estrangeiras nas parcerias p\u00fablico privadas (PPP).<\/h5>\n<h5 style=\"text-align: justify;\">Arbitragem<br \/>\nA arbitragem, regulada pela Lei 9307\/96, consiste em modalidade extrajudicial de resolu\u00e7\u00e3o de conflito, na qual um \u00e1rbitro \u00e9 escolhido pelas partes. A decis\u00e3o do \u00e1rbitro tem a mesma for\u00e7a de senten\u00e7a judicial.<\/h5>\n<h5 style=\"text-align: justify;\">O relator, deputado Andr\u00e9 Figueiredo (PDT-CE), foi favor\u00e1vel \u00e0 aprova\u00e7\u00e3o e apresentou altera\u00e7\u00f5es no texto com objetivo de aperfei\u00e7oar a t\u00e9cnica legislativa.<\/h5>\n<h5 style=\"text-align: justify;\">O deputado acredita que, mesmo mantendo a legisla\u00e7\u00e3o atual sobre o tema, o projeto incentiva a pr\u00e1tica segura da arbitragem. \u201cAo adotar os procedimentos de institui\u00e7\u00f5es arbitrais reconhecidas, as pessoas passam a ter maior seguran\u00e7a jur\u00eddica na negocia\u00e7\u00e3o de uma controv\u00e9rsia, evitando manipula\u00e7\u00f5es ou m\u00e1-f\u00e9.\u201d<\/h5>\n<h5 style=\"text-align: justify;\">Tramita\u00e7\u00e3o<br \/>\nO projeto tramita em car\u00e1ter conclusivo e ser\u00e1 analisado ainda pelas comiss\u00f5es de Finan\u00e7as e Tributa\u00e7\u00e3o; e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>\u00cdntegra da proposta:<\/strong><br \/>\n<a href=\"http:\/\/www.camara.gov.br\/internet\/sileg\/Prop_Detalhe.asp?id=300963\" target=\"_blank\" rel=\"noopener noreferrer\">PL-5935\/2005<\/a><\/h5>\n<h5 style=\"text-align: justify;\">Fonte: \u00c2mbito Jur\u00eddico<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>AdamNews &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros! A Comiss\u00e3o de Trabalho, de Administra\u00e7\u00e3o e Servi\u00e7o P\u00fablico aprovou, na \u00faltima quarta-feira (12), o Projeto de Lei (PL 5935\/05), do ex-deputado Carlos Souza (PP-AM), que fixa a arbitragem como &hellip; <a href=\"http:\/\/sitesadam.com.br\/modelo\/trabalho-aprova-arbitragem-como-unico-meio-para-resolucao-de-disputas-em-ppp\/\">Conte\u00fado<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,14],"tags":[11,13,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/620"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=620"}],"version-history":[{"count":0,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/620\/revisions"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=620"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}