﻿{"id":16412,"date":"2025-12-01T10:27:50","date_gmt":"2025-12-01T07:27:50","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo\/?p=16412"},"modified":"2025-12-07T17:33:13","modified_gmt":"2025-12-07T14:33:13","slug":"dispute-boards-prevencao-de-conflitos-e-eficiencia-contratual","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/dispute-boards-prevencao-de-conflitos-e-eficiencia-contratual\/","title":{"rendered":"Dispute boards: preven\u00e7\u00e3o de conflitos e efici\u00eancia contratual"},"content":{"rendered":"<h5 style=\"text-align: justify;\">Com um n\u00famero estimado em 80 milh\u00f5es de processos judiciais em andamento, o Brasil \u00e9 amplamente reconhecido como um pa\u00eds de alta litigiosidade. A morosidade e o custo das disputas judiciais tornam-se, cada vez mais, um fator de risco relevante para grandes neg\u00f3cios, especialmente (mas n\u00e3o apenas) nos setores de infraestrutura, energia e constru\u00e7\u00e3o civil.<\/h5>\n<h5 style=\"text-align: justify;\">Diante desse cen\u00e1rio, as empresas t\u00eam buscado formas mais r\u00e1pidas, t\u00e9cnicas e econ\u00f4micas de resolver controv\u00e9rsias. Al\u00e9m da arbitragem e da media\u00e7\u00e3o, j\u00e1 conhecidas do mercado, ganha for\u00e7a no Brasil um mecanismo amplamente utilizado internacionalmente: o\u00a0<em>dispute board (DB).<\/em><\/h5>\n<h5 style=\"text-align: justify;\">Esse mecanismo consiste em um comit\u00ea permanente formado por profissionais independentes e especializados, que pode ser estabelecido por um contrato para monitorar sua execu\u00e7\u00e3o e prevenir disputas decorrentes de interesses individuais conflitantes das partes. Diferentemente de medidas judiciais ou de procedimento arbitral, a que se recorre ap\u00f3s um lit\u00edgio surgir, a atua\u00e7\u00e3o do DB ocorre de forma preventiva (<em>ex ante<\/em>) e cont\u00ednua, ajudando as partes a evitar o escalonamento de um potencial lit\u00edgio e a eventual judicializa\u00e7\u00e3o ou submiss\u00e3o \u00e0 arbitragem, de forma a garantir o cumprimento do contrato ou manter um projeto comum em seu devido andamento.<\/h5>\n<h5 style=\"text-align: justify;\">Funcionamento do\u00a0<em>dispute board<\/em><\/h5>\n<h5 style=\"text-align: justify;\">Normalmente, o DB \u00e9 composto por tr\u00eas membros: dois especialistas t\u00e9cnicos (cada um indicado por uma das partes) e um presidente, apontado pelos especialistas e escolhido de comum acordo, geralmente com forma\u00e7\u00e3o jur\u00eddica. Esse comit\u00ea acompanha a execu\u00e7\u00e3o do contrato, analisa documentos, realiza visitas peri\u00f3dicas e emite recomenda\u00e7\u00f5es ou decis\u00f5es sobre diverg\u00eancias pontuais.<\/h5>\n<h5 style=\"text-align: justify;\">A grande vantagem \u00e9 que o DB nasce junto com o contrato, sendo institu\u00eddo por cl\u00e1usula espec\u00edfica e formalizado por termo de instaura\u00e7\u00e3o assinado por seus membros e pelas partes. Dessa forma, atua preventivamente desde o in\u00edcio da execu\u00e7\u00e3o contratual, preservando o bom relacionamento entre as partes e garantindo a continuidade do projeto objeto do contrato, mesmo diante de impasses emergentes. Al\u00e9m disso, sua estrutura pode ser adaptada a diversos tipos de contrato e projeto, havendo muita flexibilidade na defini\u00e7\u00e3o de sua atua\u00e7\u00e3o e dos respectivos limites, conforme a vontade das partes.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>Modalidades do\u00a0<em>dispute board<\/em><\/strong><\/h5>\n<h5 style=\"text-align: justify;\">Existem tr\u00eas tipos principais de DB, conforme suas fun\u00e7\u00f5es:<\/h5>\n<h5 style=\"padding-left: 80px; text-align: justify;\">Dispute Review Board (DRB): emite recomenda\u00e7\u00f5es n\u00e3o vinculantes;<br \/>\nDispute Adjudication Board (DAB): emite decis\u00f5es vinculantes, de cumprimento obrigat\u00f3rio;<br \/>\nCombined Dispute Board (CDB): combina recomenda\u00e7\u00f5es e decis\u00f5es, conforme a necessidade.<\/h5>\n<h5 style=\"text-align: justify;\">Independentemente do tipo adotado, o objetivo \u00e9 o mesmo: evitar que diverg\u00eancias t\u00e9cnicas e jur\u00eddicas travem a execu\u00e7\u00e3o do contrato e se transformem em lit\u00edgios onerosos. As partes submetem periodicamente ao comit\u00ea relat\u00f3rios e informa\u00e7\u00f5es sobre a execu\u00e7\u00e3o do contrato e o andamento do projeto acordado, permitindo que o DB identifique e resolva potenciais conflitos antes que causem paralisa\u00e7\u00f5es e outros transtornos.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>Aplica\u00e7\u00f5es e resultados<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">O uso de\u00a0<em>dispute boards<\/em>\u00a0\u00e9 amplamente consolidado em pa\u00edses como os Estados Unidos e o Reino Unido. Desde a d\u00e9cada de 1970, cerca de 90% dos contratos de constru\u00e7\u00e3o norte-americanos incluem cl\u00e1usula de DB. De acordo com a\u00a0<em>Dispute Resolution Board Foundation<\/em>, 99% dos lit\u00edgios surgidos na execu\u00e7\u00e3o desses contratos s\u00e3o resolvidos em menos de 90 dias, evitando custos e atrasos significativos.<\/h5>\n<h5 style=\"text-align: justify;\">No Brasil, o modelo tem sido adotado no \u00e2mbito da constru\u00e7\u00e3o de grandes obras p\u00fablicas e privadas, como da Linha 4-Amarela do Metr\u00f4 de S\u00e3o Paulo e dos est\u00e1dios da Copa do Mundo de 2014. Algumas Prefeituras, como a de S\u00e3o Paulo, j\u00e1 editaram normas municipais que incentivam o uso do mecanismo em licita\u00e7\u00f5es e contratos de infraestrutura. \u00c9 importante ressaltar que, no contexto brasileiro, n\u00e3o h\u00e1 qualquer barreira legal para a implementa\u00e7\u00e3o do DB, que pode ser adotado em qualquer contrato em que as partes considerem conveniente sua utiliza\u00e7\u00e3o, com base na autonomia privada e na liberdade contratual.<\/h5>\n<h5 style=\"text-align: justify;\">O prop\u00f3sito principal do DB \u00e9 manter o contrato vivo, isto \u00e9, garantir que sua execu\u00e7\u00e3o n\u00e3o seja interrompida por lit\u00edgios. O m\u00e9todo oferece:<\/h5>\n<h5 style=\"padding-left: 80px; text-align: justify;\">Celeridade: as diverg\u00eancias s\u00e3o resolvidas em semanas (e n\u00e3o em anos);<br \/>\nEconomia: os custos da atua\u00e7\u00e3o de um DB s\u00e3o muito inferiores aos de um processo judicial ou arbitral, diante do risco reduzido de paralisa\u00e7\u00e3o da execu\u00e7\u00e3o do contrato, o que tamb\u00e9m evita preju\u00edzos a investimento realizados;<br \/>\nTranspar\u00eancia: acompanhamento t\u00e9cnico e cont\u00ednuo da execu\u00e7\u00e3o contratual;<br \/>\nSeguran\u00e7a jur\u00eddica: decis\u00f5es baseadas em crit\u00e9rios t\u00e9cnicos e na boa-f\u00e9 contratual;<br \/>\nPreserva\u00e7\u00e3o de rela\u00e7\u00f5es comerciais: solu\u00e7\u00e3o cooperativa e sem desgaste entre as partes.<\/h5>\n<h5 style=\"text-align: justify;\">Al\u00e9m disso, os custos de manuten\u00e7\u00e3o do DB (normalmente com honor\u00e1rios mensais dos membros e visitas peri\u00f3dicas) s\u00e3o previs\u00edveis e compartilhados. Mesmo no caso de reuni\u00f5es extraordin\u00e1rias ou delibera\u00e7\u00f5es adicionais, o valor total tende a ser significativamente menor do que o custo de uma disputa judicial.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>Papel estrat\u00e9gico do advogado<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">A ado\u00e7\u00e3o de\u00a0<em>dispute boards<\/em>\u00a0tamb\u00e9m transforma o papel do advogado empresarial. Em vez de atuar apenas na fase contenciosa, o profissional passa a ter uma fun\u00e7\u00e3o preventiva e negocial, acompanhando a execu\u00e7\u00e3o do contrato e orientando as partes na constru\u00e7\u00e3o de solu\u00e7\u00f5es consensuais.<\/h5>\n<h5 style=\"text-align: justify;\">Essa mudan\u00e7a de perspectiva refor\u00e7a a import\u00e2ncia de cl\u00e1usulas bem estruturadas e de uma assessoria jur\u00eddica presente desde a concep\u00e7\u00e3o do contrato, garantindo que o DB funcione como um instrumento de governan\u00e7a contratual, e n\u00e3o apenas como uma alternativa ao lit\u00edgio.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>Instrumento de efici\u00eancia e confian\u00e7a<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">O avan\u00e7o dos\u00a0<em>dispute boards<\/em>\u00a0no Brasil representa um movimento de maturidade empresarial. Ao priorizar a preven\u00e7\u00e3o e o di\u00e1logo, as empresas reduzem custos, preservam parcerias e transmitem credibilidade ao mercado e aos investidores.<\/h5>\n<h5 style=\"text-align: justify;\">Mais do que um mecanismo de preven\u00e7\u00e3o e resolu\u00e7\u00e3o de conflitos, o\u00a0<em>dispute board<\/em>\u00a0\u00e9 uma ferramenta de efici\u00eancia, transpar\u00eancia e seguran\u00e7a contratual, atributos indispens\u00e1veis a qualquer neg\u00f3cio que busca sustentabilidade e solidez em um ambiente de alta complexidade.<\/h5>\n<h5 style=\"text-align: justify;\">Por Lorena Geiger Hauser, advogada da Andersen Ball\u00e3o Advocacia e especialista em direito empresarial. E Luciana de Sousa Carboni,\u00a0advogada do escrit\u00f3rio Andersen Ball\u00e3o Advocacia.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Conjur &#8211; 1 de dezembro de 2025, 11h23<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adambrasil.com\/an\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Al\u00e9m da arbitragem e da media\u00e7\u00e3o, j\u00e1 conhecidas do mercado, ganha for\u00e7a no Brasil um mecanismo amplamente utilizado internacionalmente: o dispute board (DB).<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,16,14],"tags":[11,13,17,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16412"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=16412"}],"version-history":[{"count":1,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16412\/revisions"}],"predecessor-version":[{"id":16413,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16412\/revisions\/16413"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=16412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=16412"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=16412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}