﻿{"id":16410,"date":"2025-12-05T10:23:49","date_gmt":"2025-12-05T07:23:49","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo\/?p=16410"},"modified":"2025-12-07T17:27:13","modified_gmt":"2025-12-07T14:27:13","slug":"consequencialismo-e-as-nulidades-nos-contratos-administrativos","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/consequencialismo-e-as-nulidades-nos-contratos-administrativos\/","title":{"rendered":"Consequencialismo e as nulidades nos contratos administrativos"},"content":{"rendered":"<h5 style=\"text-align: justify;\">O conceito de consequencialismo na Administra\u00e7\u00e3o P\u00fablica, fortalecido pela Lei n\u00ba 14.133\/2021, busca mudar a forma de encarar \u2014 e superar \u2014 os v\u00edcios e irregularidades nos contratos administrativos. Diferentemente da abordagem anterior (Lei n\u00ba 8.666\/1993), em que se primava pela aplica\u00e7\u00e3o rigorosa da norma-regra, independentemente das consequ\u00eancias pr\u00e1ticas, o consequencialismo prop\u00f5e que a decis\u00e3o sobre a nulidade de um contrato administrativo deve considerar, de forma ponderada, os impactos das escolhas feitas e as implica\u00e7\u00f5es que elas ter\u00e3o no interesse p\u00fablico.<\/h5>\n<h5 style=\"text-align: justify;\">Este novo modelo de an\u00e1lise reflete uma transi\u00e7\u00e3o do formalismo jur\u00eddico para uma perspectiva mais pragm\u00e1tica e adaptativa, considerando as realidades econ\u00f4micas, sociais e ambientais.<\/h5>\n<h5 style=\"text-align: justify;\">O consequencialismo, portanto, n\u00e3o busca eliminar a aplica\u00e7\u00e3o do Direito ou de qualquer regra jur\u00eddica, mas sim garantir que, ao aplicar as normas, sejam levadas em considera\u00e7\u00e3o as consequ\u00eancias reais das decis\u00f5es administrativas. Isso significa que, ao avaliar a nulidade de um contrato administrativo, deve-se avaliar se o desfazimento do contrato ser\u00e1 mais prejudicial ao interesse p\u00fablico do que a sua manuten\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">A nulidade de um contrato administrativo tem sido um tema de extrema relev\u00e2ncia na Administra\u00e7\u00e3o P\u00fablica, uma vez que a rescis\u00e3o de um contrato pode ter implica\u00e7\u00f5es graves e de longo alcance, especialmente nos considerados de grande porte, como os de obras p\u00fablicas e concess\u00f5es de servi\u00e7os essenciais.<\/h5>\n<h5 style=\"text-align: justify;\"><\/h5>\n<h5 style=\"text-align: justify;\">A Lei n\u00ba 14.133\/2021, ao adotar o consequencialismo, relativiza as nulidades, permitindo que, em determinadas situa\u00e7\u00f5es, um contrato administrativo irregular seja mantido, desde que sua extin\u00e7\u00e3o traga preju\u00edzos maiores \u00e0 Administra\u00e7\u00e3o ou \u00e0 sociedade.<\/h5>\n<h5 style=\"text-align: justify;\">O artigo 147 da Lei n\u00ba 14.133\/2021 estabelece que, no caso de irregularidades no procedimento licitat\u00f3rio ou na execu\u00e7\u00e3o contratual, a decis\u00e3o administrativa sobre a suspens\u00e3o ou anula\u00e7\u00e3o do contrato somente ser\u00e1 tomada quando, necessariamente, represente uma medida de interesse p\u00fablico. A Administra\u00e7\u00e3o P\u00fablica dever\u00e1 avaliar uma s\u00e9rie de fatores, como os impactos econ\u00f4micos, sociais e ambientais, os custos de desmobiliza\u00e7\u00e3o e o impacto sobre os servi\u00e7os p\u00fablicos prestados \u00e0 popula\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">Mudan\u00e7a de paradigma<\/h5>\n<h5 style=\"text-align: justify;\">Este dispositivo legal reflete uma mudan\u00e7a de paradigma, ao fazer com que a Administra\u00e7\u00e3o P\u00fablica atue de maneira mais flex\u00edvel e sens\u00edvel \u00e0s circunst\u00e2ncias concretas de cada caso, n\u00e3o mais se limitando \u00e0 aplica\u00e7\u00e3o da nulidade em casos de irregularidades formais, mas avaliando de maneira pragm\u00e1tica os danos que poderiam ser causados pela paralisa\u00e7\u00e3o ou rescis\u00e3o do contrato.<\/h5>\n<h5 style=\"text-align: justify;\">O consequencialismo adotado pela nova Lei de Licita\u00e7\u00f5es e Contratos Administrativos tamb\u00e9m encontra suporte nos princ\u00edpios da proporcionalidade e da razoabilidade. Antes de declarar a nulidade, a Administra\u00e7\u00e3o P\u00fablica deve sopesar os danos, cotejando os benef\u00edcios decorrentes da manuten\u00e7\u00e3o do contrato.<\/h5>\n<h5 style=\"text-align: justify;\">Esses princ\u00edpios permitem que se tenha uma vis\u00e3o mais equilibrada sobre a aplica\u00e7\u00e3o do Direito, considerando que os administradores p\u00fablicos devem considerar os efeitos pr\u00e1ticos e as consequ\u00eancias sociais e econ\u00f4micas das suas decis\u00f5es, em uma an\u00e1lise de custo-benef\u00edcio.<\/h5>\n<h5 style=\"text-align: justify;\">A decis\u00e3o administrativa, portanto, deve justificar e explicar as raz\u00f5es pelas quais uma medida mais rigorosa, como a nulidade, \u00e9 desnecess\u00e1ria e at\u00e9 contraproducente. A ideia \u00e9 que, em muitas situa\u00e7\u00f5es, a manuten\u00e7\u00e3o do contrato, com a corre\u00e7\u00e3o dos v\u00edcios administrativos ou com a ado\u00e7\u00e3o de outras solu\u00e7\u00f5es consensuais, seja mais ben\u00e9fica ao interesse p\u00fablico do que a simples anula\u00e7\u00e3o e recome\u00e7o do processo.<\/h5>\n<h5 style=\"text-align: justify;\">Diversas decis\u00f5es administrativas e judiciais t\u00eam refletido essa tend\u00eancia de relativiza\u00e7\u00e3o das nulidades. O Superior Tribunal de Justi\u00e7a (STJ), por exemplo, tem adotado uma postura de pondera\u00e7\u00e3o ao analisar a validade de contratos administrativos. Em alguns casos, apesar da constata\u00e7\u00e3o de irregularidades substanciais, a Corte tem optado por permitir o saneamento do contrato, visando garantir que a extin\u00e7\u00e3o do v\u00ednculo n\u00e3o cause preju\u00edzos mais graves ao interesse p\u00fablico.<\/h5>\n<h5 style=\"text-align: justify;\">No caso do Recurso Especial n\u00ba 950.489\/DF, por exemplo, o STJ decidiu que a continuidade dos servi\u00e7os p\u00fablicos essenciais prevalecia sobre a simples anula\u00e7\u00e3o de um contrato que apresentava falhas formais. A Corte entendeu que, ao anular o contrato de concess\u00e3o para servi\u00e7os funer\u00e1rios no Distrito Federal, seriam causados danos \u00e0 popula\u00e7\u00e3o, como a paralisa\u00e7\u00e3o dos servi\u00e7os e o fechamento de postos de trabalho. O tribunal, portanto, optou por permitir a corre\u00e7\u00e3o das irregularidades, mantendo a continuidade do servi\u00e7o e garantindo a seguran\u00e7a jur\u00eddica.<\/h5>\n<h5 style=\"text-align: justify;\">Outra importante inova\u00e7\u00e3o trazida pela Lei n\u00ba 14.133\/2021 \u00e9 a possibilidade de solu\u00e7\u00f5es consensuais (artigo 151) para resolver irregularidades contratuais. Em vez de adotar uma postura unicamente punitiva, a lei abre espa\u00e7o para que a Administra\u00e7\u00e3o P\u00fablica busque solu\u00e7\u00f5es alternativas, como acordos entre as partes ou a ado\u00e7\u00e3o de mecanismos de media\u00e7\u00e3o e arbitragem. Isso contribui para resolver as pend\u00eancias contratuais sem a necessidade de ruptura abrupta do v\u00ednculo, evitando o impacto negativo que a paralisa\u00e7\u00e3o de um contrato pode gerar.<\/h5>\n<h5 style=\"text-align: justify;\">Esse mecanismo \u00e9 especialmente \u00fatil em rela\u00e7\u00e3o aos contratos de grande vulto ou de car\u00e1ter estrat\u00e9gico, como as obras de infraestrutura, em que a simples anula\u00e7\u00e3o pode resultar em grandes custos e at\u00e9 na impossibilidade de execu\u00e7\u00e3o do servi\u00e7o contratado.<\/h5>\n<h5 style=\"text-align: justify;\">Portanto, a incorpora\u00e7\u00e3o do consequencialismo e a relativiza\u00e7\u00e3o das nulidades nos contratos administrativos representam um avan\u00e7o significativo na Administra\u00e7\u00e3o P\u00fablica, permitindo uma gest\u00e3o mais flex\u00edvel e sens\u00edvel \u00e0s consequ\u00eancias das decis\u00f5es administrativas.<\/h5>\n<h5 style=\"text-align: justify;\">Ao priorizar o interesse p\u00fablico e a continuidade dos servi\u00e7os essenciais, a Nova Lei de Licita\u00e7\u00f5es oferece \u00e0 Administra\u00e7\u00e3o P\u00fablica uma ferramenta mais eficaz para lidar com os v\u00edcios contratuais, permitindo a manuten\u00e7\u00e3o dos contratos quando mais ben\u00e9fico for \u00e0 sociedade.<\/h5>\n<h5 style=\"text-align: justify;\">Desse modo, o consequencialismo n\u00e3o significa a impunidade ou a aceita\u00e7\u00e3o de irregularidades, mas sim a pondera\u00e7\u00e3o das consequ\u00eancias dessas irregularidades para decidir qual \u00e9 a melhor solu\u00e7\u00e3o para o interesse p\u00fablico. Essa abordagem promete tornar as contrata\u00e7\u00f5es p\u00fablicas mais eficientes e menos suscet\u00edveis a paralisa\u00e7\u00f5es que causam danos econ\u00f4micos e sociais.<\/h5>\n<h5 style=\"text-align: justify;\">Por Guilherme Carvalho, doutor em Direito Administrativo, mestre em Direito e pol\u00edticas p\u00fablicas, ex-procurador do estado do Amap\u00e1, bacharel em administra\u00e7\u00e3o e s\u00f3cio fundador do escrit\u00f3rio Guilherme Carvalho &amp; Advogados Associados e presidente da Associa\u00e7\u00e3o Brasileira de Direito Administrativo e Econ\u00f4mico (Abradade). E Noel Baratieri, doutor em Direito pela UFSC (Universidade Federal de Santa Catarina), advogado, professor e palestrante.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Conjur &#8211; 5 de dezembro de 2025, 11h23<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adambrasil.com\/an\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Em vez de adotar uma postura unicamente punitiva, a lei abre espa\u00e7o para que a Administra\u00e7\u00e3o P\u00fablica busque solu\u00e7\u00f5es alternativas, como acordos entre as partes ou a ado\u00e7\u00e3o de mecanismos de media\u00e7\u00e3o e arbitragem.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,16,14],"tags":[11,13,17,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16410"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=16410"}],"version-history":[{"count":1,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16410\/revisions"}],"predecessor-version":[{"id":16411,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16410\/revisions\/16411"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=16410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=16410"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=16410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}