﻿{"id":16248,"date":"2024-07-22T10:15:59","date_gmt":"2024-07-22T07:15:59","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo\/?p=16248"},"modified":"2024-08-05T13:22:46","modified_gmt":"2024-08-05T10:22:46","slug":"alexandre-defende-uso-de-ia-em-metodos-de-resolucao-de-conflitos","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/alexandre-defende-uso-de-ia-em-metodos-de-resolucao-de-conflitos\/","title":{"rendered":"Alexandre defende uso de IA em m\u00e9todos de resolu\u00e7\u00e3o de conflitos"},"content":{"rendered":"<h5 style=\"text-align: justify;\">O ministro Alexandre de Moraes, do Supremo Tribunal Federal, defendeu nesta segunda-feira (22\/7), durante evento em S\u00e3o Paulo, o uso de intelig\u00eancia artificial (IA) para auxiliar em novos m\u00e9todos de resolu\u00e7\u00e3o de conflitos. Ele citou como exemplo as plataformas de resolu\u00e7\u00e3o de disputas online (ODRs, na sigla em ingl\u00eas), que promovem \u201cuma esp\u00e9cie de arbitragem\u201d com ajuda da IA e \u201co m\u00ednimo de participa\u00e7\u00e3o humana\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Alexandre destacou que a empresa americana de com\u00e9rcio eletr\u00f4nico eBay possui uma ferramenta do tipo, para resolver quest\u00f5es consumeristas. Mais de 60 milh\u00f5es de disputas por ano passam por esse sistema de ODR, com alt\u00edssimas taxas de resolu\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">De acordo com o magistrado, \u201cseria extremamente salutar\u201d um \u201cmeio de controv\u00e9rsias digital\u201d para resolver casos iguais (que devem ter a mesma decis\u00e3o) ou que envolvam a aplica\u00e7\u00e3o de precedentes vinculantes.<\/h5>\n<h5 style=\"text-align: justify;\">As partes que discordassem do encaminhamento do caso para tal meio poderiam fazer um destaque e apresentar como justificativa um\u00a0<em>distinguishing<\/em>, ou seja, uma distin\u00e7\u00e3o com rela\u00e7\u00e3o ao precedente. Caso essa distin\u00e7\u00e3o n\u00e3o fosse comprovada, haveria uma multa alta.<\/h5>\n<h5 style=\"text-align: justify;\">Tais ideias foram defendidas pelo ministro durante o Semin\u00e1rio Lide \u2014 Justi\u00e7a, promovido pelo Grupo de L\u00edderes Empresariais (Lide). O painel do qual Alexandre participou teve o nome \u201cSolu\u00e7\u00e3o de Controv\u00e9rsias \u2014 Media\u00e7\u00e3o e Arbitragem no Brasil\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Em outro painel no mesmo evento, o constitucionalista e ex-presidente da Rep\u00fablica\u00a0<strong>Michel Temer\u00a0<\/strong>disse que \u201ca arbitragem foi uma evolu\u00e7\u00e3o extraordin\u00e1ria do nosso sistema judici\u00e1rio, pautada justamente pela ideia do encerramento r\u00e1pido da litigiosidade\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Segundo ele, \u201cmuitas vezes se postula uma altera\u00e7\u00e3o legislativa\u201d em uma lei que, na sua vis\u00e3o, \u201cnunca foi contestada\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Solu\u00e7\u00e3o de controv\u00e9rsias<\/h5>\n<h5 style=\"text-align: justify;\">Durante sua palestra, Alexandre tamb\u00e9m afirmou que \u201ca\u00a0primeira grande medida para garantir uma seguran\u00e7a jur\u00eddica maior \u00e9 a mudan\u00e7a de mentalidade de todos, inclusive de quem litiga\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Em complemento, ele defendeu uma mudan\u00e7a de legisla\u00e7\u00e3o para ampliar a puni\u00e7\u00e3o a quem desrespeita precedentes vinculantes ou garantir uma sucumb\u00eancia maior, de forma a dificultar o acesso aos tribunais superiores.<\/h5>\n<h5 style=\"text-align: justify;\">O magistrado ressaltou que nenhuma Justi\u00e7a no mundo garante um acesso t\u00e3o f\u00e1cil a todas as inst\u00e2ncias quanto a brasileira. Da mesma forma, \u201cn\u00e3o h\u00e1 Suprema Corte com acesso t\u00e3o f\u00e1cil quanto a do Brasil\u201d. Esse acesso tamb\u00e9m \u00e9 \u201cextremamente r\u00e1pido\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">O ministro explicou que a Justi\u00e7a brasileira \u00e9 \u201cextremamente barata quando comparada a outros pa\u00edses\u201d. De acordo com ele, escrit\u00f3rios contratam seguros para entrar com recursos na Suprema Corte do Reino Unido.<\/h5>\n<h5 style=\"text-align: justify;\">O principal problema, segundo Alexandre, \u00e9 a \u201cmentalidade litigante\u201d que existe no Brasil. Para ele, uma \u201cmaior seguran\u00e7a jur\u00eddica depende de todos\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">\u201cA iniciativa privada contribui para a inseguran\u00e7a jur\u00eddica\u201d, pontuou o ministro. Isso porque muitas partes \u2014 mesmo quando \u201cj\u00e1 sabem que v\u00e3o perder\u201d \u2014 apresentam embargos, agravos e outros instrumentos jur\u00eddicos para protelar milh\u00f5es de processos com precedentes aplic\u00e1veis j\u00e1 definidos.<\/h5>\n<h5 style=\"text-align: justify;\">Reclama\u00e7\u00f5es e Habeas Corpus s\u00e3o os instrumentos mais utilizados, \u201cem desrespeito aos precedentes\u201d. Al\u00e9m disso, \u201cquando h\u00e1, eventualmente, uma multa por litig\u00e2ncia de m\u00e1-f\u00e9, \u00e9 um esc\u00e2ndalo no Brasil\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Por fim, o magistrado ainda defendeu o\u00a0<a href=\"https:\/\/www.adambrasil.com\/camara.leg.br\/proposicoes\/2300144\" target=\"_blank\" rel=\"noopener noreferrer\">Projeto de Lei 3.293\/2021<\/a>, de autoria da ex-deputada federal Margarete Coelho (PP-PI), para evitar retrocessos na arbitragem.<\/h5>\n<h5 style=\"text-align: justify;\">O texto do PL, segundo Alexandre, prop\u00f5e uma maior transpar\u00eancia na escolha dos \u00e1rbitros, na sua rotatividade e nos fundamentos usados em suas decis\u00f5es, \u201cpara que n\u00e3o se coloque em d\u00favida a arbitragem\u201d.<\/h5>\n<h5 style=\"text-align: justify;\">Tamb\u00e9m participaram do painel o advogado e \u00e1rbitro\u00a0<strong>Paulo Nasser<\/strong>, s\u00f3cio do escrit\u00f3rio M Nasser \u2014 Advocacia Estrat\u00e9gica; a advogada, \u00e1rbitra e mediadora\u00a0<strong>Ana Luiza Nery<\/strong>, s\u00f3cia do Nery Advogados; e o advogado e mediador de disputas empresariais\u00a0<strong>Marcelo Perlman<\/strong>.<\/h5>\n<h5 style=\"text-align: justify;\">Jos\u00e9 Hig\u00eddio, rep\u00f3rter da revista Consultor Jur\u00eddico.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Conjur, 22 de julho de 2024, 17h54<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adambrasil.com\/an\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>O ministro Alexandre de Moraes, do Supremo Tribunal Federal, defendeu nesta segunda-feira (22\/7), durante evento em S\u00e3o Paulo, o uso de intelig\u00eancia artificial (IA) para auxiliar em novos m\u00e9todos de resolu\u00e7\u00e3o de conflitos. <\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,18,16,14],"tags":[11,13,19,17,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16248"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=16248"}],"version-history":[{"count":4,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16248\/revisions"}],"predecessor-version":[{"id":16252,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16248\/revisions\/16252"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=16248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=16248"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=16248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}