﻿{"id":16132,"date":"2023-09-11T10:34:38","date_gmt":"2023-09-11T07:34:38","guid":{"rendered":"https:\/\/sitesadam.com.br\/modelo\/?p=16132"},"modified":"2023-09-18T04:50:30","modified_gmt":"2023-09-18T01:50:30","slug":"o-papel-das-partes-na-producao-das-provas-no-processo-arbitral","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/o-papel-das-partes-na-producao-das-provas-no-processo-arbitral\/","title":{"rendered":"O papel das partes na produ\u00e7\u00e3o das provas no processo arbitral"},"content":{"rendered":"<h5 style=\"text-align: justify;\">Com o advento do Novo C\u00f3digo de Processo Civil, institu\u00eddo pela Lei 13.105, de 16 de mar\u00e7o de 2015, houve uma profunda modifica\u00e7\u00e3o do processo civil e, notadamente, do conceito de acesso \u00e0 justi\u00e7a.<\/h5>\n<h5 style=\"text-align: justify;\">Verificou-se, com o tempo, que a justi\u00e7a estatal n\u00e3o \u00e9 o \u00fanico meio leg\u00edtimo de pacifica\u00e7\u00e3o social de conflitos, e que, apesar da inafastabilidade do controle jurisdicional ser um direito constitucionalmente assegurado\u00a0[1], a justi\u00e7a adequada \u00e9 aquela que oferece uma justi\u00e7a multiportas.<\/h5>\n<h5 style=\"text-align: justify;\">Nesse sentido, conforme esclarecem Didier Junior e Zaneti Junior\u00a0[2]\u00a0<em>&#8220;a solu\u00e7\u00e3o judicial deixa de ter a primazia nos lit\u00edgios que permitem a autocomposi\u00e7\u00e3o e passa a ser a<\/em>\u00a0ultima ratio<em>,<\/em>\u00a0<em>extrema ratio&#8221;<\/em>.<\/h5>\n<h5 style=\"text-align: justify;\">N\u00e3o por acaso o artigo par\u00e1grafo primeiro do artigo 3\u00ba do C\u00f3digo de Processo Civil[3]\u00a0estabelece a arbitragem. Esta, na vis\u00e3o de Fredie Didier Jr[4]., \u00e9 t\u00e9cnica de solu\u00e7\u00e3o de conflitos mediante a qual os conflitantes buscam em uma terceira pessoa, de sua confian\u00e7a, a solu\u00e7\u00e3o amig\u00e1vel e imparcial do lit\u00edgio.<\/h5>\n<h5 style=\"text-align: justify;\">Com aquela norma permissiva, \u00e9 imperioso verificar quais s\u00e3o os deveres das partes na produ\u00e7\u00e3o de provas no processo arbitral, considerando que um dos princ\u00edpios que norteiam o processo \u2014 seja ele judicial ou arbitral \u2014 \u00e9 o princ\u00edpio da coopera\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">A partir dessa perspectiva, pretende-se analisar o princ\u00edpio da coopera\u00e7\u00e3o em conjunto com a Lei 9.307\/1996 (Lei da Arbitragem), estabelecendo par\u00e2metros m\u00ednimos dos deveres das partes no desenvolvimento do processo arbitral, para que elas obtenham em prazo razo\u00e1vel a solu\u00e7\u00e3o integral do m\u00e9rito do lit\u00edgio que enfrentam.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>Arbitragem<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">Antes de avan\u00e7armos no dever das partes na produ\u00e7\u00e3o de provas no processo arbitral, \u00e9 imperioso entender o conceito de arbitragem.<\/h5>\n<h5 style=\"text-align: justify;\">Para Fitchner, Mannheimer e Monteiro\u00a0[5], a arbitragem \u00e9 um\u00a0<em>&#8220;m\u00e9todo de heterocomposi\u00e7\u00e3o de conflitos em que o \u00e1rbitro, exercendo a cogni\u00e7\u00e3o nos limites da conven\u00e7\u00e3o de arbitragem livremente estabelecida pelas partes, decide a controv\u00e9rsia com autonomia e definitividade&#8221;.<\/em><\/h5>\n<h5 style=\"text-align: justify;\">Decompondo o conceito assinalado, \u00e9 importante esclarecer que essa conven\u00e7\u00e3o de arbitragem pode se dar de duas formas: por meio de cl\u00e1usula compromiss\u00f3ria ou por meio do compromisso arbitral.<\/h5>\n<h5 style=\"text-align: justify;\">Cahali\u00a0[6]\u00a0explica que a primeira tem\u00a0<em>&#8220;car\u00e1ter preventivo, na medida em que que as partes est\u00e3o na expectativa de contratar e honrar seus compromissos contratuais, por\u00e9m desde ent\u00e3o deixam previsto que eventual conflito decorrente do contrato dever\u00e1 ser resolvido por arbitragem, n\u00e3o pelo Judici\u00e1rio&#8221;<\/em>, enquanto que o segundo\u00a0<em>&#8220;\u00e9 o instrumento firmado pelas partes por meio do qual, diante de um conflito manifesto, j\u00e1 deflagrado entre os envolvidos, faz-se a op\u00e7\u00e3o por direcionar ao ju\u00edzo arbitral a jurisdi\u00e7\u00e3o para solucionar a quest\u00e3o&#8221;<\/em>.<\/h5>\n<h5 style=\"text-align: justify;\">No que tange a autonomia das partes na arbitragem, Scavone Junior\u00a0[7]\u00a0salienta que as partes s\u00e3o livres para criar suas obriga\u00e7\u00f5es, desde que respeitadas as normas de ordem p\u00fablica.<\/h5>\n<h5 style=\"text-align: justify;\">A autonomia das partes, al\u00e9m de ser uma das caracter\u00edsticas da arbitragem, \u00e9 um dos princ\u00edpios norteadores desse modo de resolu\u00e7\u00e3o de conflito, que confere \u00e0s partes o poder de modelar, em conjunto, toda a arbitragem, desde sua elei\u00e7\u00e3o e seu in\u00edcio, at\u00e9 a sua conclus\u00e3o, passando pelo seu conte\u00fado\u00a0[8].<\/h5>\n<h5 style=\"text-align: justify;\">Nesse sentido, Didier\u00a0[9]\u00a0esclarece que as partes podem convencionar que o julgamento se realize com base nos princ\u00edpios gerais de direito, nos usos e costumes e nas regras internacionais de com\u00e9rcio.<\/h5>\n<h5 style=\"text-align: justify;\">A definitividade da arbitragem reside no fato de que, desde o advento da Lei 9.307\/1996, n\u00e3o h\u00e1 mais necessidade de homologa\u00e7\u00e3o judicial da senten\u00e7a arbitral, pois o \u00e1rbitro foi equiparado ao juiz togado no desempenho da arbitragem, conforme estabelece o artigo 18\u00a0[10], eis que a decis\u00e3o \u00e9 senten\u00e7a e, como tal, \u00e9 t\u00edtulo executivo judicial, capaz de fazer coisa julgada material ao compor o conflito. Embora seja t\u00edtulo executivo judicial, a sua execu\u00e7\u00e3o, invariavelmente, depende da provoca\u00e7\u00e3o do Poder Judici\u00e1rio, na medida em que n\u00e3o \u00e9 poss\u00edvel a sua execu\u00e7\u00e3o for\u00e7ada, pois o \u00e1rbitro n\u00e3o det\u00e9m poder coercitivo. Nesse sentido, esclarece Cahali\u00a0[11]:<\/h5>\n<h5 style=\"text-align: justify;\">&#8220;A decis\u00e3o dada pelo \u00e1rbitro imp\u00f5e \u00e0s partes, e por esta raz\u00e3o a solu\u00e7\u00e3o \u00e9 adjudicada, e n\u00e3o consensual, como se pretende na concilia\u00e7\u00e3o e na media\u00e7\u00e3o, e delas pode ser exigido o cumprimento, por\u00e9m a execu\u00e7\u00e3o for\u00e7ada se far\u00e1 perante o Poder Judici\u00e1rio, sendo a senten\u00e7a arbitral considerada um t\u00edtulo executivo judicial (art. 31 da Lei 9.307\/1996 e art. 515, VII, do CPC\/2015).&#8221;<\/h5>\n<h5 style=\"text-align: justify;\">Conclui-se que a arbitragem \u00e9 o instrumento adequado para solucionar conflitos que versem sobre direitos patrimoniais dispon\u00edveis, conforme determina o artigo 1\u00ba da Lei 9.307\/1996.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>O princ\u00edpio da coopera\u00e7\u00e3o<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">Inicialmente, \u00e9 importante destacar que princ\u00edpio \u00e9 esp\u00e9cie normativa, que conforme destaca \u00c1vila\u00a0[12], trata-se de norma que estabelece um fim a ser atingido.<\/h5>\n<h5 style=\"text-align: justify;\">Nesse sentido, o C\u00f3digo de Processo Civil, ao estabelecer em seu artigo 6\u00ba, que\u00a0<em>&#8220;todos os sujeitos do processo devem cooperar entre si para se obtenha, em tempo razo\u00e1vel, decis\u00e3o de m\u00e9rito e justa e efetiva<\/em>&#8220;, o estabeleceu no cap\u00edtulo das normas fundamentais do processo. E n\u00e3o foi \u00e0 toa.<\/h5>\n<h5 style=\"text-align: justify;\">O objetivo do artigo 6\u00ba do CPC foi de trazer um novo modelo de processo: o chamado processo cooperativo. Esse modelo, conforme li\u00e7\u00e3o esclarecedora de Didier Junior\u00a0[13]:<\/h5>\n<h5 style=\"text-align: justify; padding-left: 80px;\"><em>&#8220;Caracteriza-se pelo redimensionamento do princ\u00edpio do contradit\u00f3rio, com a inclus\u00e3o do \u00f3rg\u00e3o jurisdicional no rol de sujeitos do di\u00e1logo processual, e n\u00e3o mais como um mero espectador do duelo das partes. O contradit\u00f3rio \u00e9 valorizado como instrumento indispens\u00e1vel ao aprimoramento da decis\u00e3o judicial, e n\u00e3o apenas como uma regra formal que deve ser observada para que a decis\u00e3o seja v\u00e1lida.&#8221;<\/em><\/h5>\n<h5 style=\"text-align: justify;\">Esse modelo de processo exige a lealdade das partes na condu\u00e7\u00e3o do processo, que dever\u00e3o observar certos deveres, os quais, segundo Didier Junior\u00a0[14], podem ser alocados em direitos de esclarecimento, lealdade, e de prote\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">Theodoro Junior\u00a0[15]\u00a0salienta que neste modelo de processo, a l\u00f3gica dedutiva de resolu\u00e7\u00e3o de conflitos \u00e9 substitu\u00edda pela l\u00f3gica argumentativa, fazendo que o contradit\u00f3rio, como direito de informa\u00e7\u00e3o\/rea\u00e7\u00e3o, ceda espa\u00e7o a um direito de influ\u00eancia, refor\u00e7ando, deste modo, o papel das partes na forma\u00e7\u00e3o da decis\u00e3o judicial.<\/h5>\n<h5 style=\"text-align: justify;\">Em s\u00edntese conclusiva\u00a0[16], a coopera\u00e7\u00e3o pressup\u00f5e divis\u00e3o de tarefas, redistribui\u00e7\u00e3o de responsabilidades e um pacto de trabalho, em que todos aqueles que participem do processo, incluindo o julgador, as partes e seus advogados, devem estar em busca da justa composi\u00e7\u00e3o do lit\u00edgio.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>Os deveres das partes na produ\u00e7\u00e3o de provas no processo arbitral<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">Para Theodoro Junior\u00a0[17], o acesso \u00e0 justi\u00e7a, mediante um processo justo, \u00e9 garantido pelos direitos fundamentais assegurados na Constitui\u00e7\u00e3o, dentre os quais se destacam a ampla defesa e contradit\u00f3rio, que, indubitavelmente, envolvem o direito inafast\u00e1vel \u00e0 prova necess\u00e1ria \u00e0 solu\u00e7\u00e3o justa do lit\u00edgio.<\/h5>\n<h5 style=\"text-align: justify;\">Nessa perspectiva, para Theodoro Junior, a prova possui dois sentidos: um objetivo, que pode ser definido como o instrumento ou o meio h\u00e1bil para demonstrar a exist\u00eancia de um fato, e, por outro lado, um subjetivo, que \u00e9 a certeza originada quanto ao fato, em virtude da produ\u00e7\u00e3o do instrumento probat\u00f3rio. Isto \u00e9, a convic\u00e7\u00e3o formada no esp\u00edrito do julgador em torno do fato demonstrado.<\/h5>\n<h5 style=\"text-align: justify;\">N\u00e3o se pode olvidar que partes, seja em processo judicial ou arbitral, possuem o direito de empregar todos os meios legais, bem como os moralmente leg\u00edtimos, para provar a verdade dos fatos em que se funda o pedido ou a defesa e influir eficazmente na convic\u00e7\u00e3o do juiz\u00a0[18]. Entretanto, como se depreende da Lei da Arbitragem, n\u00e3o h\u00e1 uma distribui\u00e7\u00e3o legal do \u00f4nus da prova.<\/h5>\n<h5 style=\"text-align: justify;\">Todavia, em raz\u00e3o do princ\u00edpio da autonomia da vontade que rege o referido processo, nada impede que as partes convencionem sobre quem dever\u00e1 recair o \u00f4nus da prova ou se caber\u00e1 ao \u00e1rbitro defini-lo.<\/h5>\n<h5 style=\"text-align: justify;\">Nessa linha, Parente\u00a0[19]\u00a0sustenta que a instru\u00e7\u00e3o do processo arbitral \u00e9 pautada por uma enorme flexibilidade do procedimento, na medida em que n\u00e3o h\u00e1 uma dicotomia clara no regime de apresenta\u00e7\u00e3o, admissibilidade e valora\u00e7\u00e3o da prova nos moldes dos sistemas jur\u00eddicos do\u00a0<em>civil law<\/em>\u00a0e\u00a0<em>common law<\/em>, mas sim uma mistura dos dois modelos, gerando uma composi\u00e7\u00e3o personalizada para cada processo arbitral.<\/h5>\n<h5 style=\"text-align: justify;\">Entretanto, \u00e9 ineg\u00e1vel, conforme alerta Cahali\u00a0[20]\u00a0, que a contribui\u00e7\u00e3o da parte para instruir a causa \u00e9 de seu total interesse, cabendo-lhe a mais completa indica\u00e7\u00e3o de provas, com o foco na revela\u00e7\u00e3o da ocorr\u00eancia, n\u00e3o s\u00f3 como pelo interesse alegado, mas tamb\u00e9m na vers\u00e3o que lhe conv\u00e9m.<\/h5>\n<h5 style=\"text-align: justify;\">Contudo, o pr\u00f3prio \u00e1rbitro tem alargada, de direito e de fato, a sua autoridade na condu\u00e7\u00e3o do procedimento, cabendo interferir ativamente na instru\u00e7\u00e3o da causa, para consolidar o seu livre convencimento sobre os fatos, conforme determina o artigo 22, caput, da Lei da Arbitragem. Al\u00e9m disso, pelo princ\u00edpio da coopera\u00e7\u00e3o, o \u00e1rbitro deve ter conduta proativa, determinando provas para a descoberta da verdade.<\/h5>\n<h5 style=\"text-align: justify;\">Ainda que n\u00e3o houvesse o princ\u00edpio da coopera\u00e7\u00e3o no C\u00f3digo de Processo Civil, a lei de arbitragem bastaria para nortear o comportamento das partes. Isso porque o artigo 27 da referida lei estabelece que\u00a0<em>&#8220;a senten\u00e7a arbitral decidir\u00e1 sobre a responsabilidade das partes acerca das custas e despesas coma arbitragem, bem como sobre verba decorrente de litig\u00e2ncia de m\u00e1-f\u00e9, se for o caso, respeitadas as disposi\u00e7\u00f5es da conven\u00e7\u00e3o de arbitragem, se houver&#8221;<\/em>. Para Fitchener, Mannheimer e Monteiro[21], esse artigo \u00e9 a fonte legal direta do princ\u00edpio da lealdade processual (ou boa-f\u00e9 processual) na arbitragem.<\/h5>\n<h5 style=\"text-align: justify;\">Um dos primeiros deveres que as partes devem observar \u00e9 a veda\u00e7\u00e3o a produ\u00e7\u00e3o de provas il\u00edcitas, que, em linhas gerais, trata-se de uma garantia fundamental do indiv\u00edduo de que somente ser\u00e3o levadas em considera\u00e7\u00e3o aquelas provas extra\u00eddas por meios que n\u00e3o possam ser considerados atentat\u00f3rios a moralidade comum, com vistas \u00e0 preserva\u00e7\u00e3o dos valores intimamente atrelados \u00e0 dignidade humana\u00a0[22].<\/h5>\n<h5 style=\"text-align: justify;\">Sobre o aspecto da produ\u00e7\u00e3o de provas e os deveres das partes, Arruda Alvim\u00a0[23]\u00a0\u00e9 certeiro ao definir que o princ\u00edpio da lealdade objetiva evitar pretens\u00f5es sem fundamento, requerimento de provas e dilig\u00eancias in\u00fateis ou desnecess\u00e1rias. Acompanhando o entendimento de Arruda Alvim, Fitchener, Mannheimer e Monteiro\u00a0[24]\u00a0tamb\u00e9m entendem que &#8220;os pedidos infundados, muitas vezes feitos durante a instru\u00e7\u00e3o probat\u00f3ria, normalmente acompanhados de insinua\u00e7\u00f5es quanto \u00e0 validade do processo arbitral, bem como de entrelinhares amea\u00e7as de invalida\u00e7\u00e3o da futura senten\u00e7a arbitral, tamb\u00e9m representam viola\u00e7\u00e3o ao princ\u00edpio da lealdade processual.<\/h5>\n<h5 style=\"text-align: justify;\">No que tange \u00e0 prova testemunhal, o princ\u00edpio da lealdade processual impede que as partes e seus representantes procurem guiar o depoimento das testemunhas e assistentes t\u00e9cnicos, induzindo aos colaboradores do processo a prestar informa\u00e7\u00f5es inver\u00eddicas em fazer uma tese ou outra no processo arbitral\u00a0[25].<\/h5>\n<h5 style=\"text-align: justify;\">Ainda sobre a prova testemunhal, Didier Junior\u00a0[26]\u00a0destaca que o dever preven\u00e7\u00e3o (um dos deveres decorrentes da coopera\u00e7\u00e3o) permite a sugest\u00e3o do ju\u00edzo de certa atua\u00e7\u00e3o pela parte, dando como exemplo o questionamento se a parte desistiu do depoimento de uma testemunha indicada ou apenas se esqueceu dela.<\/h5>\n<h5 style=\"text-align: justify;\">Em rela\u00e7\u00e3o a prova pericial, esta pode ser determinada de of\u00edcio ou a requerimento das partes, cabendo ao \u00e1rbitro ou tribunal julgar se ela \u00e9 necess\u00e1ria\u00a0[27]. Sobre esse aspecto, as partes n\u00e3o devem formular prova pericial quando ela tiver conte\u00fado meramente protelat\u00f3rio, sob pena de violar o princ\u00edpio da coopera\u00e7\u00e3o e da dura\u00e7\u00e3o razo\u00e1vel do processo.<\/h5>\n<h5 style=\"text-align: justify;\">Em s\u00edntese conclusiva, \u00e9 necess\u00e1rio que os operadores do direito observem o princ\u00edpio da coopera\u00e7\u00e3o na atua\u00e7\u00e3o judicial ou extrajudicial, sendo de grande valia a colabora\u00e7\u00e3o da doutrina sobre os limites, benef\u00edcios e vantagens da coopera\u00e7\u00e3o em um processo que busca a dura\u00e7\u00e3o razo\u00e1vel do processo.<\/h5>\n<h5 style=\"text-align: justify;\"><strong>Refer\u00eancias bibliogr\u00e1ficas<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">Arruda Alvim, Jos\u00e9 Manoel de. Manual de direito processual civil. 9\u00aa ed. S\u00e3o Paulo. RT, 2005.<\/h5>\n<h5 style=\"text-align: justify;\">\u00c1vila, Humberto. Teoria dos Princ\u00edpios. 5\u00aa ed. S\u00e3o Paulo: Malheiros, ed., 2006, p. 78.<\/h5>\n<h5 style=\"text-align: justify;\">BRASIL. Constitui\u00e7\u00e3o (1988).\u00a0<em>Constitui\u00e7\u00e3o da Rep\u00fablica Federativa do Brasil<\/em>. Bras\u00edlia: Senado Federal, 1988.<\/h5>\n<h5 style=\"text-align: justify;\">BRASIL. C\u00f3digo de Processo Civil. Lei n\u00ba 13.105, de 16 de mar\u00e7o de 2015. Dispon\u00edvel em: http:\/\/www.planalto.gov.br\/ccivil_03\/_Ato2015-2018\/2015\/Lei\/L13105.htm. Acesso em 02.07.2019.<\/h5>\n<h5 style=\"text-align: justify;\">BRASIL. Lei 9.307, de 23 de setembro de 1996. Dispon\u00edvel em: http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l9307.htm. Acesso em 02.07.2019.<\/h5>\n<h5 style=\"text-align: justify;\">Cahali, Francisco Jos\u00e9. Curso de Arbitragem: Media\u00e7\u00e3o: Concilia\u00e7\u00e3o: Tribunal de Multiportas. S\u00e3o Paulo: Thompson Reuters Brasil, 2018. 7\u00aa ed. ver., atual. e ampl.<\/h5>\n<h5 style=\"text-align: justify;\">Didier Junior, Fredie; Zaneti Junior, Hermes. Justi\u00e7a Multiportas: media\u00e7\u00e3o, concilia\u00e7\u00e3o, arbitragem e outros meios adequados de solu\u00e7\u00e3o de conflitos. Salvador: Juspodivm, 2018.<\/h5>\n<h5 style=\"text-align: justify;\">Fichtner, Jos\u00e9 Antonio; Mannheimer, Sergio Nelson; Monteiro, Andr\u00e9 Luis. Teoria Geral da arbitragem. Rio de Janeiro: Forense, 2019.<\/h5>\n<h5 style=\"text-align: justify;\">Gouveia, L\u00facio Grassi de. A fun\u00e7\u00e3o legitimadora do princ\u00edpio da coopera\u00e7\u00e3o intersubjetiva no processo civil brasileiro. Revista de Processo. S\u00e3o Paulo: Revista dos Tribunais, n\u00ba 172, jun.\/2009.<\/h5>\n<h5 style=\"text-align: justify;\">Nag\u00e3o, Paulo Issamu. Do controle judicial da senten\u00e7a arbitral. Distrito Federal: Gazeta Jur\u00eddica, 2013.<\/h5>\n<h5 style=\"text-align: justify;\">Parente, Eduardo de Albuquerque. Processo arbitral e sistema. S\u00e3o Paulo: Atlas, 2012.<\/h5>\n<h5 style=\"text-align: justify;\">Scavone Junior, Luiz Antonio. Manual de arbitragem e concilia\u00e7\u00e3o. Rio de Janeiro: Forense, 2018. 8\u00aa ed. ver. e atual.<\/h5>\n<h5 style=\"text-align: justify;\">Theodoro J\u00fanio, Humberto. Curso de Direito Processual Civil. Teoria Geral do direito processual civil, processo de conhecimento e procedimento comum. Volume I. 57\u00aa ed. ver., atual. e ampl. Rio de Janeiro: Forense, 2016.<\/h5>\n<h5 style=\"text-align: justify;\">[1]\u00a0Art. 5\u00ba, XXXV da CRFB:\u00a0<em>&#8220;A lei n\u00e3o excluir\u00e1 da aprecia\u00e7\u00e3o do Poder Judici\u00e1rio les\u00e3o ou amea\u00e7a a direito<\/em>&#8220;.<\/h5>\n<h5 style=\"text-align: justify;\">[2]\u00a0Didier Junior, Fredie; Zaneti Junior, Hermes. Justi\u00e7a Multiportas: media\u00e7\u00e3o, concilia\u00e7\u00e3o, arbitragem e outros meios adequados de solu\u00e7\u00e3o de conflitos. Salvador: Juspodivm, 2018.p.\u00a0<em>38.<\/em><\/h5>\n<h5 style=\"text-align: justify;\"><em><strong>[3]<\/strong><\/em>\u00a0Art. 3\u00ba par\u00e1grafo \u00fanico do CPC: &#8220;\u00c9 permitida a arbitragem, na forma da lei&#8221;.<\/h5>\n<h5 style=\"text-align: justify;\">[4]\u00a0Didier Junior, Fredie; Zaneti Junior, Hermes. Justi\u00e7a Multiportas: media\u00e7\u00e3o, concilia\u00e7\u00e3o, arbitragem e outros meios adequados de solu\u00e7\u00e3o de conflitos. Salvador: Juspodivm, 2018.p. 206.<\/h5>\n<h5 style=\"text-align: justify;\">[5]\u00a0Fichtner, Jos\u00e9 Antonio; Mannheimer, Sergio Nelson; Monteiro, Andr\u00e9 Luis. Teoria Geral da arbitragem. Rio de Janeiro: Forense, 2019. p.33<\/h5>\n<h5 style=\"text-align: justify;\">[6]\u00a0Cahali, Francisco Jos\u00e9. Curso de Arbitragem: Media\u00e7\u00e3o: Concilia\u00e7\u00e3o: Tribunal de Multiportas. S\u00e3o Paulo: Thompson Reuters Brasil, 2018. 7\u00aa ed. ver., atual. e ampl. p. 165-166.<\/h5>\n<h5 style=\"text-align: justify;\">[7]\u00a0Scavone Junior, Luiz Antonio. Manual de arbitragem e concilia\u00e7\u00e3o. Rio de Janeiro: Forense, 2018. 8\u00aa ed. ver. e atual. p.84.<\/h5>\n<h5 style=\"text-align: justify;\">[8]\u00a0Cahali, Francisco Jos\u00e9. Curso de Arbitragem: Media\u00e7\u00e3o: Concilia\u00e7\u00e3o: Tribunal de Multiportas. S\u00e3o Paulo: Thompson Reuters Brasil, 2018. 7\u00aa ed. ver., atual. e ampl. p. 148.<\/h5>\n<h5 style=\"text-align: justify;\">[9]\u00a0Didier Jr., Fredie. Curso de direito processual civil: introdu\u00e7\u00e3o ao direito processual civil. Parte geral e processo de conhecimento. 20\u00aa ed. Salvador: Ed. Juspodivm, 2018. p.207<\/h5>\n<h5 style=\"text-align: justify;\">[10]\u00a0Art. 18 da Lei 9.307\/1996: O \u00e1rbitro \u00e9 juiz de fato e de direito, e a senten\u00e7a que proferir n\u00e3o fica sujeita a recurso ou a homologa\u00e7\u00e3o pelo Poder Judici\u00e1rio.<\/h5>\n<h5 style=\"text-align: justify;\">[11]\u00a0Cahali, Francisco Jos\u00e9. Curso de Arbitragem: Media\u00e7\u00e3o: Concilia\u00e7\u00e3o: Tribunal de Multiportas. S\u00e3o Paulo: Thompson Reuters Brasil, 2018. 7\u00aa ed. ver., atual. e ampl. p. 124.<\/h5>\n<h5 style=\"text-align: justify;\">[12]\u00a0\u00c1vila, Humberto. Teoria dos Princ\u00edpios. 5\u00aa ed. S\u00e3o Paulo: Malheiros, ed., 2006, p. 78.<\/h5>\n<h5 style=\"text-align: justify;\">[13]\u00a0Didier Jr., Fredie. Curso de direito processual civil: introdu\u00e7\u00e3o ao direito processual civil. Parte geral e processo de conhecimento. 20\u00aa ed. Salvador: Ed. Juspodivm, 2018. p.156.<\/h5>\n<h5 style=\"text-align: justify;\">[14]\u00a0Didier Jr., Fredie. Curso de direito processual civil: introdu\u00e7\u00e3o ao direito processual civil. Parte geral e processo de conhecimento. 20\u00aa ed. Salvador: Ed. Juspodivm, 2018. p.156.<\/h5>\n<h5 style=\"text-align: justify;\">[15]\u00a0Theodoro J\u00fanio, Humberto. Curso de Direito Processual Civil. Teoria Geral do direito processual civil, processo de conhecimento e procedimento comum. Volume I. 57\u00aa ed. ver., atual. e ampl. Rio de Janeiro: Forense, 2016.p.82.<\/h5>\n<h5 style=\"text-align: justify;\">[16]\u00a0Gouveia, L\u00facio Grassi de. A fun\u00e7\u00e3o legitimadora do princ\u00edpio da coopera\u00e7\u00e3o intersubjetiva no processo civil brasileiro. Revista de Processo. S\u00e3o Paulo: Revista dos Tribunais, n\u00ba 172, jun.\/2009, p. 35.<\/h5>\n<h5 style=\"text-align: justify;\">[17]\u00a0Theodoro J\u00fanio, Humberto. Curso de Direito Processual Civil. Teoria Geral do direito processual civil, processo de conhecimento e procedimento comum. Volume I. 57\u00aa ed. ver., atual. e ampl. Rio de Janeiro: Forense, 2016.p.862-863.<\/h5>\n<h5 style=\"text-align: justify;\">[18]\u00a0Art. 369 do CPC: As partes t\u00eam o direito de empregar todos os meios legais, bem como os moralmente leg\u00edtimos, ainda que n\u00e3o especificados neste c\u00f3digo, para provar a verdade dos fatos em que se funda o pedido ou a defesa e influir eficazmente na convic\u00e7\u00e3o do juiz.<\/h5>\n<h5 style=\"text-align: justify;\">[19]\u00a0Parente, Eduardo de Albuquerque. Processo arbitral e sistema. S\u00e3o Paulo: Atlas, 2012.p.221.<\/h5>\n<h5 style=\"text-align: justify;\">[20]\u00a0Cahali, Francisco Jos\u00e9. Curso de Arbitragem: Media\u00e7\u00e3o: Concilia\u00e7\u00e3o: Tribunal de Multiportas. S\u00e3o Paulo: Thompson Reuters Brasil, 2018. 7\u00aa ed. ver., atual. e ampl. p. 148.<\/h5>\n<h5 style=\"text-align: justify;\">[21]\u00a0Fichtner, Jos\u00e9 Antonio; Mannheimer, Sergio Nelson; Monteiro, Andr\u00e9 Luis. Teoria Geral da arbitragem. Rio de Janeiro: Forense, 2019. p.197<\/h5>\n<h5 style=\"text-align: justify;\">[22]\u00a0Nag\u00e3o, Paulo Issamu. Do controle judicial da senten\u00e7a arbitral. Distrito Federal: Gazeta Jur\u00eddica, 2013. p.102.<\/h5>\n<h5 style=\"text-align: justify;\">[23]\u00a0Arruda Alvim, Jos\u00e9 Manoel de. Manual de direito processual civil. 9\u00aa ed. S\u00e3o Paulo. RT, 2005.p.38.<\/h5>\n<h5 style=\"text-align: justify;\">[24]\u00a0Fichtner, Jos\u00e9 Antonio; Mannheimer, Sergio Nelson; Monteiro, Andr\u00e9 Luis. Teoria Geral da arbitragem. Rio de Janeiro: Forense, 2019. p.198<\/h5>\n<h5 style=\"text-align: justify;\">[25]\u00a0Fichtner, Jos\u00e9 Antonio; Mannheimer, Sergio Nelson; Monteiro, Andr\u00e9 Luis. Teoria Geral da arbitragem. Rio de Janeiro: Forense, 2019. p.199.<\/h5>\n<h5 style=\"text-align: justify;\">[26]\u00a0Didier Jr., Fredie. Curso de direito processual civil: introdu\u00e7\u00e3o ao direito processual civil. Parte geral e processo de conhecimento. 20\u00aa ed. Salvador: Ed. Juspodivm, 2018. p.161.<\/h5>\n<h5 style=\"text-align: justify;\">[27]\u00a0Art. 22 da Lei 9.307\/1996: Poder\u00e1 o \u00e1rbitro ou o tribunal arbitral tomar o depoimento das partes, ouvir testemunhas e determinar a realiza\u00e7\u00e3o de per\u00edcias ou outras provas que julgar necess\u00e1rias, mediante requerimento das partes ou de of\u00edcio.<\/h5>\n<h5 style=\"text-align: justify;\">Por Mariana da Silva Brito, advogada, assessora jur\u00eddica na Secretaria de Estado e Fazenda do Estado do Rio de Janeiro, mestra em Direito Processual Civil pela Universidade do Estado do Rio de Janeiro e p\u00f3s-graduada em Direito e Advocacia P\u00fablica pela Universidade do Estado do Rio de Janeiro<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Revista Consultor Jur\u00eddico, 11 de setembro de 2023, 18h28<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adambrasil.com\/an\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Em s\u00edntese conclusiva, \u00e9 necess\u00e1rio que os operadores do direito observem o princ\u00edpio da coopera\u00e7\u00e3o na atua\u00e7\u00e3o judicial ou extrajudicial, sendo de grande valia a colabora\u00e7\u00e3o da doutrina sobre os limites, benef\u00edcios e vantagens da coopera\u00e7\u00e3o em um processo que busca a dura\u00e7\u00e3o razo\u00e1vel do processo.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,14],"tags":[11,13,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16132"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=16132"}],"version-history":[{"count":1,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16132\/revisions"}],"predecessor-version":[{"id":16133,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/16132\/revisions\/16133"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=16132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=16132"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=16132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}