﻿{"id":10073,"date":"2023-03-16T04:39:00","date_gmt":"2023-03-16T07:39:00","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo2\/?p=10073"},"modified":"2023-03-16T04:39:00","modified_gmt":"2023-03-16T07:39:00","slug":"falencia-da-parte-nao-justifica-afastamento-da-convencao-de-arbitragem-pelo-juizo-estatal-2","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/falencia-da-parte-nao-justifica-afastamento-da-convencao-de-arbitragem-pelo-juizo-estatal-2\/","title":{"rendered":"Fal\u00eancia da parte n\u00e3o justifica afastamento da conven\u00e7\u00e3o de arbitragem pelo ju\u00edzo estatal"},"content":{"rendered":"<h5 style=\"text-align: justify;\">A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) entendeu que a conven\u00e7\u00e3o de arbitragem n\u00e3o pode ser afastada pelo ju\u00edzo estatal sob o argumento de hipossufici\u00eancia financeira da parte contratante que teve a fal\u00eancia decretada.<\/h5>\n<h5 style=\"text-align: justify;\">&#8220;Diante da fal\u00eancia de uma das contratantes, que firmou cl\u00e1usula compromiss\u00f3ria, o princ\u00edpio <em>k<\/em><em>ompetenz-kompetenz<\/em> deve ser respeitado, impondo ao \u00e1rbitro avaliar a viabilidade ou n\u00e3o da instaura\u00e7\u00e3o da arbitragem&#8221;, afirmou a relatora do processo, ministra Nancy Andrighi.<\/h5>\n<h5 style=\"text-align: justify;\">A decis\u00e3o teve origem em a\u00e7\u00e3o ordin\u00e1ria com pedido de indeniza\u00e7\u00e3o ajuizada por um grupo de empresas do ramo da constru\u00e7\u00e3o civil contra seus investidores, em raz\u00e3o de suposto descumprimento na entrega dos aportes financeiros e na execu\u00e7\u00e3o das garantias.<\/h5>\n<h5 style=\"text-align: justify;\">Em primeira inst\u00e2ncia, o processo foi extinto sem resolu\u00e7\u00e3o do m\u00e9rito, diante da exist\u00eancia de cl\u00e1usula arbitral. Em apela\u00e7\u00e3o, a decis\u00e3o foi reformada, e afastada a conven\u00e7\u00e3o arbitral, em virtude da situa\u00e7\u00e3o de hipossufici\u00eancia financeira de uma das autoras, cuja fal\u00eancia foi decretada.<\/h5>\n<h5 style=\"text-align: justify;\">O tribunal considerou que a massa falida havia pedido a gratuidade de Justi\u00e7a, o que demonstraria sua total impossibilidade de suportar as despesas da arbitragem.<\/h5>\n<h5 style=\"text-align: justify;\">Celebra\u00e7\u00e3o de cl\u00e1usula compromiss\u00f3ria tem for\u00e7a vinculante<\/h5>\n<h5 style=\"text-align: justify;\">Em seu voto, Nancy Andrighi lembrou que a celebra\u00e7\u00e3o da cl\u00e1usula compromiss\u00f3ria possui for\u00e7a vinculante, obrigando as partes da rela\u00e7\u00e3o contratual a respeitar, para a resolu\u00e7\u00e3o dos conflitos, a compet\u00eancia atribu\u00edda ao \u00e1rbitro.<\/h5>\n<h5 style=\"text-align: justify;\">&#8220;A celebra\u00e7\u00e3o de cl\u00e1usula compromiss\u00f3ria implica a derroga\u00e7\u00e3o da jurisdi\u00e7\u00e3o estatal, impondo ao \u00e1rbitro o poder-dever de decidir as quest\u00f5es decorrentes do contrato e, inclusive, decidir acerca da pr\u00f3pria exist\u00eancia, validade e efic\u00e1cia da cl\u00e1usula compromiss\u00f3ria (princ\u00edpio <em>kompetenz-kompetenz<\/em>)&#8221;, afirmou.<\/h5>\n<h5 style=\"text-align: justify;\">A magistrada destacou que, ao contr\u00e1rio do entendimento do tribunal de origem, o estado de fal\u00eancia posterior ao processo arbitral n\u00e3o impede o regular prosseguimento da arbitragem j\u00e1 instaurada, e, ainda que houvesse d\u00favida nesse sentido, tal quest\u00e3o deveria ser dirimida pelo tribunal arbitral, n\u00e3o cabendo \u00e0 parte acionar o ju\u00edzo estatal, como forma de preservar o princ\u00edpio <em>pacta sunt servanda<\/em>, a autonomia privada e a seguran\u00e7a jur\u00eddica.<\/h5>\n<h5 style=\"text-align: justify;\">&#8220;O ju\u00edzo arbitral prevalece at\u00e9 mesmo para an\u00e1lise de medidas cautelares ou urgentes, sendo instado o Poder Judici\u00e1rio a atuar apenas em situa\u00e7\u00f5es excepcionais que possam representar o pr\u00f3prio esvaimento do direito ou mesmo preju\u00edzo \u00e0s partes&#8221;, acrescentou a ministra.<\/h5>\n<h5 style=\"text-align: justify;\">Tribunal arbitral deve decidir sobre a instaura\u00e7\u00e3o da arbitragem<\/h5>\n<h5 style=\"text-align: justify;\">Quanto \u00e0 hip\u00f3tese dos autos, Nancy Andrighi registrou que \u2013 embora a jurisprud\u00eancia e a doutrina admitam a submiss\u00e3o de quest\u00e3o urgente \u00e0 an\u00e1lise do Judici\u00e1rio at\u00e9 que se instaure o procedimento arbitral \u2013 a situa\u00e7\u00e3o financeira da empresa deve ser apresentada ao tribunal arbitral, para que ele mesmo decida sobre a viabilidade ou n\u00e3o da instaura\u00e7\u00e3o da arbitragem.<\/h5>\n<h5 style=\"text-align: justify;\">&#8220;Nota-se pelos pedidos da inicial que n\u00e3o se busca nenhum tipo de medida cautelar que possa excepcionar o ju\u00edzo arbitral; ao contr\u00e1rio, pretende a parte discutir o pr\u00f3prio conte\u00fado do contrato que cont\u00e9m cl\u00e1usula compromiss\u00f3ria, almejando a substitui\u00e7\u00e3o da jurisdi\u00e7\u00e3o arbitral pela estatal&#8221;, disse a relatora.<\/h5>\n<h5 style=\"text-align: justify;\"><a href=\"https:\/\/www.adambrasil.com\/processo\/revista\/documento\/mediado\/?componente=ITA&amp;sequencial=2208630&amp;num_registro=202102897496\" target=\"_blank\" rel=\"noopener\"><strong>Leia o acord\u00e3o no REsp 1.959.435<\/strong><\/a>.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: STJ &#8211; 16\/03\/2023 07:00<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adambrasil.com\/an\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>\u200bA Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) entendeu que a conven\u00e7\u00e3o de arbitragem n\u00e3o pode ser afastada pelo ju\u00edzo estatal sob o argumento de hipossufici\u00eancia financeira da parte contratante que teve a fal\u00eancia decretada.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,14],"tags":[11,13,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/10073"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=10073"}],"version-history":[{"count":0,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/10073\/revisions"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=10073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=10073"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=10073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}