﻿{"id":10045,"date":"2022-10-11T20:16:00","date_gmt":"2022-10-11T23:16:00","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo2\/?p=10045"},"modified":"2022-10-11T20:16:00","modified_gmt":"2022-10-11T23:16:00","slug":"a-influencia-da-lgpd-na-arbitragem-internacional-2","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/a-influencia-da-lgpd-na-arbitragem-internacional-2\/","title":{"rendered":"A Influ\u00eancia da LGPD na Arbitragem Internacional"},"content":{"rendered":"<h5 style=\"text-align: justify;\"><strong>Resumo<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">Em uma sociedade em constante busca de conhecimento e informa\u00e7\u00e3o, onde os dados pessoais tornaram-se uma moeda de troca e um verdadeiro par\u00e2metro de pesquisa e influ\u00eancia, a Lei Geral de Prote\u00e7\u00e3o de Dados surge como uma ferramenta que visa assegurar o direito \u00e0 privacidade, \u00e0 liberdade e ao livre desenvolvimento da pessoa natural. Em vista disso, prop\u00f5e-se um estudo dos aspectos principais da LGPD, seus objetivos, fundamentos, conceitos relevantes e determina\u00e7\u00f5es, bem como, a verifica\u00e7\u00e3o da influ\u00eancia dessa nova legisla\u00e7\u00e3o nas C\u00e2maras Arbitrais e procedimentos de Arbitragem Internacional. Ser\u00e1 demonstrada a necessidade de prote\u00e7\u00e3o dos dados tratados pelas C\u00e2maras Arbitrais e as principais legisla\u00e7\u00f5es internacionais que influenciaram direta ou indiretamente na cria\u00e7\u00e3o da Lei Geral de Prote\u00e7\u00e3o de Dados atrav\u00e9s de uma an\u00e1lise bibliogr\u00e1fica e comparativa. Por fim, ser\u00e3o verificadas ainda as principais medidas preventivas a serem adotadas para proteger os dados coletados no \u00e2mbito das arbitragens internacionais.<\/h5>\n<h5 style=\"text-align: justify;\">Palavras-chave: Lei Geral de Prote\u00e7\u00e3o de Dados. Tratamento de Dados. Arbitragem Internacional. Direito Internacional. C\u00e2maras Arbitrais.<\/h5>\n<h5>\u00a0<\/h5>\n<h5 style=\"text-align: justify;\"><strong>INTRODU\u00c7\u00c3O<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">Os procedimentos arbitrais s\u00e3o geralmente protegidos por sigilo, sendo resguardados os atos procedimentais e provas obtidas durante o procedimento, por\u00e9m, \u00e9 ineg\u00e1vel que por tr\u00e1s de todo procedimento, seja entre pessoas f\u00edsicas ou jur\u00eddicas, s\u00e3o coletados diversos dados pessoais. O crescimento das rela\u00e7\u00f5es negociais internacionais alavancou tamb\u00e9m a utiliza\u00e7\u00e3o da Arbitragem Internacional como um mecanismo de resolu\u00e7\u00e3o de eventuais conflitos decorrentes das rela\u00e7\u00f5es contratuais. Essas rela\u00e7\u00f5es muitas vezes englobam o cadastro de dados pessoais dos sujeitos envolvidos no procedimento arbitral: partes, advogados, \u00e1rbitros, experts, testemunhas, dentre outros. Al\u00e9m disso, a pr\u00f3pria dila\u00e7\u00e3o probat\u00f3ria poder\u00e1 coletar dados referentes a terceiros\u00a0por meio de depoimentos e provas documentais.<\/h5>\n<h5 style=\"text-align: justify;\">Todas essas informa\u00e7\u00f5es coletadas s\u00e3o armazenadas em um banco de dados, normalmente no sistema interno de uma C\u00e2mara Arbitral. Diante desse cen\u00e1rio, \u00e9 necess\u00e1rio resguardar os dados armazenados e fazer a devida adequa\u00e7\u00e3o das C\u00e2maras Arbitrais \u00e0s exig\u00eancias apontadas pela Lei Geral de Prote\u00e7\u00e3o de Dados que entrou em vigor em 18 de setembro de 2020.<\/h5>\n<h5 style=\"text-align: justify;\">Ao longo deste estudo ser\u00e3o abordados os aspectos gerais da LGPD, seus principais conceitos e princ\u00edpios, bem como, ser\u00e1 realizada uma an\u00e1lise comparativa entre a Lei Geral de Prote\u00e7\u00e3o de Dados e sua antecessora na Europa: a General Data Protection Regulation \u2013 GDPR. Ser\u00e3o elencadas tamb\u00e9m algumas das recomenda\u00e7\u00f5es elaboradas pela do Protocolo de Cyberseguran\u00e7a na Arbitragem Internacional da International Council for Commercial Arbitration -ICCA, em parceria com a New York City Bar Association e o International Institute for Conflict Prevention &amp; Resolution.<\/h5>\n<h5 style=\"text-align: justify;\">Outro aspecto abordado ser\u00e1 a necessidade de adequa\u00e7\u00e3o das C\u00e2maras Arbitrais \u00e0s disposi\u00e7\u00f5es da LGPD, a observ\u00e2ncia aos crit\u00e9rios de transfer\u00eancia internacional de dados e as medidas que podem ser adotadas a fim de garantir a seguran\u00e7a dos dados coletados e assegurar o direito dos titulares.<\/h5>\n<h5>\u00a0<\/h5>\n<h5 style=\"text-align: justify;\"><strong>ASPECTOS GERAIS DA LGPD<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">A troca de conhecimento e informa\u00e7\u00f5es sempre foi uma atividade presente no comportamento humano, por\u00e9m, atualmente, muito mais do que apenas dados, essas informa\u00e7\u00f5es tornaram-se mercadorias valiosas. Os dados coletados em diversas plataformas t\u00eam transformado as informa\u00e7\u00f5es pessoais em um verdadeiro produto, vendido com o intuito de identificar padr\u00f5es, prefer\u00eancias e opini\u00f5es sob o pretexto de melhor adequar os servi\u00e7os \u00e0s necessidades de seus clientes.<\/h5>\n<h5 style=\"text-align: justify;\">Mas a partir do momento em que essa coleta de informa\u00e7\u00f5es \u00e9 tratada como mercadoria, o titular se torna o produto e n\u00e3o mais o cliente. Apesar de o tratamento de dados ser uma pr\u00e1tica recorrente e necess\u00e1ria para o bom funcionamento de diversos setores da sociedade, \u00e9 preciso estabelecer limites para o tratamento desses dados a fim de assegurar a privacidade do titular dessas informa\u00e7\u00f5es.<\/h5>\n<h5 style=\"text-align: justify;\">Al\u00e9m disso, a tecnologia e a inova\u00e7\u00e3o tem sido aspectos essenciais para o desenvolvimento da sociedade contempor\u00e2nea, de modo que, a globaliza\u00e7\u00e3o proporcionada pelo acesso \u00e0 internet e o crescimento da troca de informa\u00e7\u00f5es online, bem como, das redes sociais e aplicativos, intensificou a necessidade de prote\u00e7\u00e3o dos dados que s\u00e3o compartilhados pelos usu\u00e1rios.<\/h5>\n<h5 style=\"text-align: justify;\">De acordo com FRAZ\u00c3O, TEPEDINO e OLIVA:<\/h5>\n<h5 style=\"text-align: justify;\">Com o acelerado desenvolvimento tecnol\u00f3gico e a consolida\u00e7\u00e3o de espa\u00e7os p\u00fablicos virtuais, a gest\u00e3o da informa\u00e7\u00e3o sobre si pr\u00f3prio tornou-se express\u00e3o fundamental do indiv\u00edduo. Por conseguinte, revela-se imposs\u00edvel cogitar a prote\u00e7\u00e3o integral \u00e0 liberdade, \u00e0 privacidade e ao desenvolvimento da pessoa natural sem que se lhe garanta eficaz defesa e controle de seus pr\u00f3prios dados \u2013 o que se traduz na express\u00e3o autodetermina\u00e7\u00e3o informativa. (FRAZ\u00c3O; TEPEDINO; OLIVA, 2019, p. 677\/678)<\/h5>\n<h5 style=\"text-align: justify;\">A Lei Geral de Prote\u00e7\u00e3o de Dados surge com o intuito de atender aos aspectos jur\u00eddicos dessas novas demandas que s\u00e3o apresentadas pela P\u00f3s-Modernidade.<\/h5>\n<h5 style=\"text-align: justify;\">O Art. 1\u00b0 da referida lei apresenta em termos gerais o objeto a ser regulado por ela e o objetivo da cria\u00e7\u00e3o da LGPD:<\/h5>\n<h5 style=\"text-align: justify;\">Esta Lei disp\u00f5e sobre o tratamento de dados pessoais, inclusive nos meios digitais, por pessoa natural ou por pessoa jur\u00eddica de direito p\u00fablico ou privado, com o objetivo de proteger os direitos fundamentais de liberdade e de privacidade e o livre desenvolvimento da personalidade da pessoa natural. (BRASIL, 2018, Art.1\u00ba)<\/h5>\n<h5 style=\"text-align: justify;\">O objetivo da Lei Geral de Prote\u00e7\u00e3o de Dados \u00e9, portanto, assegurar o direito de privacidade e liberdade dos usu\u00e1rios, assim como, garantir o livre desenvolvimento da pessoa natural, resguardando seus dados pessoais.<\/h5>\n<h5 style=\"text-align: justify;\">Vale ressaltar que a lei abrange tanto os dados tratados por meio digital quanto por meios n\u00e3o- digitais, tratados por pessoas f\u00edsicas ou jur\u00eddicas, de direito p\u00fablico ou privado, devendo ser observada em todo o territ\u00f3rio nacional.<\/h5>\n<h5 style=\"text-align: justify;\">Segundo COSTA:<\/h5>\n<h5 style=\"text-align: justify;\">Em uma Era na qual reputa\u00e7\u00e3o e credibilidade s\u00e3o julgadas t\u00e3o rapidamente quanto o dedilhar dos limitados caracteres dos aplicativos de smartphones, e diante da flagrante fragilidade dos usu\u00e1rios da internet perante o tratamento e a manipula\u00e7\u00e3o dos seus dados, a preserva\u00e7\u00e3o da privacidade, ancorada pela ent\u00e3o fr\u00e1gil autodetermina\u00e7\u00e3o informativa, esta entendida como a faculdade de que toda e qualquer pessoa possa determinar os limites do uso de seus dados pessoais ganha aos poucos a prote\u00e7\u00e3o estatal. Ainda que a preocupa\u00e7\u00e3o pela privacidade remonte \u00e0 Antiguidade, \u00e9 na sociedade moderna que o embate entre o avan\u00e7o tecnol\u00f3gico e a invas\u00e3o da vida privada carece cada vez mais de prote\u00e7\u00e3o, fazendo com que as legisla\u00e7\u00f5es nacionais primem por legislar quanto \u00e0 coleta, ao armazenamento, ao uso e \u00e0 transmiss\u00e3o dos dados pessoais. (COSTA, 2019, p. 4)<\/h5>\n<h5 style=\"text-align: justify;\">No que diz respeito \u00e0 abrang\u00eancia da lei, o Art.3\u00b0 da LGPD elenca tamb\u00e9m a possibilidade de aplica\u00e7\u00e3o da lei a dados em tratamento em outros pa\u00edses, desde que, a atividade de tratamento tenha por objetivo a oferta ou o fornecimento de bens ou servi\u00e7os, o tratamento de dados de indiv\u00edduos localizados no territ\u00f3rio nacional; ou ainda de dados que tenham sido coletados no territ\u00f3rio nacional, sendo assim considerado se a pessoa titular dos dados estiver no Brasil no momento da coleta.<\/h5>\n<h5 style=\"text-align: justify;\">O Art.5\u00b0 da LGPD apresenta alguns conceitos extremamente relevantes para a abordagem da mat\u00e9ria, sendo essencial ressaltar alguns deles: o conceito de dado pessoal, tratamento, banco de dados, titular, controlador, operador, encarregado e agentes de tratamento.<\/h5>\n<h5 style=\"text-align: justify;\">O dado pessoal \u00e9 toda informa\u00e7\u00e3o relativa a uma pessoa identificada ou identific\u00e1vel, h\u00e1 ainda o dado pessoal sens\u00edvel que diz respeito \u00e0 aspectos raciais e \u00e9tnicos, sexuais, dados referentes \u00e0 sa\u00fade, gen\u00e9ticos ou biom\u00e9tricos, ou dados referentes a filia\u00e7\u00e3o a organiza\u00e7\u00f5es religiosas, pol\u00edticas, filos\u00f3ficas ou sindicatos. Existe tamb\u00e9m o dado anonimizado que se refere ao caso em que n\u00e3o \u00e9 poss\u00edvel identificar, atrav\u00e9s dos meios dispon\u00edveis no momento do tratamento, a pessoa natural titular da informa\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">O tratamento consiste em toda opera\u00e7\u00e3o realizada com dados pessoais, desde a coleta, produ\u00e7\u00e3o, recep\u00e7\u00e3o, classifica\u00e7\u00e3o, utiliza\u00e7\u00e3o, acesso, reprodu\u00e7\u00e3o, transmiss\u00e3o, distribui\u00e7\u00e3o, processamento, arquivamento, armazenamento, elimina\u00e7\u00e3o, avalia\u00e7\u00e3o, controle da informa\u00e7\u00e3o, modifica\u00e7\u00e3o, comunica\u00e7\u00e3o, transfer\u00eancia, difus\u00e3o ou extra\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">Outros conceitos importantes s\u00e3o os sujeitos envolvidos na opera\u00e7\u00e3o de tratamento de dados. O titular \u00e9 a pessoa a quem os dados tratados se referem, o controlador \u00e9 o sujeito a quem compete as decis\u00f5es acerca do tratamento desses dados, podendo ser tanto pessoa natural quanto jur\u00eddica, de direito p\u00fablico ou privado.<\/h5>\n<h5 style=\"text-align: justify;\">H\u00e1 ainda o operador, aquele que de fato realiza o tratamento dos dados em nome do controlador, havendo tamb\u00e9m, o encarregado, a pessoa indicada para ser um canal de comunica\u00e7\u00e3o entre o controlador, os titulares e a Autoridade Nacional de Prote\u00e7\u00e3o de Dados. J\u00e1 a atua\u00e7\u00e3o conjunta do controlador e operador forma o conjunto de sujeitos denominados como agentes de tratamento.<\/h5>\n<h5 style=\"text-align: justify;\">A LGPD tem como princ\u00edpios: a finalidade que determina que os dados coletados dever\u00e3o ser usados apenas para o fim espec\u00edfico informado ao titular; a adequa\u00e7\u00e3o da forma de tratamento utilizada \u00e0 sua finalidade; a necessidade, devendo o tratamento restringir-se ao m\u00ednimo de informa\u00e7\u00f5es necess\u00e1rias para cumprir a finalidade; o livre acesso do titular \u00e0s suas informa\u00e7\u00f5es; a\u00a0\u00a0qualidade dos dados coletados; a seguran\u00e7a; transpar\u00eancia; a preven\u00e7\u00e3o; a n\u00e3o-discrimina\u00e7\u00e3o; responsabiliza\u00e7\u00e3o e a presta\u00e7\u00e3o de contas.<\/h5>\n<h5 style=\"text-align: justify;\">O Art. 18 da LGPD lista ainda alguns dos direitos do titular, sendo estes o direito de obter do controlador dos dados a confirma\u00e7\u00e3o da exist\u00eancia de tratamento, o acesso aos dados tratados, a corre\u00e7\u00e3o de dados que eventualmente estejam incompletos ou desatualizados, a anonimiza\u00e7\u00e3o, bloqueio ou elimina\u00e7\u00e3o de dados desnecess\u00e1rios, a portabilidade desses dados para outro fornecedor de produto ou servi\u00e7o, informa\u00e7\u00e3o sobre as entidades com as quais o controlador compartilhou esses dados, a revoga\u00e7\u00e3o do consentimento e informa\u00e7\u00f5es sobre a possibilidade de n\u00e3o dar o consentimento e as consequ\u00eancias de uma eventual negativa.<\/h5>\n<h5 style=\"text-align: justify;\">Em face do exposto, \u00e9 poss\u00edvel verificar que o principal intuito desta legisla\u00e7\u00e3o \u00e9 proteger os dados pessoais dos titulares a fim de assegurar o direito \u00e0 privacidade constitucionalmente estabelecido no Art. 5, X da Constitui\u00e7\u00e3o Federal. A LGPD surge com o intuito de impedir a comercializa\u00e7\u00e3o desenfreada de dados pessoais, visando preservar o direito ao livre desenvolvimento do indiv\u00edduo a fim de que este n\u00e3o seja transformado em um mero produto em meio \u00e0 sociedade da informa\u00e7\u00e3o.<\/h5>\n<h5>\u00a0<\/h5>\n<h5 style=\"text-align: justify;\"><strong>LEGISLA\u00c7\u00d5ES INTERNACIONAIS E ESTRANGEIRAS SOBRE PROTE\u00c7\u00c3O DE DADOS<\/strong><\/h5>\n<h5 style=\"text-align: justify;\">A necessidade de prote\u00e7\u00e3o dos dados pessoais \u00e9 um fator que n\u00e3o se limita ao territ\u00f3rio nacional, mas que tem se evidenciado mundialmente, gerando ent\u00e3o o surgimento de diversas legisla\u00e7\u00f5es e protocolos internacionais que buscam regular a mat\u00e9ria.<\/h5>\n<h5 style=\"text-align: justify;\">Com a expans\u00e3o das rela\u00e7\u00f5es pessoais, comerciais, negociais e jur\u00eddicas para al\u00e9m das fronteiras nacionais, surgiu a necessidade de observar, nas transa\u00e7\u00f5es internacionais, as leis acerca do tratamento de dados.<\/h5>\n<h5 style=\"text-align: justify;\">Em decorr\u00eancia disto, a cria\u00e7\u00e3o da LGPD foi fortemente influenciada por outros dispositivos internacionais e estrangeiros que j\u00e1 vinham sendo implementado em outros pa\u00edses, uma dessas legisla\u00e7\u00f5es foi a General Data Protection Regulation \u2013 GDPR, adotada pela Uni\u00e3o Europeia para proteger os dados pessoais referentes a seus cidad\u00e3os.<\/h5>\n<h5 style=\"text-align: justify;\">A cria\u00e7\u00e3o da GDPR uniformizou os crit\u00e9rios para tratamento de dados em toda a Uni\u00e3o Europ\u00e9ia, gerando uma forte press\u00e3o internacional a fim de que os demais pa\u00edses, inclusive o Brasil, se adequassem e implementarem normas mais r\u00edgidas de tratamento de dados para dar continuidade a suas rela\u00e7\u00f5es comerciais com a Europa:<\/h5>\n<h5 style=\"text-align: justify;\">Al\u00e9m das quest\u00f5es \u00e9ticas, a press\u00e3o internacional exercida pela General Data Protection Regulation (GDPR) da Uni\u00e3o Europeia (UE) foi uma motiva\u00e7\u00e3o, definindo que apenas organiza\u00e7\u00f5es de pa\u00edses com um n\u00edvel maior ou igual de rigor para prote\u00e7\u00e3o de dados em\u00a0legisla\u00e7\u00e3o podem armazenar dados pessoais dos cidad\u00e3os da Uni\u00e3o Europ\u00e9ia, impactando, por exemplo, diretamente os neg\u00f3cios brasileiros. (CARVALHO; OLIVEIRA; CAPPELI; MAJER, 2019, p.1)<\/h5>\n<h5 style=\"text-align: justify;\">A GDPR entrou em vigor em 25 de maio de 2018 sendo aplic\u00e1vel a todos os pa\u00edses membros da Uni\u00e3o Europeia e surgiu como uma verdadeira revolu\u00e7\u00e3o acerca do conceito de privacidade ao regular o tratamento de dados pessoais de todos os cidad\u00e3os da Uni\u00e3o Europeia independentemente de onde esses dados ser\u00e3o tratados (GODDARD, Michel, 2017, p.703, tradu\u00e7\u00e3o nossa).<sup>3<\/sup><\/h5>\n<h5 style=\"text-align: justify;\">Existem claras semelhan\u00e7as entre a GDPR e a LGPD que evidenciam o uso da legisla\u00e7\u00e3o europeia como uma fonte de inspira\u00e7\u00e3o na elabora\u00e7\u00e3o da Lei Geral de Prote\u00e7\u00e3o de Dados, tal fato \u00e9 constatado, por exemplo, na conceitua\u00e7\u00e3o legal de alguns termos.<\/h5>\n<h5 style=\"text-align: justify;\">Tanto a LGPD em seu Art.5, inciso I quanto \u00e0 GDPR em seu Art. 4 (1) definem dados pessoais como qualquer informa\u00e7\u00e3o relativa a uma pessoa natural identificada ou identific\u00e1vel. J\u00e1 o termo tratamento, conceituado no Art.5, X da LGPD e no Art.4\u00b0(2) da GDPR, apresenta algumas diverg\u00eancias entre as duas leis, sendo importante ressaltar que ambas apresentam um rol de opera\u00e7\u00f5es realizadas com dados pessoais que se enquadram no conceito, levantando diverg\u00eancias acerca da taxatividade ou n\u00e3o desse dispositivo.<\/h5>\n<h5 style=\"text-align: justify;\">Ambas as legisla\u00e7\u00f5es, na reda\u00e7\u00e3o do conceito de tratamento de dados passam a ideia de um rol meramente exemplificativo:<\/h5>\n<h5 style=\"text-align: justify;\">Art. 5\u00ba Para os fins desta Lei, considera-se:<\/h5>\n<h5 style=\"text-align: justify;\">X \u2013 tratamento: toda opera\u00e7\u00e3o realizada com dados pessoais, como as que se referem a coleta, produ\u00e7\u00e3o, recep\u00e7\u00e3o, classifica\u00e7\u00e3o, utiliza\u00e7\u00e3o, acesso, reprodu\u00e7\u00e3o, transmiss\u00e3o, distribui\u00e7\u00e3o, processamento, arquivamento, armazenamento, elimina\u00e7\u00e3o, avalia\u00e7\u00e3o ou controle da informa\u00e7\u00e3o, modifica\u00e7\u00e3o, comunica\u00e7\u00e3o, transfer\u00eancia, difus\u00e3o ou extra\u00e7\u00e3o;\u201d (BRASIL, LGPD, 2018, Art. 5\u00ba)<\/h5>\n<h5 style=\"text-align: justify;\">Art. 4\u00ba Para fins desta lei, considera-se:<\/h5>\n<h5 style=\"text-align: justify;\">(2) processamento\u2019 significa qualquer opera\u00e7\u00e3o ou conjunto de opera\u00e7\u00f5es realizado em dados pessoais ou em conjuntos de dados pessoais, por meios automatizados ou n\u00e3o, como coleta, registro, organiza\u00e7\u00e3o, estrutura\u00e7\u00e3o, armazenamento, adapta\u00e7\u00e3o ou altera\u00e7\u00e3o, recupera\u00e7\u00e3o, consulta, uso, divulga\u00e7\u00e3o por transmiss\u00e3o, dissemina\u00e7\u00e3o ou de outra forma disponibilizando, alinhamento ou combina\u00e7\u00e3o, restri\u00e7\u00e3o, apagamento ou destrui\u00e7\u00e3o; (UNI\u00c3O EUROP\u00c9IA, GDPR, 2018, Art. 4\u00ba-2,\u00a0<em>tradu\u00e7\u00e3o nossa<\/em>).4<\/h5>\n<h5 style=\"text-align: justify;\">Essa inexatid\u00e3o no conceito de tratamento de dados pode criar um cen\u00e1rio de enorme inseguran\u00e7a para os agentes de tratamento que precisam enquadrar-se nos par\u00e2metros legais. Com um rol t\u00e3o extenso e ampli\u00e1vel \u00e9 preciso haver uma cuidadosa observ\u00e2ncia das medidas necess\u00e1rias para prote\u00e7\u00e3o de dados pessoais.<\/h5>\n<h5 style=\"text-align: justify;\">Outra compara\u00e7\u00e3o necess\u00e1ria diz respeito aos princ\u00edpios norteadores de ambas as legisla\u00e7\u00f5es em an\u00e1lise. A LGPD em seu Art. 6 elenca 10 princ\u00edpios que devem ser observados, j\u00e1 a GDPR em seu Art. 5 enumera 8 princ\u00edpios, apesar de haver algumas diverg\u00eancias entre uma lei e outra, muitos desses institutos se correspondem em ambas as legisla\u00e7\u00f5es.<\/h5>\n<h5 style=\"text-align: justify;\">O princ\u00edpio da finalidade apresenta-se em ambas as leis com a mesma nomenclatura, j\u00e1 a adequa\u00e7\u00e3o, preven\u00e7\u00e3o e necessidade presentes na LGPD apresentam-se reunidos na GDPR como um mesmo princ\u00edpio: a minimiza\u00e7\u00e3o de danos. O princ\u00edpio do livre acesso, previsto na legisla\u00e7\u00e3o brasileira n\u00e3o encontra um correspondente na lei adotada pela Uni\u00e3o Europeia.<\/h5>\n<h5 style=\"text-align: justify;\">A qualidade dos dados \u00e9 nomeada na GDPR como o instituto da exatid\u00e3o dos dados tratados, j\u00e1 os conceitos de n\u00e3o-discrimina\u00e7\u00e3o e transpar\u00eancia foram reunidos em um \u00fanico princ\u00edpio: o da justi\u00e7a e transpar\u00eancia. O conceito de seguran\u00e7a do tratamento de dados \u00e9 nomeado na legisla\u00e7\u00e3o Europeia como integridade e confidencialidade. No que concerne \u00e0 responsabilidade e presta\u00e7\u00e3o de contas previsto pela LGPD, na GDPR consta apenas o princ\u00edpio da presta\u00e7\u00e3o de contas.<\/h5>\n<h5 style=\"text-align: justify;\">Vale ressaltar que a GDPR adota um princ\u00edpio que n\u00e3o foi incorporado \u00e0 legisla\u00e7\u00e3o brasileira: o instituto da limita\u00e7\u00e3o de armazenamento, que consiste na limita\u00e7\u00e3o do armazenamento dos dados por tempo n\u00e3o superior ao necess\u00e1rio para os fins os quais os dados s\u00e3o processados. Abre-se a exce\u00e7\u00e3o por per\u00edodos mais longos desde que os dados sejam processados para fins exclusivamente de interesse p\u00fablico, pesquisa cient\u00edfica, hist\u00f3rica ou fins estat\u00edsticos, devendo ser adotadas as medidas preventivas previstas pela GDPR.<\/h5>\n<h5 style=\"text-align: justify;\">Al\u00e9m da influ\u00eancia direta da GDPR, especificamente no que concerne \u00e0 prote\u00e7\u00e3o de dados no \u00e2mbito da Arbitragem Internacional, a Lei Geral de Prote\u00e7\u00e3o de Dados foi precedida tamb\u00e9m por um protocolo elaborado pelo International Council for Commercial Arbitration -ICCA, em parceria com a New York City Bar Association e o International Institute for Conflict Prevention &amp; Resolution por meio do Working Group on Cybersecurity in International Arbitration que tra\u00e7ou diretrizes gerais para melhorar a ciberseguran\u00e7a nos procedimentos arbitrais.<\/h5>\n<h5 style=\"text-align: justify;\">Esse protocolo tem o status de\u00a0<em>soft law,\u00a0<\/em>uma vez que, foi elaborado por organismos n\u00e3o- estatais visando tra\u00e7ar par\u00e2metros gerais e orienta\u00e7\u00f5es sobre prote\u00e7\u00e3o de dados:<\/h5>\n<h5 style=\"text-align: justify;\">Em s\u00edntese, normas n\u00e3o-estatais devem ser compreendidas como normas emanadas por entes n\u00e3o estatais e que n\u00e3o s\u00e3o consideradas vinculantes. Para fim do estudo sobre processo arbitral, s\u00e3o normas n\u00e3o estatais os instrumentos elaborados por organiza\u00e7\u00f5es<\/h5>\n<h5 style=\"text-align: justify;\">internacionais, institui\u00e7\u00f5es arbitrais e entidades destinadas ao estudo e ao desenvolvimento da arbitragem. Podem ter a forma de leis-modelo, diretrizes, regulamentos, resolu\u00e7\u00f5es, regras, checklists, notas, c\u00f3digos de conduta, entre outros, com a finalidade de organizar o procedimento arbitral, ou certos aspectos desse procedimento, e n\u00e3o possuem car\u00e1ter mandat\u00f3rio ou vinculante. (MANGE; 2014, p. 194)<\/h5>\n<h5 style=\"text-align: justify;\">O Protocolo da ICCA de Ciberseguran\u00e7a na Arbitragem Internacional n\u00e3o tem como intuito estabelecer uma forma espec\u00edfica de prote\u00e7\u00e3o de dados no procedimento arbitral, mas oferece diretrizes, princ\u00edpios gerais que podem ser considerados pelas partes e pelo Tribunal Arbitral, resguardada a autonomia da vontade das partes e a independ\u00eancia dos \u00e1rbitros para julgar quais medidas seriam necess\u00e1rias frente \u00e0s circunst\u00e2ncias de cada caso.<\/h5>\n<h5 style=\"text-align: justify;\">O Protocolo da ICCA ressalta a import\u00e2ncia de que, uma vez estipuladas as medidas para prote\u00e7\u00e3o de dados, estas devem ser devidamente observadas por todos os envolvidos no procedimento arbitral, como disp\u00f5e o Princ\u00edpio 3:<\/h5>\n<h5 style=\"text-align: justify;\">As partes, \u00e1rbitros e institui\u00e7\u00f5es administradoras devem garantir que todas as pessoas direta ou indiretamente envolvidas em uma arbitragem em seu nome estejam cientes e sigam quaisquer medidas de seguran\u00e7a da informa\u00e7\u00e3o adotadas em um processo, bem como o impacto potencial de quaisquer incidentes de seguran\u00e7a (ICCA, 2020, p. 1,\u00a0<em>tradu\u00e7\u00e3o nossa<\/em>)5<\/h5>\n<h5 style=\"text-align: justify;\">A n\u00e3o observ\u00e2ncia das medidas de seguran\u00e7a adotadas pode gerar puni\u00e7\u00f5es para aquele que eventualmente d\u00ea causa a um vazamento de informa\u00e7\u00f5es e incidentes de seguran\u00e7a da informa\u00e7\u00e3o podem gerar uma aloca\u00e7\u00e3o dos custos entre as partes, conforme prev\u00ea o Princ\u00edpio 13 do Protocolo da ICCA:<\/h5>\n<h5 style=\"text-align: justify;\">Em caso de viola\u00e7\u00e3o das medidas de seguran\u00e7a da informa\u00e7\u00e3o adotadas em procedimento arbitral ou na ocorr\u00eancia de incidente de seguran\u00e7a da informa\u00e7\u00e3o, o tribunal arbitral poder\u00e1, a seu crit\u00e9rio: (a) alocar os custos relacionados entre as partes; e \/ ou (b) impor san\u00e7\u00f5es \u00e0s partes (ICCA, 2020, p. 3,\u00a0<em>tradu\u00e7\u00e3o nossa<\/em>).6<\/h5>\n<h5 style=\"text-align: justify;\">Para que sejam determinadas as medidas de prote\u00e7\u00e3o de dados adequadas a cada caso, o Protocolo sugere no Princ\u00edpio n\u00ba 6 alguns fatores a serem considerados pelas partes, pela C\u00e2mara Arbitral e pelo Tribunal Arbitral: o perfil de risco da arbitragem; as pr\u00e1ticas existentes de seguran\u00e7a da informa\u00e7\u00e3o, infraestrutura e capacidade das partes; os encargos, custos e recursos; a proporcionalidade em rela\u00e7\u00e3o ao tamanho, valor e perfil de risco da controv\u00e9rsia e a efici\u00eancia do procedimento arbitral.<\/h5>\n<h5 style=\"text-align: justify;\">O instituto traz ainda uma lista das principais \u00e1reas de vulnerabilidade que precisam ser observadas e fortalecidas para garantir a maior prote\u00e7\u00e3o dos dados pessoais coletados durante um procedimento arbitral, como disp\u00f5e o Princ\u00edpio n\u00ba 7 do Protocolo da ICCA:<\/h5>\n<h5 style=\"text-align: justify;\">Princ\u00edpio 7 Ao considerar as medidas espec\u00edficas de seguran\u00e7a da informa\u00e7\u00e3o a serem aplicadas em uma arbitragem, devem ser consideradas as seguintes categorias:<\/h5>\n<ul style=\"text-align: justify;\">\n<li>\n<h5>gest\u00e3o de ativos;<\/h5>\n<\/li>\n<li>\n<h5>controles de acesso;<\/h5>\n<\/li>\n<li>\n<h5>criptografia;<\/h5>\n<\/li>\n<li>\n<h5>seguran\u00e7a das comunica\u00e7\u00f5es;<\/h5>\n<\/li>\n<li>\n<h5>seguran\u00e7a f\u00edsica e ambiental;<\/h5>\n<\/li>\n<li>\n<h5>seguran\u00e7a das opera\u00e7\u00f5es; e<\/h5>\n<\/li>\n<li>\n<h5>gest\u00e3o de incidentes de seguran\u00e7a da informa\u00e7\u00e3o. (ICCA, 2020, 2,\u00a0<em>tradu\u00e7\u00e3o nossa<\/em>)7<\/h5>\n<\/li>\n<\/ul>\n<h5 style=\"text-align: justify;\">Diante disto, \u00e9 poss\u00edvel verificar que, em todo o mundo, a prote\u00e7\u00e3o de dados, sejam eles armazenados em meio f\u00edsico ou virtual, tem sido alvo de muitos questionamentos e estudos, havendo ainda um cen\u00e1rio de incerteza mesmo nos pa\u00edses que j\u00e1 regulamentaram a mat\u00e9ria. Assim como o modo de compartilhar informa\u00e7\u00f5es est\u00e1 em constante mudan\u00e7a, a prote\u00e7\u00e3o dessas informa\u00e7\u00f5es \u00e9 uma atividade din\u00e2mica e extremamente necess\u00e1ria. Nenhuma legisla\u00e7\u00e3o foi capaz de trazer uma resposta definitiva acerca da seguran\u00e7a de dados, mas \u00e9 evidente o crescimento desse setor no estudo do Direito.<\/h5>\n<h5>\u00a0<\/h5>\n<h5 style=\"text-align: justify;\">A NECESSIDADE DE PROTE\u00c7\u00c3O DE DADOS NAS C\u00c2MARAS DE ARBITRAGEM<\/h5>\n<h5 style=\"text-align: justify;\">A Lei de Arbitragem em seu Art. 10 estabelece a necessidade de qualifica\u00e7\u00e3o das partes compromitentes, a fim de que haja identifica\u00e7\u00e3o dos contratantes. A esse respeito o douto professor Carlos Alberto Carmona delineia:<\/h5>\n<h5 style=\"text-align: justify;\">O primeiro inciso do Art.10 preocupou-se com a qualifica\u00e7\u00e3o, t\u00e3o completa quanto poss\u00edvel, das partes compromitentes. O objetivo da regra sob an\u00e1lise \u00e9 apenas o de deixar fora de qualquer d\u00favida a identifica\u00e7\u00e3o dos contratantes. (CARMONA, 2009, p.198)<\/h5>\n<h5 style=\"text-align: justify;\">Essa qualifica\u00e7\u00e3o dos sujeitos envolvidos no procedimento arbitral enquadra-se exatamente no conceito de dado pessoal apresentado pela LGPD, uma vez que, ao longo do procedimento arbitral ser\u00e3o coletadas diversas informa\u00e7\u00f5es relativas \u00e0s partes devidamente identificadas.<\/h5>\n<h5 style=\"text-align: justify;\">Vale salientar que, ainda que o procedimento envolva pessoas jur\u00eddicas, algumas das informa\u00e7\u00f5es coletadas podem referir-se especificamente a pessoas naturais ocupantes de cargos<\/h5>\n<h5 style=\"text-align: justify;\">diretivos das empresas envolvidas, enquadrando-se, nesses casos, no conceito de dado pessoal protegido pela LGDP.<\/h5>\n<h5 style=\"text-align: justify;\">Como resultado dessa necessidade de qualifica\u00e7\u00e3o e coleta de informa\u00e7\u00f5es, as C\u00e2maras Arbitrais possuem um enorme banco de dados acerca de seus clientes, \u00e1rbitros, experts e testemunhas, seja por meio de um cadastro desses dados em seu sistema interno, seja atrav\u00e9s das provas coletadas no curso do procedimento arbitral, em decorr\u00eancia disto, h\u00e1 a necessidade de regular o tratamento desses dados.<\/h5>\n<h5 style=\"text-align: justify;\">Em uma sociedade em que a reputa\u00e7\u00e3o e a opini\u00e3o p\u00fablica s\u00e3o fatores t\u00e3o relevantes para uma empresa quanto os seus pr\u00f3prios rendimentos, \u00e9 preciso atentar para a ado\u00e7\u00e3o de a\u00e7\u00f5es preventivas para prote\u00e7\u00e3o de dados pessoais. As medidas de prote\u00e7\u00e3o de dados s\u00e3o t\u00e3o necess\u00e1rias quanto as ferramentas de\u00a0<em>compliance\u00a0<\/em>para afastar o envolvimento em atos anticoncorrenciais, as medidas para maior diversidade e inclus\u00e3o, bem como, a preocupa\u00e7\u00e3o com a consci\u00eancia ambiental que atualmente s\u00e3o fatores extremamente relevantes para a imagem de uma empresa. A ado\u00e7\u00e3o dessas medidas j\u00e1 se tornou um fator diferencial na competitividade do mercado.<\/h5>\n<h5 style=\"text-align: justify;\">As C\u00e2maras Arbitrais, tais quais as empresas privadas, devem grande parte de sua atua\u00e7\u00e3o ao prest\u00edgio a elas associado, de modo que, qualquer mat\u00e9ria capaz de interferir na credibilidade dessas institui\u00e7\u00f5es, precisa ser devidamente analisada.<\/h5>\n<h5 style=\"text-align: justify;\">Atualmente j\u00e1 existem casos de ataques cibern\u00e9ticos a C\u00e2maras Arbitrais, cabendo destacar o caso ocorrido em 2015 na Permanent Court of Arbitration em Haia, na Holanda, na qual ocorreu um ataque cibern\u00e9tico ao site da C\u00e2mara Arbitral no curso de um procedimento entre a China e as Filipinas acerca do controle do Mar do Sul da China. Ocorre que a invas\u00e3o do site possibilitou o acesso aos computadores dos diplomatas e advogados envolvidos no caso, de modo que a China contou com uma vantagem indevida.<\/h5>\n<h5 style=\"text-align: justify;\">O pr\u00f3prio Judici\u00e1rio brasileiro vem sendo alvo de ataques cibern\u00e9ticos que j\u00e1 invadiram o sistema do Superior Tribunal de Justi\u00e7a em 03 de novembro de 2020, o que gerou a suspens\u00e3o dos prazos processuais e sess\u00f5es de julgamento (VALENTE; VITAL; 2020, p.1). De igual modo, o Tribunal Regional Federal da 1\u00aa Regi\u00e3o sofreu um ataque cibern\u00e9tico pelo qual um perfil an\u00f4nimo na rede social Twitter assumiu a autoria no dia 27 de novembro de 2020 (JURINEWS; 2020, p.1)<\/h5>\n<h5 style=\"text-align: justify;\">Os ataques cibern\u00e9ticos s\u00e3o uma realidade assustadora tanto no setor p\u00fablico quanto no privado e causam danos irrepar\u00e1veis \u00e0s organiza\u00e7\u00f5es atacadas. No \u00e2mbito das C\u00e2maras Arbitrais esse preju\u00edzo pode ser ainda maior, compreendendo n\u00e3o apenas danos econ\u00f4micos, como tamb\u00e9m, possibilitando a realiza\u00e7\u00e3o de quebras de confian\u00e7a que comprometeriam a credibilidade da institui\u00e7\u00e3o e colocariam em d\u00favida a independ\u00eancia e a imparcialidade dos \u00e1rbitros.<\/h5>\n<h5 style=\"text-align: justify;\">A necessidade de prote\u00e7\u00e3o dos dados nas C\u00e2maras Arbitrais n\u00e3o se restringe ao \u00e2mbito do procedimento arbitral, abrangendo tamb\u00e9m as informa\u00e7\u00f5es armazenadas para al\u00e9m do procedimento a fim de que essas n\u00e3o venham a ser acessadas ilegalmente e utilizadas para outras finalidades.<\/h5>\n<h5 style=\"text-align: justify;\">No ano de 2015, a Cambridge Analytica, uma firma brit\u00e2nica, acessou dados pessoais de 87 (oitenta e sete) milh\u00f5es de usu\u00e1rios do Facebook para fazer a an\u00e1lise dessas informa\u00e7\u00f5es e atrav\u00e9s delas e influenciar os eleitores nos Estados Unidos da Am\u00e9rica (ISAAK E HANNA, 2018, p.56\/59). Outro caso importante ocorreu em 2014, no Brasil, no qual a empresa de telecomunica\u00e7\u00e3o Velox foi acusada de vender dados pessoais de seus clientes a terceiros, ilegalmente, sendo condenada a pagar multa de R$3,5 milh\u00f5es (ZANATTA, 2015, p.447\/470). Ambos os casos, demonstram que, por mais irrelevante que a informa\u00e7\u00e3o aparente ser, esta precisa ser resguardada e deve atender aos limites da finalidade para a qual foi coletada, sendo sempre observado o consentimento do titular.<\/h5>\n<h5 style=\"text-align: justify;\">Outro fator indispens\u00e1vel \u00e0 adequa\u00e7\u00e3o das C\u00e2maras Arbitrais \u00e0 LGPD \u00e9 o da transfer\u00eancia internacional de dados, entendida com a transfer\u00eancia de dados pessoais para pa\u00eds estrangeiro ou organismo internacional do qual o pa\u00eds seja membro.<\/h5>\n<h5 style=\"text-align: justify;\">A LGPD regula o tema nos seus Artigos 33 a 36 e apresenta as hip\u00f3teses em que \u00e9 autorizada a transfer\u00eancia internacional de dados:<\/h5>\n<h5 style=\"text-align: justify;\">Art. 33. A transfer\u00eancia internacional de dados pessoais somente \u00e9 permitida nos seguintes casos:<\/h5>\n<ul style=\"text-align: justify;\">\n<li>\n<h5>\u2013 para pa\u00edses ou organismos internacionais que proporcionem grau de prote\u00e7\u00e3o de dados pessoais adequado ao previsto nesta Lei;<\/h5>\n<\/li>\n<li>\n<h5>\u2013 quando o controlador oferecer e comprovar garantias de cumprimento dos princ\u00edpios, dos direitos do titular e do regime de prote\u00e7\u00e3o de dados previstos nesta Lei, na forma de:<\/h5>\n<\/li>\n<\/ul>\n<ol style=\"text-align: justify;\">\n<li>\n<h5>cl\u00e1usulas contratuais espec\u00edficas para determinada transfer\u00eancia;<\/h5>\n<\/li>\n<li>\n<h5>cl\u00e1usulas-padr\u00e3o contratuais;<\/h5>\n<\/li>\n<li>\n<h5>normas corporativas globais;<\/h5>\n<\/li>\n<li>\n<h5>selos, certificados e c\u00f3digos de conduta regularmente emitidos;[\u2026](BRASIL, LGPD, 2018, 33)<\/h5>\n<\/li>\n<\/ol>\n<h5 style=\"text-align: justify;\">Nota-se que um dos requisitos de autoriza\u00e7\u00e3o da transfer\u00eancia internacional de dados \u00e9 atrav\u00e9s da comprova\u00e7\u00e3o do cumprimento dos direitos do titular por meio de cl\u00e1usulas contratuais espec\u00edficas que autorizam a transfer\u00eancia. Essa hip\u00f3tese abre a possibilidade de inclus\u00e3o de cl\u00e1usulas contratuais acerca da transfer\u00eancia de dados juntamente com o compromisso arbitral ou cl\u00e1usula compromiss\u00f3ria, a fim de legitimar a transfer\u00eancia desses dados em arbitragens internacionais.<\/h5>\n<h5 style=\"text-align: justify;\">Outro requisito observado \u00e9 de que o pa\u00eds ou organismo internacional para quem esses dados ser\u00e3o transferidos deve proporcionar o mesmo grau de prote\u00e7\u00e3o dos dados previstos pela LGPD, ressalta-se que a GDPR, em seu Artigo 46, tamb\u00e9m apresenta esse requisito para<\/h5>\n<h5 style=\"text-align: justify;\">transfer\u00eancia de dados entre pa\u00edses da Uni\u00e3o Europeia e os demais pa\u00edses. Isso demonstra a tend\u00eancia mundial e crescente de buscar rela\u00e7\u00f5es comerciais, contratuais e jur\u00eddicas apenas entre institui\u00e7\u00f5es que possuam medidas adequadas para prote\u00e7\u00e3o de dados.<\/h5>\n<h5 style=\"text-align: justify;\">Tanto a GDPR em seu Artigo 46.2 quanto a LGPD no Artigo 34 estabelecem a necessidade de que o pa\u00eds ou organiza\u00e7\u00e3o de destino tenha uma regulamenta\u00e7\u00e3o que atenda aos princ\u00edpios gerais da prote\u00e7\u00e3o de dados pessoais e que adote medidas de seguran\u00e7a para resguardar os direitos dos titulares das informa\u00e7\u00f5es.<\/h5>\n<h5 style=\"text-align: justify;\">Desse modo, a cria\u00e7\u00e3o da Lei Geral de Prote\u00e7\u00e3o de Dados apresenta-se como uma verdadeira revolu\u00e7\u00e3o n\u00e3o apenas no funcionamento de empresas, como tamb\u00e9m nos procedimentos de arbitragem internacional que, al\u00e9m de coletar informa\u00e7\u00f5es, frequentemente transferem os dados coletados para outras institui\u00e7\u00f5es internacionais e estrangeiras.<\/h5>\n<h5>\u00a0<\/h5>\n<h5 style=\"text-align: justify;\">1.\u00a0\u00a0 ADEQUA\u00c7\u00d5ES NECESS\u00c1RIAS PARA AS C\u00c2MARAS ARBITRAIS<\/h5>\n<h5 style=\"text-align: justify;\">Um dos princ\u00edpios norteadores da Lei Geral de Prote\u00e7\u00e3o de Dados \u00e9 o princ\u00edpio da preven\u00e7\u00e3o que determina o dever dos agentes de tratamento de adotarem medidas para prevenir poss\u00edveis danos decorrentes do tratamento de dados pessoais, nos termos do Art. 6 da referida lei. Esse princ\u00edpio, aliado ao princ\u00edpio da seguran\u00e7a, da responsabiliza\u00e7\u00e3o e da presta\u00e7\u00e3o de contas gera a necessidade de adequa\u00e7\u00e3o dos diversos agentes de tratamento aos termos da LGPD, bem como, a ado\u00e7\u00e3o de medidas preventivas que resguardem o direito dos titulares:<\/h5>\n<h5 style=\"text-align: justify;\">Outra fundamental caracter\u00edstica da nova legisla\u00e7\u00e3o consiste no significativo fomento ao aspecto preventivo, estabelecendo procedimentos mandat\u00f3rios para os controladores e operadores de dados pessoais, tais como os deveres atinentes \u00e0 implementa\u00e7\u00e3o de severas pol\u00edticas de seguran\u00e7a para prote\u00e7\u00e3o dos dados de acessos n\u00e3o autorizados. (FRAZ\u00c3O; TEPEDINO; OLIVA; 2019, p.681)<\/h5>\n<h5 style=\"text-align: justify;\">Diversas s\u00e3o as possibilidades de medidas a serem adotadas para proteger dados pessoais tanto por meio da cria\u00e7\u00e3o de protocolos, imposi\u00e7\u00e3o de limites de acesso e divulga\u00e7\u00e3o de informa\u00e7\u00f5es, quanto por meio do estabelecimento de diretrizes em casos de ciberataques.<\/h5>\n<h5 style=\"text-align: justify;\">Uma vez que as partes e o tribunal tenham avaliado as custas e o procedimento, as partes e o tribunal podem ent\u00e3o considerar os tr\u00eas princ\u00edpios tem\u00e1ticos a seguir com rela\u00e7\u00e3o \u00e0 amea\u00e7a de ciberataques no contexto da arbitragem: (i) o estabelecimento de protocolos de seguran\u00e7a para o armazenamento e transfer\u00eancia de informa\u00e7\u00f5es confidenciais, (ii) limita\u00e7\u00e3o da divulga\u00e7\u00e3o de informa\u00e7\u00f5es confidenciais, e (iii) em caso de qualquer viola\u00e7\u00e3o \/ ataque, o processo para notificar a pessoa afetada e para corrigir \/ mitigar a viola\u00e7\u00e3o \/ ataque.(PASTORE; 2017, p. 1028)<\/h5>\n<h5 style=\"text-align: justify;\">No Brasil, n\u00e3o h\u00e1 uma regulamenta\u00e7\u00e3o espec\u00edfica acerca da ciberseguran\u00e7a na arbitragem, deixando a crit\u00e9rio de cada C\u00e2mara Arbitral o desenvolvimento de seus pr\u00f3prios meios de seguran\u00e7a. Faz-se necess\u00e1rio, portanto, que sejam estabelecidos protocolos internos nas\u00a0institui\u00e7\u00f5es, contando com a expertise tanto de profissionais do direito quanto de profissionais da tecnologia especializados na \u00e1rea.<\/h5>\n<h5 style=\"text-align: justify;\">Al\u00e9m disso, \u00e9 essencial a promo\u00e7\u00e3o de par\u00e2metros gerais, diretrizes m\u00ednimas a serem seguidas pelos Tribunais Arbitrais do pa\u00eds todo, resguardada a autonomia dos \u00e1rbitros para decis\u00e3o das medidas de seguran\u00e7a mais adequadas para cada caso.<\/h5>\n<h5 style=\"text-align: justify;\">A cria\u00e7\u00e3o de equipes multidisciplinares fixas dentro das C\u00e2maras Arbitrais tamb\u00e9m se tornou um requisito inafast\u00e1vel, visto que, \u00e9 necess\u00e1rio profissionais do direito para a compreens\u00e3o dos aspectos jur\u00eddicos da LGPD e profissionais da tecnologia para colocar em pr\u00e1tica as medidas de seguran\u00e7a.<\/h5>\n<h5 style=\"text-align: justify;\">O Protocolo da ICCA elenca diversas medidas de prote\u00e7\u00e3o de dados que podem ser adotadas pelos Tribunais Arbitrais que merecem ser destacadas para serem aplicadas tamb\u00e9m no Brasil. A primeira diretriz apresentada \u00e9 a do Conhecimento e Educa\u00e7\u00e3o, \u00e9 essencial manter-se informado sobre as amea\u00e7as e solu\u00e7\u00f5es de seguran\u00e7a, a seguran\u00e7a de dados requer aten\u00e7\u00e3o cont\u00ednua e constante atualiza\u00e7\u00e3o, sendo necess\u00e1rio que as institui\u00e7\u00f5es procurem estar sempre a par das medidas de prote\u00e7\u00e3o de dados mais atuais e repassem esse conhecimento para aqueles que possuem acesso \u00e0s informa\u00e7\u00f5es tratadas.<\/h5>\n<h5 style=\"text-align: justify;\">Outro aspecto importante \u00e9 a gest\u00e3o de ativos, a consci\u00eancia de onde esses dados est\u00e3o circulando e o investimento na qualidade da infraestrutura digital utilizada, bem como, a necessidade de estabelecer pr\u00e1ticas e pol\u00edticas organizacionais e dar ci\u00eancia delas aos profissionais e partes que de alguma forma possuem acesso \u00e0 informa\u00e7\u00e3o, para que estas adotem as diretrizes necess\u00e1rias, por exemplo, para proteger os dados acessados por meio de um dispositivo pessoal.<\/h5>\n<h5 style=\"text-align: justify;\">A pr\u00f3pria minimiza\u00e7\u00e3o dos dados coletados tamb\u00e9m deve ser uma medida recorrente, que encontra previs\u00e3o na LGPD e tamb\u00e9m foi adotada pela GDPR. Al\u00e9m disso, h\u00e1 a necessidade de evitar c\u00f3pias desnecess\u00e1rias de documentos e estabelecer pr\u00e1ticas de reten\u00e7\u00e3o e destrui\u00e7\u00e3o dessas informa\u00e7\u00f5es desnecess\u00e1rias, tanto no meio digital, quanto nas c\u00f3pias f\u00edsicas.<\/h5>\n<h5 style=\"text-align: justify;\">Outra medida que deve ser observada, principalmente no curso de arbitragens internacionais, \u00e9 a limita\u00e7\u00e3o do acesso a dados confidenciais durante viagens. As arbitragens internacionais muitas vezes requerem um deslocamento entre um pa\u00eds e outro, de modo que, ao transitar entre diversas redes n\u00e3o seguras e acessar dados referentes ao procedimento arbitral, o \u00e1rbitro, expert ou parte envolvida pode acabar facilitando o vazamento dessas informa\u00e7\u00f5es.<\/h5>\n<h5 style=\"text-align: justify;\">Ademais, existe a necessidade de estabelecer um sistema de backups peri\u00f3dicos, tanto por meio da nuvem quanto atrav\u00e9s de dispositivos externos. Outra medida que pode ser implementada \u00e9 a limita\u00e7\u00e3o do acesso a esses dados, estabelecendo quais indiv\u00edduos poder\u00e3o ter acesso,\u00a0implementando senhas fortes com altera\u00e7\u00f5es peri\u00f3dicas e at\u00e9 mesmo requerendo identifica\u00e7\u00e3o biom\u00e9trica ou identifica\u00e7\u00e3o multifatorial.<\/h5>\n<h5 style=\"text-align: justify;\">A criptografia para a transmiss\u00e3o de dados tamb\u00e9m \u00e9 uma medida indispens\u00e1vel na Arbitragem Internacional, uma vez que grande parte das comunica\u00e7\u00f5es oficiais do procedimento ocorrem por e-mail e frequentemente cont\u00eam informa\u00e7\u00f5es sigilosas. Al\u00e9m da criptografia \u00e9 poss\u00edvel recorrer a servi\u00e7os especializados de compartilhamento de dados, sendo essencial orientar os usu\u00e1rios de como proceder para resguardar as informa\u00e7\u00f5es e evitar vazamento de dados por falha humana.<\/h5>\n<h5 style=\"text-align: justify;\">Tanto a LGPD, quanto a GDPR e o Protocolo da ICCA ressaltam que a prote\u00e7\u00e3o de dados n\u00e3o se refere apenas \u00e0s informa\u00e7\u00f5es armazenadas em meio digital, como tamb\u00e9m, documentos salvos em meio f\u00edsico. Em vista disso, h\u00e1 a necessidade ainda de resguardar o pr\u00f3prio espa\u00e7o f\u00edsico de armazenamento de documentos das C\u00e2maras Arbitrais a fim de que n\u00e3o haja extravio de documenta\u00e7\u00e3o armazenada fisicamente.<\/h5>\n<h5 style=\"text-align: justify;\">Para proteger adequadamente as informa\u00e7\u00f5es \u00e9 necess\u00e1rio investimento nas ferramentas eficientes, pois, apesar dos in\u00fameros recursos dispon\u00edveis gratuitamente e tendo em vista a natureza das informa\u00e7\u00f5es compartilhadas nos procedimentos arbitrais, \u00e9 necess\u00e1rio que as C\u00e2maras Arbitrais se adaptem a essa nova legisla\u00e7\u00e3o investindo amplamente na seguran\u00e7a dos dados tratados, a fim de garantir a privacidade dos titulares e resguardar a credibilidade da institui\u00e7\u00e3o.<\/h5>\n<h5>\u00a0<\/h5>\n<h5 style=\"text-align: justify;\">2.\u00a0\u00a0 CONCLUS\u00c3O<\/h5>\n<h5 style=\"text-align: justify;\">A prote\u00e7\u00e3o de dados pessoais \u00e9 uma tem\u00e1tica ainda pouco explorada e recentemente regulamentada pelo direito brasileiro, o tratamento de dados apesar de ser uma pr\u00e1tica extremamente recorrente, somente ganhou um enfoque maior a partir das novas necessidades trazidas pelo desenvolvimento da tecnologia e das inova\u00e7\u00f5es relativas \u00e0 coleta de informa\u00e7\u00f5es.<\/h5>\n<h5 style=\"text-align: justify;\">A Lei Geral de Prote\u00e7\u00e3o de Dados foi elaborada objetivando assegurar o livre desenvolvimento da pessoa natural e garantir a liberdade e a privacidade dos titulares desses dados. Em vista disso, surge a necessidade de adequa\u00e7\u00e3o dos agentes de tratamento \u00e0s novas diretrizes tra\u00e7adas pela LGPD a fim de prevenir o vazamento e mal uso de informa\u00e7\u00f5es pessoais.<\/h5>\n<h5 style=\"text-align: justify;\">No contexto dos procedimentos arbitrais h\u00e1 uma necessidade ainda maior de prote\u00e7\u00e3o dessas informa\u00e7\u00f5es, de modo que, as C\u00e2maras Arbitrais, em observ\u00e2ncia ao princ\u00edpio da preven\u00e7\u00e3o, responsabilidade e presta\u00e7\u00e3o de contas, dever\u00e3o adotar medidas minuciosas para resguardar esses dados.<\/h5>\n<h5 style=\"text-align: justify;\">Essas adequa\u00e7\u00f5es s\u00e3o essenciais n\u00e3o apenas para assegurar o direito dos titulares, como tamb\u00e9m, proteger a credibilidade e reputa\u00e7\u00e3o das C\u00e2maras Arbitrais, uma vez que, as medidas preventivas tornaram-se par\u00e2metros para avaliar a credibilidade dessas institui\u00e7\u00f5es. A elabora\u00e7\u00e3o de protocolos, a cria\u00e7\u00e3o de setores especializados em ciberseguran\u00e7a e a exclus\u00e3o peri\u00f3dica de dados desnecess\u00e1rios s\u00e3o apenas algumas das mudan\u00e7as essenciais para proteger os procedimentos arbitrais dom\u00e9sticos e internacionais dos riscos trazidos pelo vazamento de dados pessoais.<\/h5>\n<h5 style=\"text-align: justify;\">Portanto, vislumbra-se claramente que a cria\u00e7\u00e3o da Lei Geral de Prote\u00e7\u00e3o de Dados trouxe um avan\u00e7o consider\u00e1vel nas discuss\u00f5es sobre seguran\u00e7a de informa\u00e7\u00f5es, entretanto, no \u00e2mbito da arbitragem internacional ainda h\u00e1 muito a ser regulamentado e adequado para garantir a prote\u00e7\u00e3o dos dados pessoais e o direito constitucional \u00e0 privacidade.<\/h5>\n<h5>\u00a0<\/h5>\n<h5 style=\"text-align: justify;\">3.\u00a0\u00a0 REFER\u00caNCIAS<\/h5>\n<h5 style=\"text-align: justify;\">BRASIL. Lei 13.709 de 14 de agosto de 2018. Lei Geral de Prote\u00e7\u00e3o de Dados Pessoais (LGPD).Bras\u00edlia, DF: Presid\u00eancia da Rep\u00fablica [2018]. Dispon\u00edvel em: http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015- 2018\/2018\/Lei\/L13709.htm. Acesso em: 24 nov 2020.<\/h5>\n<h5 style=\"text-align: justify;\">CARMONA, Carlos Alberto. Arbitragem e Processo. 3\u00aa Edi\u00e7\u00e3o, S\u00e3o Paulo,Editora Atlas, 2009, p.198.<\/h5>\n<h5 style=\"text-align: justify;\">CARVALHO, Lu\u00eds Paulo; OLIVEIRA, Jonice; CAPPELI, Claudia; MAJER, Violeta. Desafios de Transpar\u00eancia pela Lei Geral de Prote\u00e7\u00e3o de Dados. 2019. Programa de P\u00f3s-gradua\u00e7\u00e3o em Inform\u00e1tica, Universidade Federal do Rio de Janeiro \u2013 UFRJ , p.1.<\/h5>\n<h5 style=\"text-align: justify;\">COSTA, Tiago R. Veloso. Prote\u00e7\u00e3o de Dados e Arbitragem: para al\u00e9m de uma quest\u00e3o legal. JOTA, 2019.Dispon\u00edvel em: https:\/\/www.jota.info\/opiniao-e-analise\/artigos\/protecao-de-dados-e-arbitragem- para-alem-de-uma-questao-legal-29062019 Acesso em: 24 nov 2020.<\/h5>\n<h5 style=\"text-align: justify;\">FRAZ\u00c3O, Ana; TEPEDINO, Gustavo; OLIVA, Milena Donato, A Lei Geral de Prote\u00e7\u00e3o de dados pessoais e suas repercuss\u00f5es no direito brasileiro, Revista dos Tribunais, 2\u00aa Edi\u00e7\u00e3o, S\u00e3o Paulo, 2019,p. 677\/678.<\/h5>\n<h5 style=\"text-align: justify;\">GODDARD, Michele. The EU General Data Protection Regulation (GDPR): European Regulation that has a Global Impact International Journal of Marketing Research. 2017. International Joural of Market Research, vol. 59, P. 703\/705. Dispon\u00edvel em: https:\/\/journals.sagepub.com\/doi\/abs\/10.2501\/IJMR-2017-050?journalCode=mrea. Acesso em: 24 nov 2020.<\/h5>\n<h5 style=\"text-align: justify;\">ICCA; NYC Bar; CPR. Cybersecurity Protocol for International Arbitration. 2019. [S.I.], International Council for Commercial Arbitration, New York City Bar Association, and International Institute for Conflict Prevention and Resolution.<\/h5>\n<h5 style=\"text-align: justify;\">ISAAK, J., HANNA, M. J.User Data Privacy: Facebook, Cambridge Analytica, and Privacy Protection, 2018, IEEE, Computer 51 (8), p. 56\/59.<\/h5>\n<h5 style=\"text-align: justify;\">VIROU moda: TRF1 sofre ataque hacker e site est\u00e1 fora do ar. Jurinews: not\u00edcias jur\u00eddicas. Publicado em 27 nov 2020. Dispon\u00edvel em: https:\/\/jurinews.com.br\/tecnologia\/virou-moda-site-do-trf1-sofre- ataque-hacker\/. Acesso em: 29 nov 2020.<\/h5>\n<h5 style=\"text-align: justify;\">MANGE,Flavia Foz. Processo Arbitral: aspectos transnacionais. Editora Quartier Latin do Brasil, S\u00e3o Paulo, 2014.<\/h5>\n<h5 style=\"text-align: justify;\">PASTORE, Jim; Practical Approaches To Cybersecurity In Arbitration. Fordham International Law Journal, [S.I.], volume 14, 2017.<\/h5>\n<h5 style=\"text-align: justify;\">UNI\u00c3O EUROPEIA. EU General Data Protection Regulation (GDPR). Dispon\u00edvel em: https:\/\/gdpr- info.eu. [S.I.]. Acesso em: 24 nov 2020.<\/h5>\n<h5 style=\"text-align: justify;\">VALENTE, Fernanda; VITAL, Danilo. STJ sofre ataque hacker e suspende prazos processuais at\u00e9 segunda-feira.CONJUR.Publicado em 04 nov 2020. Dispon\u00edvel em: https:\/\/www.conjur.com.br\/2020- nov-04\/stj-sofre-ataque-hacker-suspende-prazos-segunda-911 Acesso em: 29 nov 2020.<\/h5>\n<h5 style=\"text-align: justify;\">ZANATTA, R. A Prote\u00e7\u00e3o de Dados entre Leis, C\u00f3digos e Programa\u00e7\u00e3o: os limites do Marco Civil da Internet, 2015, S\u00e3o Paulo: Quartier Latin, p. 447\/470.<\/h5>\n<h5 style=\"text-align: justify;\">Por <strong>Adriano Fernandes Ferreira<\/strong>, Gradua\u00e7\u00e3o em Direito pelo Centro Universit\u00e1rio de Maring\u00e1 (2001), Mestrado em Direito pela Universidade Gama Filho (2005), Doutorado em Ci\u00eancias Jur\u00eddicas pela Universidad Castilha la Mancha, na Espanha (2014) e P\u00f3s-Doutor em Direito Pela Universidade de Santiago de Compostela, na Espanha (2019). Atualmente \u00e9 professor Adjunto IV, da Universidade Federal do Amazonas- UFAM &#8211; das disciplinas de Direito Internacional P\u00fablico e Direito Internacional Privado e Vice-Diretor da Faculdade de Direito da UFAM. E <strong>Eloah Scantelbury de Almeid<\/strong>a,\u00a0Membro do Grupo de Estudos em Arbitragem e Direito Empresarial- UFAM, do N\u00facleo de Estudos em Arbitragem do Norte, do Young International Council for Commercial Arbitration e do Comit\u00ea de Jovens Arbitralistas. Competidora do 27 Willem C. Vis International Commercial Arbitration Moot (2019) e da XI Competi\u00e7\u00e3o Brasileira de Arbitragem da CAMARB (2020). Men\u00e7\u00e3o Honrosa na Competi\u00e7\u00e3o Regional Norte de Arbitragem, 2020. Graduanda em direito na Universidade Federal do Amazonas, Manaus, Amazonas.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: OAB\/RJ &#8211; 11\/10\/2022.<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adambrasil.com\/an\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>A prote\u00e7\u00e3o de dados pessoais \u00e9 uma tem\u00e1tica ainda pouco explorada e recentemente regulamentada pelo direito brasileiro, o tratamento de dados apesar de ser uma pr\u00e1tica extremamente recorrente, somente ganhou um enfoque maior a partir das novas necessidades trazidas pelo desenvolvimento da tecnologia e das inova\u00e7\u00f5es relativas \u00e0 coleta de informa\u00e7\u00f5es.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,14],"tags":[11,13,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/10045"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=10045"}],"version-history":[{"count":0,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/10045\/revisions"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=10045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=10045"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=10045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}