﻿{"id":10001,"date":"2021-12-25T00:23:00","date_gmt":"2021-12-24T21:23:00","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo\/?p=10001"},"modified":"2022-01-01T00:29:23","modified_gmt":"2021-12-31T21:29:23","slug":"desjudicializacao-e-a-valorizacao-do-consenso","status":"publish","type":"post","link":"http:\/\/sitesadam.com.br\/modelo\/desjudicializacao-e-a-valorizacao-do-consenso\/","title":{"rendered":"Desjudicializa\u00e7\u00e3o e a valoriza\u00e7\u00e3o do consenso"},"content":{"rendered":"<h5 style=\"text-align: justify;\">2021 vai ficando para tr\u00e1s, com a esperan\u00e7a e a expectativa de um 2022 com mais encontros presenciais, abra\u00e7os, conversas, di\u00e1logos e conv\u00edvio. A dist\u00e2ncia e o isolamento impostos pela\u00a0crise sanit\u00e1ria evidenciaram a necessidade que o ser humano tem de pertencer, de conviver, de se relacionar e de estar pr\u00f3ximo.<\/h5>\n<h5 style=\"text-align: justify;\">Como destacado por Steven Pinker: &#8220;<em>Os seres humanos s\u00e3o sociais por natureza e encontram sentido em seus relacionamentos. Os humanistas [&#8230;] lutam por um mundo de cuidados e preocupa\u00e7\u00f5es m\u00fatuos, livre de crueldade e suas consequ\u00eancias, onde as diferen\u00e7as sejam resolvidas de forma cooperativa, sem recorrer \u00e0 viol\u00eancia<\/em>\u00a0[&#8230;]&#8221;\u00a0[1].<\/h5>\n<h5 style=\"text-align: justify;\">Se em 2021 n\u00e3o foi poss\u00edvel estar t\u00e3o perto, a dist\u00e2ncia serviu para que muitos se conscientizassem da import\u00e2ncia do conv\u00edvio saud\u00e1vel. Hoje h\u00e1 um olhar mais atento para a sa\u00fade do ser humano, n\u00e3o s\u00f3 f\u00edsica como mental. Hoje se busca mais o di\u00e1logo do que lit\u00edgio. Fala-se mais em colabora\u00e7\u00e3o do que em adversariedade; mais em renegocia\u00e7\u00e3o do que em a\u00e7\u00e3o judicial.<\/h5>\n<h5 style=\"text-align: justify;\">Consenso, empatia e solidariedade est\u00e3o mais em voga do que diverg\u00eancia, avers\u00e3o, indiferen\u00e7a e ego\u00edsmo.<\/h5>\n<h5 style=\"text-align: justify;\">Sob os prismas social e cultural, 2021 foi, sem d\u00favida, um ano relevante para o necess\u00e1rio projeto de desjudicializa\u00e7\u00e3o e de valoriza\u00e7\u00e3o da busca do consenso e da constru\u00e7\u00e3o conjunta de solu\u00e7\u00f5es.<\/h5>\n<h5 style=\"text-align: justify;\">Como avan\u00e7o, no \u00e2mbito educacional, cite-se a homologa\u00e7\u00e3o pelo ministro da Educa\u00e7\u00e3o de parecer da C\u00e2mara de Educa\u00e7\u00e3o Superior do Conselho Nacional de Educa\u00e7\u00e3o que altera as Diretrizes Curriculares Nacionais do curso de gradua\u00e7\u00e3o em Direito para incluir &#8220;Formas Consensuais de Solu\u00e7\u00e3o de Conflitos&#8221; como conte\u00fado essencial na gradua\u00e7\u00e3o. Com isso, as pr\u00f3ximas gera\u00e7\u00f5es de operadores do Direito j\u00e1 iniciar\u00e3o suas vidas profissionais com um maior conhecimento dos m\u00e9todos alternativos para resolu\u00e7\u00e3o de conflitos, como a negocia\u00e7\u00e3o, concilia\u00e7\u00e3o, media\u00e7\u00e3o, arbitragem e dispute boards, dentre outros.<\/h5>\n<h5 style=\"text-align: justify;\">Outro importante passo foi a realiza\u00e7\u00e3o, em agosto deste ano, da 2\u00aa Jornada de Preven\u00e7\u00e3o e Solu\u00e7\u00e3o Extrajudicial de Lit\u00edgios do Conselho da Justi\u00e7a Federal, que aprova enunciados que sintetizam um entendimento sobre determinada mat\u00e9ria, servindo de orienta\u00e7\u00e3o doutrin\u00e1ria para advogados e magistrados.<\/h5>\n<h5 style=\"text-align: justify;\">A primeira jornada havia sido realizada em 2016, com a aprova\u00e7\u00e3o de 87 enunciados. As tr\u00eas comiss\u00f5es tem\u00e1ticas (arbitragem, media\u00e7\u00e3o e outras formas de solu\u00e7\u00e3o de lit\u00edgios) receberam 227 proposi\u00e7\u00f5es de enunciados.<\/h5>\n<h5 style=\"text-align: justify;\">Neste ano, foram 689 proposi\u00e7\u00f5es, ou seja, o triplo de propostas, o que revela como aumentou o interesse pelo tema. Foram quatro comiss\u00f5es tem\u00e1ticas (arbitragem, media\u00e7\u00e3o, desjudicializa\u00e7\u00e3o e novas formas de solu\u00e7\u00e3o de conflitos e novas tecnologias) e, ao final, 143 enunciados aprovados.<\/h5>\n<h5 style=\"text-align: justify;\">Em 2021, iniciativas do Conselho Nacional de Justi\u00e7a como o Pr\u00eamio Conciliar \u00e9 legal e a Semana da Concilia\u00e7\u00e3o continuaram a todo vapor.<\/h5>\n<h5 style=\"text-align: justify;\">Criado em 2010, o Pr\u00eamio Conciliar \u00e9 legal tem como objetivo identificar, disseminar e estimular a realiza\u00e7\u00e3o de a\u00e7\u00f5es de moderniza\u00e7\u00e3o, colaborando com a pacifica\u00e7\u00e3o entre as partes. O CNJ d\u00e1 visibilidade \u00e0s pr\u00e1ticas de sucesso, incentivando a mobiliza\u00e7\u00e3o em favor da concilia\u00e7\u00e3o e da media\u00e7\u00e3o e apresentando a Justi\u00e7a como um sistema sens\u00edvel, pacificador e eficiente. As inscri\u00e7\u00f5es ocorreram at\u00e9 setembro de 2021 e no in\u00edcio do ano que vem ser\u00e3o premiadas as melhores pr\u00e1ticas em diversas categorias.<\/h5>\n<h5 style=\"text-align: justify;\">J\u00e1 a Semana da Concilia\u00e7\u00e3o, que integra o calend\u00e1rio do Poder Judici\u00e1rio brasileiro desde 2006, se caracteriza pela realiza\u00e7\u00e3o de um esfor\u00e7o concentrado voltado para a sedimenta\u00e7\u00e3o da Pol\u00edtica Judici\u00e1ria Nacional de Tratamento Adequado dos Conflitos de Interesses, institu\u00edda pela conhecida Resolu\u00e7\u00e3o CNJ 125\/2010. A edi\u00e7\u00e3o 2021 adotou o conceito &#8220;Concilia\u00e7\u00e3o: mais tempo para voc\u00ea&#8221; e teve foco nos processos em fase de execu\u00e7\u00e3o, j\u00e1 que em 2020 foram contabilizadas 10,8 milh\u00f5es de a\u00e7\u00f5es em que a parte vencedora n\u00e3o teve o direito concretizado.<\/h5>\n<h5 style=\"text-align: justify;\">O Poder Legislativo tamb\u00e9m fez a diferen\u00e7a em 2021, impulsionando a desjudicializa\u00e7\u00e3o. Tr\u00eas importantes leis que disciplinam contratos e processos de suma relev\u00e2ncia para o Brasil fizeram men\u00e7\u00e3o expressa aos meios alternativos de preven\u00e7\u00e3o e resolu\u00e7\u00e3o de controv\u00e9rsias.<\/h5>\n<h5 style=\"text-align: justify;\">A Lei de Recupera\u00e7\u00e3o Empresarial e Fal\u00eancia (lei 11.101\/05), com a recente reforma trazida pela lei 14.112 que entrou em vigor em janeiro de 2021, determinou ao administrador judicial que estimule a media\u00e7\u00e3o, concilia\u00e7\u00e3o e outros m\u00e9todos alternativos para solucionar conflitos relacionados \u00e0 recupera\u00e7\u00e3o da empresa (artigo 22, j). Al\u00e9m disso, criou uma nova Se\u00e7\u00e3o na lei (artigo 20-A, B, C, e D), para cuidar das media\u00e7\u00f5es antecedentes ou incidentais ao processo de recupera\u00e7\u00e3o judicial, contribuindo para a necess\u00e1ria desjudicializa\u00e7\u00e3o e pacifica\u00e7\u00e3o social.<\/h5>\n<h5 style=\"text-align: justify;\">Na mesma linha, a Lei de Licita\u00e7\u00f5es e Contratos Administrativos (lei 14.133\/21) prev\u00ea o uso da media\u00e7\u00e3o, concilia\u00e7\u00e3o, arbitragem e\u00a0<em>dispute boards<\/em>\u00a0nas contrata\u00e7\u00f5es que regula. O legislador estimula os m\u00e9todos alternativos em novas contrata\u00e7\u00f5es, como tamb\u00e9m nas rela\u00e7\u00f5es e contratos j\u00e1 existentes, mediante a celebra\u00e7\u00e3o de aditivos contratuais.<\/h5>\n<h5 style=\"text-align: justify;\">Em igual sentido, a Lei do Superendividamento do Consumidor (lei 14.181\/21) que alterou o C\u00f3digo de Defesa do Consumidor passando a prever uma audi\u00eancia especial de concilia\u00e7\u00e3o entre o consumidor superendividado e todos os seus credores, incentivando-se a cria\u00e7\u00e3o de centros de concilia\u00e7\u00e3o e media\u00e7\u00e3o destinados especialmente ao consumidor superendividado. A cria\u00e7\u00e3o destes centros, com a capacita\u00e7\u00e3o de mediadores especializados, ser\u00e1 de grande import\u00e2ncia para o sucesso das media\u00e7\u00f5es com os consumidores superendividados.<\/h5>\n<h5 style=\"text-align: justify;\">Cabe ressaltar, ainda, que est\u00e1 em discuss\u00e3o no Congresso Nacional a Medida Provis\u00f3ria 1.040\/2021 que traz regras de moderniza\u00e7\u00e3o do ambiente de neg\u00f3cios no pa\u00eds. Dentre as propostas de emendas ao texto da MP apresentadas pelos parlamentares, est\u00e3o propostas que exigem a comprova\u00e7\u00e3o da pr\u00e9via resist\u00eancia do r\u00e9u em satisfazer a pretens\u00e3o do autor para haver interesse processual no ajuizamento de demandas que cuidem de direitos patrimoniais dispon\u00edveis.<\/h5>\n<h5 style=\"text-align: justify;\">Em outras palavras, os parlamentares iniciaram em 2021 debate sobre a previs\u00e3o de uma nova condi\u00e7\u00e3o para se propor determinadas a\u00e7\u00f5es judiciais: a busca pr\u00e9via do consenso, como, ali\u00e1s, determinava a Constitui\u00e7\u00e3o Pol\u00edtica do Imp\u00e9rio de 1824.<\/h5>\n<h5 style=\"text-align: justify;\">Na \u00e1rea acad\u00eamica, foram muitos eventos, semin\u00e1rios, podcasts, cursos, artigos e disserta\u00e7\u00f5es voltados ao tema, mostrando que a ideia de desjudicializa\u00e7\u00e3o tem ganhado muitos adeptos. O Semin\u00e1rio &#8220;A Advocacia na Constru\u00e7\u00e3o de Solu\u00e7\u00f5es de Ganhos M\u00fatuos&#8221; organizado pela Comiss\u00e3o de Media\u00e7\u00e3o do Conselho Federal a OAB em novembro deste ano teve uma grande audi\u00eancia de advogados que queriam ouvir a experi\u00eancia de outros advogados em procedimentos de media\u00e7\u00e3o.<\/h5>\n<h5 style=\"text-align: justify;\">Os m\u00e9todos de solu\u00e7\u00e3o de controv\u00e9rsias, alternativos \u00e0 jurisdi\u00e7\u00e3o, est\u00e3o em franca valoriza\u00e7\u00e3o e 2021 foi um ano marcante, em termos de propaga\u00e7\u00e3o e divulga\u00e7\u00e3o destas ferramentas. Um ano que fez muitos refletirem sobre como querem viver suas vidas p\u00f3s pandemia e me parece que a busca pelo consenso e pelo encontro do caminho mais inteligente e eficaz para solucionar os problemas est\u00e1 sendo a escolha vencedora. Que venha 2022 com menos lit\u00edgios!<\/h5>\n<h5 style=\"text-align: justify;\">Por Samantha Mendes Longo, s\u00f3cia de Longo Abelha Advogados, mestranda em Direito Empresarial pelo UniCuritiba, Negotiation and Leadership Program na Harvard University, membro do GT de recupera\u00e7\u00e3o empresarial e do Comit\u00ea Gestor de Concilia\u00e7\u00e3o, ambos do Conselho Nacional de Justi\u00e7a, secret\u00e1ria das Comiss\u00f5es de Recupera\u00e7\u00e3o Judicial e de Media\u00e7\u00e3o, ambas do Conselho Federal da OAB, diretora acad\u00eamica do Ibajud, vice-presidente da CamCMR e professora da Emerj.<\/h5>\n<h5 style=\"text-align: justify;\">Fonte: Revista Consultor Jur\u00eddico, 24 de dezembro de 2021, 10h01<\/h5>\n<h5 style=\"text-align: justify;\"><a title=\"AdamNews\" href=\"http:\/\/www.adambrasil.com\/an\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone\" src=\"http:\/\/www.adamsistemas.com\/imagens\/favicon_adam.ico\" alt=\"\" width=\"16\" height=\"16\" \/> AdamNews<\/a> &#8211; Divulga\u00e7\u00e3o exclusiva de not\u00edcias para clientes e parceiros!<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Os m\u00e9todos de solu\u00e7\u00e3o de controv\u00e9rsias, alternativos \u00e0 jurisdi\u00e7\u00e3o, est\u00e3o em franca valoriza\u00e7\u00e3o e 2021 foi um ano marcante, em termos de propaga\u00e7\u00e3o e divulga\u00e7\u00e3o destas ferramentas.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kt_blocks_editor_width":""},"categories":[10,12,18,16,14],"tags":[11,13,19,17,15],"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/10001"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=10001"}],"version-history":[{"count":1,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/10001\/revisions"}],"predecessor-version":[{"id":10002,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/posts\/10001\/revisions\/10002"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=10001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/categories?post=10001"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/tags?post=10001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}