﻿{"id":9545,"date":"2019-03-27T17:10:57","date_gmt":"2019-03-27T17:10:57","guid":{"rendered":"http:\/\/sitesadam.com.br\/modelo\/?page_id=9545"},"modified":"2022-08-09T19:30:12","modified_gmt":"2022-08-09T16:30:12","slug":"lei-de-arbitragem","status":"publish","type":"page","link":"http:\/\/sitesadam.com.br\/modelo\/lei-de-arbitragem\/","title":{"rendered":"Lei de Arbitragem"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>LEI N\u00ba 9.307, DE 23 DE SETEMBRO DE 1996<br \/><\/strong>Disp\u00f5e sobre a <strong>arbitragem<\/strong>.<\/p>\r\n<p style=\"text-align: right;\"><a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_Ato2015-2018\/2015\/Lei\/L13129.htm#art1\" target=\"_blank\" rel=\"noopener noreferrer\">Com altera\u00e7\u00f5es advindas da Lei 13.129\/2015<\/a><\/p>\r\n<p style=\"text-align: center;\">O PRESIDENTE DA REP\u00daBLICA<br \/>Fa\u00e7o saber que o Congresso Nacional decreta e eu sanciono a seguinte:<\/p>\r\n<p style=\"text-align: center;\"><strong>Cap\u00edtulo I<br \/><\/strong><strong>DISPOSI\u00c7\u00d5ES GERAIS <\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 1\u00ba <\/strong>As pessoas capazes de contratar poder\u00e3o valer-se da arbitragem para dirimir lit\u00edgios relativos a direitos patrimoniais dispon\u00edveis.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba\u00a0A administra\u00e7\u00e3o p\u00fablica direta e indireta poder\u00e1 utilizar-se da arbitragem para dirimir conflitos relativos a direitos patrimoniais dispon\u00edveis. <strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><br \/>\u00a7 2\u00ba A autoridade ou o \u00f3rg\u00e3o competente da administra\u00e7\u00e3o p\u00fablica direta para a celebra\u00e7\u00e3o de conven\u00e7\u00e3o de arbitragem \u00e9 a mesma para a realiza\u00e7\u00e3o de acordos ou transa\u00e7\u00f5es.\u00a0<strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 2\u00ba<\/strong>\u00a0A arbitragem poder\u00e1 ser de direito ou de eq\u00fcidade, a crit\u00e9rio das partes.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba Poder\u00e3o as partes escolher livremente, as regras de direito que ser\u00e3o aplicadas na arbitragem, desde que n\u00e3o haja viola\u00e7\u00e3o aos bons costumes e \u00e0 ordem p\u00fablica.<br \/>\u00a7 2\u00ba Poder\u00e3o, tamb\u00e9m, as partes convencionar que a arbitragem se realize com base nos princ\u00edpios gerais de direito, nos usos e costumes e nas regras internacionais de com\u00e9rcio.<br \/>\u00a7 3\u00ba A arbitragem que envolva a administra\u00e7\u00e3o p\u00fablica ser\u00e1 sempre de direito e respeitar\u00e1 o princ\u00edpio da publicidade.\u00a0<strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: center;\"><strong>Cap\u00edtulo II<br \/><\/strong><strong>DA CONVEN\u00c7\u00c3O DE ARBITRAGEM E SEUS EFEITOS<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 3\u00ba<\/strong>\u00a0As partes interessadas podem submeter a solu\u00e7\u00e3o de seus lit\u00edgios ao ju\u00edzo arbitral mediante conven\u00e7\u00e3o de arbitragem, assim entendida a cl\u00e1usula compromiss\u00f3ria e o compromisso arbitral.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 4\u00ba <\/strong>A cl\u00e1usula compromiss\u00f3ria \u00e9 a conven\u00e7\u00e3o atrav\u00e9s da qual as partes em um contrato comprometem-se em submeter \u00e0 arbitragem os lit\u00edgios que possam vir a surgir, relativamente a tal contrato.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba A cl\u00e1usula compromiss\u00f3ria deve ser estipulada por escrito, podendo estar inserta no pr\u00f3prio contrato ou em documento apartado que a ele se refira.<br \/>\u00a7 2\u00ba Nos contratos de ades\u00e3o, a cl\u00e1usula compromiss\u00f3ria s\u00f3 ter\u00e1 efic\u00e1cia se o aderente tomar a iniciativa de instituir a arbitragem ou concordar, expressamente, com a sua institui\u00e7\u00e3o, desde que por escrito em documento anexo ou em negrito, com a assinatura ou visto especialmente para essa cl\u00e1usula.<br \/>\u00a7 3\u00ba\u00a0 (VETADO). <strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<br \/><\/strong>\u00a7 4\u00ba\u00a0 (VETADO). <strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)\u00a0<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 5\u00ba <\/strong>Reportando-se as partes, na cl\u00e1usula compromiss\u00f3ria, \u00e0s regras de algum \u00f3rg\u00e3o arbitral institucional ou entidade especializada, a arbitragem ser\u00e1 institu\u00edda e processada de acordo com tais regras, podendo, igualmente, as partes estabelecer na pr\u00f3pria cl\u00e1usula, ou em outro documento, a forma convencionada para institui\u00e7\u00e3o da arbitragem.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 6\u00ba <\/strong>N\u00e3o havendo acordo pr\u00e9vio sobre a forma de instituir a arbitragem, a parte interessada manifestar\u00e1 \u00e0 outra parte sua inten\u00e7\u00e3o de dar in\u00edcio \u00e0 arbitragem, por via postal ou por outro meio qualquer de comunica\u00e7\u00e3o, mediante comprova\u00e7\u00e3o de recebimento, convocando-a para, em dia, hora e local certos, firmar o compromisso arbitral.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. N\u00e3o comparecendo a parte convocada ou, comparecendo, recusar-se a firmar o compromisso arbitral, poder\u00e1 a outra parte propor a demanda de que trata o art. 7\u00ba desta Lei, perante o \u00f3rg\u00e3o do Poder Judici\u00e1rio a que, originariamente, tocaria o julgamento da causa.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 7\u00ba<\/strong>\u00a0Existindo cl\u00e1usula compromiss\u00f3ria e havendo resist\u00eancia quanto \u00e0 institui\u00e7\u00e3o da arbitragem, poder\u00e1 a parte interessada requerer a cita\u00e7\u00e3o da outra parte para comparecer em ju\u00edzo a fim de lavrar-se o compromisso, designando o juiz audi\u00eancia especial para tal fim.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba\u00a0O autor indicar\u00e1, com precis\u00e3o, o objeto da arbitragem, instruindo o pedido com o documento que contiver a cl\u00e1usula compromiss\u00f3ria.<br \/>\u00a7 2\u00ba Comparecendo as partes \u00e0 audi\u00eancia, o juiz tentar\u00e1, previamente, a concilia\u00e7\u00e3o acerca do lit\u00edgio. N\u00e3o obtendo sucesso, tentar\u00e1 o juiz conduzir as partes \u00e0 celebra\u00e7\u00e3o, de comum acordo, do compromisso arbitral.<br \/>\u00a7 3\u00ba N\u00e3o concordando as partes sobre os termos do compromisso, decidir\u00e1 o juiz, ap\u00f3s ouvir o r\u00e9u, sobre seu conte\u00fado, na pr\u00f3pria audi\u00eancia ou no prazo de dez dias, respeitadas as disposi\u00e7\u00f5es da cl\u00e1usula compromiss\u00f3ria e atendendo ao disposto nos artigos 10 e 21, \u00a7 2\u00ba, desta Lei.<br \/>\u00a7 4\u00ba Se a cl\u00e1usula compromiss\u00f3ria nada dispuser sobre a nomea\u00e7\u00e3o de \u00e1rbitros, caber\u00e1 ao juiz, ouvidas as partes estatuir a respeito, podendo nomear arbitro \u00fanico para a solu\u00e7\u00e3o do lit\u00edgio.<br \/>\u00a7 5\u00ba A aus\u00eancia do autor, sem justo motivo, \u00e0 audi\u00eancia designada para a lavratura do compromisso arbitral, importar\u00e1 a extin\u00e7\u00e3o do processo sem julgamento de m\u00e9rito.<br \/>\u00a7 6\u00ba N\u00e3o comparecendo o r\u00e9u \u00e0 audi\u00eancia, caber\u00e1 ao juiz, ouvido o autor, estatuir a respeito do conte\u00fado do compromisso, nomeando \u00e1rbitro \u00fanico.<br \/>\u00a7 7\u00ba A senten\u00e7a que julgar procedente o pedido valer\u00e1 como compromisso arbitral.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 8\u00ba <\/strong>A cl\u00e1usula compromiss\u00f3ria \u00e9 aut\u00f4noma em rela\u00e7\u00e3o ao contrato em que estiver inserta, de tal sorte que a nulidade deste n\u00e3o implica, necessariamente, a nulidade da cl\u00e1usula compromiss\u00f3ria.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. Caber\u00e1 ao \u00e1rbitro decidir de of\u00edcio, ou por provoca\u00e7\u00e3o das partes, as quest\u00f5es acerca da exist\u00eancia, validade e efic\u00e1cia da conven\u00e7\u00e3o de arbitragem e do contrato que contenha a cl\u00e1usula compromiss\u00f3ria.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 9\u00ba<\/strong>\u00a0O compromisso arbitral \u00e9 a conven\u00e7\u00e3o atrav\u00e9s da qual as partes submetem um lit\u00edgio \u00e0 arbitragem de uma ou mais pessoas, podendo ser judicial ou extrajudicial.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba O compromisso arbitral judicial celebrar-se-\u00e1 por termo nos autos, perante o ju\u00edzo ou tribunal, onde tem curso a demanda.<br \/>\u00a7 2\u00ba O compromisso arbitral extrajudicial ser\u00e1 celebrado por escrito particular, assinado por duas testemunhas, ou por instrumento p\u00fablico.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 10\u00ba <\/strong>Constar\u00e1, obrigatoriamente, do compromisso arbitral:<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">I &#8211; o nome, profiss\u00e3o, estado civil e domic\u00edlio das partes;<br \/>II &#8211; o nome, profiss\u00e3o e domic\u00edlio do \u00e1rbitro, ou dos \u00e1rbitros, ou se for o caso a identifica\u00e7\u00e3o da entidade \u00e0 qual as partes delegaram a indica\u00e7\u00e3o de \u00e1rbitros:<br \/>III &#8211; a mat\u00e9ria que ser\u00e1 objeto da arbitragem: e<br \/>IV &#8211; o lugar em que ser\u00e1 proferida a senten\u00e7a arbitral.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 11.<\/strong>\u00a0Poder\u00e1, ainda, o compromisso arbitral conter:<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">I &#8211; local, ou locais, onde se desenvolver\u00e1 a arbitragem:<br \/>II &#8211; autoriza\u00e7\u00e3o para que o \u00e1rbitro ou os \u00e1rbitros julguem por eq\u00fcidade, se assim for convencionado pelas partes:<br \/>III &#8211; o prazo para apresenta\u00e7\u00e3o da senten\u00e7a arbitral:<br \/>IV &#8211; a indica\u00e7\u00e3o da lei nacional ou das regras corporativas aplic\u00e1veis \u00e0 arbitragem, quando assim convencionarem as partes;<br \/>V &#8211; a declara\u00e7\u00e3o da responsabilidade pelo pagamento dos honor\u00e1rios e das despesas com a arbitragem; e<br \/>VI &#8211; a fixa\u00e7\u00e3o dos honor\u00e1rios do \u00e1rbitro, ou dos \u00e1rbitros.<\/p>\r\n<p style=\"text-align: justify; padding-left: 120px;\">Par\u00e1grafo \u00fanico. Fixando as partes os honor\u00e1rios dos \u00e1rbitros, no compromisso arbitral, este constituir\u00e1 t\u00edtulo executivo extrajudicial; n\u00e3o havendo tal estipula\u00e7\u00e3o, o \u00e1rbitro requerer\u00e1 ao \u00f3rg\u00e3o do Poder Judici\u00e1rio que seria competente para julgar, originariamente, a causa que os fixe por senten\u00e7a.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 12.<\/strong>\u00a0Extingue-se o compromisso arbitral:<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">I &#8211; escusando-se qualquer dos \u00e1rbitros, antes de aceitar a nomea\u00e7\u00e3o, desde que as partes tenham declarado, expressamente, n\u00e3o aceitar substituto; e<br \/>II &#8211; falecendo ou ficando impossibilitado de dar seu voto algum dos \u00e1rbitros, desde que as partes declarem, expressamente, n\u00e3o aceitar substituto; e<br \/>III &#8211; tendo expirado o prazo a que se refere o art. 11, inciso III, desde que a parte interessada tenha notificado o \u00e1rbitro, ou o presidente do tribunal arbitral, concedendo-lhe o prazo de dez dias para o prola\u00e7\u00e3o e apresenta\u00e7\u00e3o da senten\u00e7a arbitral.<\/p>\r\n<p style=\"padding-left: 60px; text-align: center;\"><strong>Cap\u00edtulo III<br \/><\/strong><strong>DOS \u00c1RBITROS <\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 13.<\/strong>\u00a0Pode ser \u00e1rbitro qualquer pessoa capaz e que tenha a confian\u00e7a das partes.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba\u00a0As partes nomear\u00e3o um ou mais \u00e1rbitros, sempre em n\u00famero \u00edmpar, podendo nomear, tamb\u00e9m, os respectivos suplentes.<br \/>\u00a7 2\u00b0\u00a0Quando as partes nomearem \u00e1rbitros em n\u00famero par, estes est\u00e3o autorizados, desde logo, a nomear mais um \u00e1rbitro. N\u00e3o havendo acordo, requerer\u00e3o as partes ao \u00f3rg\u00e3o do Poder Judici\u00e1rio a que tocaria, originariamente, o julgamento da causa, a nomea\u00e7\u00e3o do \u00e1rbitro, aplic\u00e1vel, no que couber, o procedimento previsto no art. 7\u00ba desta Lei.<br \/>\u00a7 3\u00ba\u00a0As partes poder\u00e3o, de comum acordo, estabelecer o processo de escolha dos \u00e1rbitros, ou adotar as regras de um \u00f3rg\u00e3o arbitral institucional ou entidade especializada.<br \/>\u00a7 4\u00ba As partes, de comum acordo, poder\u00e3o afastar a aplica\u00e7\u00e3o de dispositivo do regulamento do \u00f3rg\u00e3o arbitral institucional ou entidade especializada que limite a escolha do \u00e1rbitro \u00fanico, co\u00e1rbitro ou presidente do tribunal \u00e0 respectiva lista de \u00e1rbitros, autorizado o controle da escolha pelos \u00f3rg\u00e3os competentes da institui\u00e7\u00e3o, sendo que, nos casos de impasse e arbitragem multiparte, dever\u00e1 ser observado o que dispuser o regulamento aplic\u00e1vel.\u00a0<strong>(Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<br \/><\/strong>\u00a7 5\u00ba O \u00e1rbitro ou o presidente do tribunal designar\u00e1, se julgar conveniente, um secret\u00e1rio, que poder\u00e1 ser um \u00e1rbitro.<br \/>\u00a7 6\u00ba No desempenho de sua fun\u00e7\u00e3o, o \u00e1rbitro dever\u00e1 proceder com imparcialidade, independ\u00eancia, compet\u00eancia, dilig\u00eancia e discri\u00e7\u00e3o.<br \/>\u00a7 7\u00ba Poder\u00e1 o \u00e1rbitro ou tribunal arbitral determinar \u00e0s partes o adiantamento de verbas para despesas e dilig\u00eancias que julgar necess\u00e1rias.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 14.\u00a0<\/strong>Est\u00e3o impedidos de funcionar como \u00e1rbitros as pessoas que tenham, como as partes ou com o lit\u00edgio que lhes for submetido, algumas das rela\u00e7\u00f5es que caracterizam os casos de impedimento ou suspei\u00e7\u00e3o de juizes, aplicando-se-lhes, no couber, os mesmos deveres e responsabilidades, conforme previsto no C\u00f3digo de Processo Civil.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba &#8211; As pessoas indicadas para funcionar como \u00e1rbitro t\u00eam o dever de revelar, antes da aceita\u00e7\u00e3o da fun\u00e7\u00e3o, qualquer fato que denote d\u00favida justificada quanto \u00e0 sua imparcialidade e independ\u00eancia.<br \/>\u00a7 2\u00ba &#8211; O \u00e1rbitro somente poder\u00e1 ser recusado por motivo ocorrido ap\u00f3s sua nomea\u00e7\u00e3o. Poder\u00e1, entretanto, ser recusado por motivo anterior \u00e0 sua nomea\u00e7\u00e3o, quando:<\/p>\r\n<p style=\"text-align: justify; padding-left: 120px;\">a) n\u00e3o for nomeado, diretamente, pela parte; ou<br \/>b) o motivo para a recusa do \u00e1rbitro for conhecido posteriormente \u00e0 sua nomea\u00e7\u00e3o.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 15.\u00a0<\/strong>A parte interessada em arg\u00fcir a recusa do \u00e1rbitro apresentar\u00e1, nos termos do art. 20, a respectiva exce\u00e7\u00e3o, diretamente ao \u00e1rbitro ou ao presidente do tribunal arbitral, deduzindo suas raz\u00f5es e apresentando as provas pertinentes.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. Acolhida a exce\u00e7\u00e3o, ser\u00e1 afastado o \u00e1rbitro suspeito ou impedido, que ser\u00e1 substitu\u00eddo, na forma do art. 16 desta Lei.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 16.\u00a0<\/strong>Se o \u00e1rbitro escusar-se antes da aceita\u00e7\u00e3o da nomea\u00e7\u00e3o, ou, ap\u00f3s a aceita\u00e7\u00e3o, vier a falecer, tornar-se impossibilitado para o exerc\u00edcio da fun\u00e7\u00e3o, ou for recusado, assumir\u00e1 seu lugar o substituto indicado no compromisso, se houver.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba N\u00e3o havendo substituto indicado para o \u00e1rbitro, aplicar-se-\u00e3o as regras do \u00f3rg\u00e3o arbitral institucional ou entidade especializada, se as partes as tiverem invocado na conven\u00e7\u00e3o de arbitragem.<br \/>\u00a7 2\u00ba Nada dispondo a conven\u00e7\u00e3o de arbitragem e n\u00e3o chegando as partes a um acordo sobre a nomea\u00e7\u00e3o do \u00e1rbitro a ser substitu\u00eddo, proceder\u00e1 a parte interessada na forma prevista no art. 7\u00ba desta Lei, a menos que as partes tenham declarado, expressamente, na conven\u00e7\u00e3o de arbitragem, n\u00e3o aceitar substituto.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 17.\u00a0<\/strong>Os \u00e1rbitros, quando no exerc\u00edcio de suas fun\u00e7\u00f5es ou em raz\u00e3o delas, ficam equiparados aos funcion\u00e1rios p\u00fablicos, para os efeitos da legisla\u00e7\u00e3o penal.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 18<\/strong>\u00a0O \u00e1rbitro \u00e9 juiz de fato e de direito, e a senten\u00e7a que proferir n\u00e3o fica sujeita a recurso ou homologa\u00e7\u00e3o pelo Poder Judici\u00e1rio.<\/p>\r\n<p style=\"text-align: center;\"><strong>Cap\u00edtulo IV<br \/><\/strong><strong>DO PROCEDIMENTO ARBITRAL<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 19.\u00a0<\/strong>Considera-se institu\u00edda a arbitragem quando aceita a nomea\u00e7\u00e3o pelo \u00e1rbitro, se for \u00fanico, ou por todos, se forem v\u00e1rios.<\/p>\r\n<p style=\"padding-left: 60px; text-align: justify;\">\u00a7 1\u00ba Institu\u00edda a arbitragem e entendendo o \u00e1rbitro ou o tribunal arbitral que h\u00e1 necessidade de explicitar quest\u00e3o disposta na conven\u00e7\u00e3o de arbitragem, ser\u00e1 elaborado, juntamente com as partes, adendo firmado por todos, que passar\u00e1 a fazer parte integrante da conven\u00e7\u00e3o de arbitragem.\u00a0<strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"padding-left: 60px; text-align: justify;\">\u00a7 2\u00ba A institui\u00e7\u00e3o da arbitragem interrompe a prescri\u00e7\u00e3o, retroagindo \u00e0 data do requerimento de sua instaura\u00e7\u00e3o, ainda que extinta a arbitragem por aus\u00eancia de jurisdi\u00e7\u00e3o.<strong>\u00a0(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 20.\u00a0<\/strong>A parte que pretender arg\u00fcir quest\u00f5es relativas \u00e0 compet\u00eancia, suspei\u00e7\u00e3o ou impedimento do \u00e1rbitro ou dos \u00e1rbitros, bem como nulidade, invalidade ou inefic\u00e1cia da conven\u00e7\u00e3o de arbitragem, dever\u00e1 faz\u00ea-lo na primeira oportunidade que tiver de se manifestar, ap\u00f3s a institui\u00e7\u00e3o da arbitragem.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba Acolhida a arg\u00fci\u00e7\u00e3o de suspei\u00e7\u00e3o ou impedimento, ser\u00e1 o \u00e1rbitro substitu\u00eddo nos termos do art. 16 desta Lei, reconhecida a incompet\u00eancia do \u00e1rbitro ou do tribunal arbitral, bem como a nulidade, invalidade ou inefic\u00e1cia da conven\u00e7\u00e3o de arbitragem, ser\u00e3o as partes remetidas ao \u00f3rg\u00e3o do Poder Judici\u00e1rio competente para julgar a causa.<br \/>\u00a7 2\u00ba\u00a0N\u00e3o sendo acolhida a arg\u00fci\u00e7\u00e3o, ter\u00e1 normal prosseguimento a arbitragem, sem preju\u00edzo de vir a ser examinada a decis\u00e3o pelo \u00f3rg\u00e3o do Poder Judici\u00e1rio competente, quando da eventual propositura da demanda de que trata o art. 33 desta Lei.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 21.\u00a0<\/strong>A arbitragem obedecer\u00e1 ao procedimento estabelecido pelas partes na conven\u00e7\u00e3o de arbitragem, que poder\u00e1 reportar-se \u00e0s regras de um \u00f3rg\u00e3o arbitral institucional ou entidade especializada, facultando-se, ainda, \u00e0s partes delegar ao pr\u00f3prio \u00e1rbitro, ou ao tribunal arbitral, regular o procedimento.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba N\u00e3o havendo estipula\u00e7\u00e3o acerca do procedimento, caber\u00e1 ao \u00e1rbitro ou ao tribunal arbitral disciplin\u00e1-lo.<br \/>\u00a7 2\u00ba Ser\u00e3o, sempre, respeitados no procedimento arbitral os princ\u00edpios do contradit\u00f3rio, da igualdade das partes, da imparcialidade do \u00e1rbitro e de seu livre convencimento.<br \/>\u00a7 3\u00ba\u00a0As partes poder\u00e3o postular por interm\u00e9dio de advogado, respeitada, sempre, a faculdade de designar quem as represente ou assista no procedimento arbitral.<br \/>\u00a7 4\u00ba Competir\u00e1 ao \u00e1rbitro ou ao tribunal arbitral, no in\u00edcio do procedimento, tentar a concilia\u00e7\u00e3o das partes, aplicando-se, no que couber, o art. 28 desta Lei.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 22.\u00a0<\/strong>Poder\u00e1 o \u00e1rbitro ou o tribunal arbitral tomar o depoimento das partes, ouvir testemunhas e determinar a realiza\u00e7\u00e3o de per\u00edcias ou provas que julgar necess\u00e1rias, mediante requerimento das partes ou de of\u00edcio.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba O depoimento das partes e das testemunhas ser\u00e1 tomado em local, dia e hora previamente comunicados, por escrito, e reduzido a termo, assinado pelo depoente, ou a seu rogo, e pelos \u00e1rbitros.<br \/>\u00a7 2\u00ba Em caso de desentendimento, sem justa causa, da convoca\u00e7\u00e3o para prestar depoimento pessoal, o \u00e1rbitro ou o tribunal arbitral levar\u00e1 em considera\u00e7\u00e3o o comportamento da parte faltosa, ao proferir sua senten\u00e7a; se a aus\u00eancia for de testemunha, nas mesmas circunst\u00e2ncias, poder\u00e1 o \u00e1rbitro ou o presidente do tribunal arbitral requerer \u00e0 autoridade judici\u00e1ria que conduza a testemunha renitente, comprovando a exist\u00eancia da conven\u00e7\u00e3o de arbitragem.<br \/>\u00a7 3\u00ba A revelia da parte n\u00e3o impedir\u00e1 que seja proferida a senten\u00e7a arbitral.<br \/>\u00a7 4\u00ba\u00a0<strong>(Revogado pela Lei n\u00ba 13.129, de 2015)<\/strong><br \/>\u00a7 5\u00ba Se, durante o procedimento arbitral, um \u00e1rbitro vier a ser substitu\u00eddo fica a crit\u00e9rio do substituto repetir as provas j\u00e1 produzidas.<\/p>\r\n<p style=\"text-align: center;\"><strong>CAP\u00cdTULO IV-A<br \/><\/strong><strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<br \/><\/strong><strong>DAS TUTELAS CAUTELARES E DE URG\u00caNCIA<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 22-A.<\/strong> Antes de institu\u00edda a arbitragem, as partes poder\u00e3o recorrer ao Poder Judici\u00e1rio para a concess\u00e3o de medida cautelar ou de urg\u00eancia.\u00a0<strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. Cessa a efic\u00e1cia da medida cautelar ou de urg\u00eancia se a parte interessada n\u00e3o requerer a institui\u00e7\u00e3o da arbitragem no prazo de 30 (trinta) dias, contado da data de efetiva\u00e7\u00e3o da respectiva decis\u00e3o.<strong>\u00a0(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 22-B.<\/strong> Institu\u00edda a arbitragem, caber\u00e1 aos \u00e1rbitros manter, modificar ou revogar a medida cautelar ou de urg\u00eancia concedida pelo Poder Judici\u00e1rio.\u00a0<strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. Estando j\u00e1 institu\u00edda a arbitragem, a medida cautelar ou de urg\u00eancia ser\u00e1 requerida diretamente aos \u00e1rbitros.\u00a0<strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: center;\"><strong>CAP\u00cdTULO IV-B<br \/><\/strong><strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<br \/><\/strong><strong>DA CARTA ARBITRAL<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 22-C.<\/strong> O \u00e1rbitro ou o tribunal arbitral poder\u00e1 expedir carta arbitral para que o \u00f3rg\u00e3o jurisdicional nacional pratique ou determine o cumprimento, na \u00e1rea de sua compet\u00eancia territorial, de ato solicitado pelo \u00e1rbitro. <strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. No cumprimento da carta arbitral ser\u00e1 observado o segredo de justi\u00e7a, desde que comprovada a confidencialidade estipulada na arbitragem.\u00a0 <strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: center;\"><strong>Cap\u00edtulo V<br \/><\/strong><strong>DA SENTEN\u00c7A ARBITRAL <\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 23.\u00a0<\/strong>A senten\u00e7a arbitral ser\u00e1 proferida no prazo estipulado pelas partes. Nada tendo sido convencionado, o prazo para a apresenta\u00e7\u00e3o da senten\u00e7a \u00e9 de seis meses, contado da institui\u00e7\u00e3o da arbitragem ou da substitui\u00e7\u00e3o do \u00e1rbitro.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba Os \u00e1rbitros poder\u00e3o proferir senten\u00e7as parciais.\u00a0<strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><br \/>\u00a7 2\u00ba As partes e os \u00e1rbitros, de comum acordo, poder\u00e3o prorrogar o prazo para proferir a senten\u00e7a final.\u00a0 <strong>(Inclu\u00eddo pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 24.\u00a0<\/strong>A decis\u00e3o do \u00e1rbitro ou dos \u00e1rbitros ser\u00e1 expressa em documento escrito.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba quando forem v\u00e1rios os \u00e1rbitros, a decis\u00e3o ser\u00e1 tomada por maioria. Se n\u00e3o houver acordo majorit\u00e1rio, prevalecer\u00e1 o voto do presidente do tribunal arbitral.<br \/>\u00a7 2\u00ba O \u00e1rbitro que divergir da maioria poder\u00e1, querendo, declarar seu voto em separado.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 25. \u00a0(Revogado pela Lei n\u00ba 13.129, de 2015) <\/strong><\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. <strong>(Revogado pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 26.\u00a0<\/strong>S\u00e3o requisitos obrigat\u00f3rios da senten\u00e7a arbitral:<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">I &#8211; o relat\u00f3rio, que conter\u00e1 os nomes das partes e um resumo do lit\u00edgio;<br \/>II &#8211; os fundamentos da decis\u00e3o, onde ser\u00e3o analisadas as quest\u00f5es de fato e de direito, mencionando-se, expressamente, se os \u00e1rbitros julgaram por eq\u00fcidade;<br \/>III &#8211; o dispositivo, em que os \u00e1rbitros resolver\u00e3o as quest\u00f5es que lhes forem submetidas e estabelecer\u00e3o o prazo para o cumprimento da decis\u00e3o, se for o caso; e<br \/>IV &#8211; a data e o lugar em que foi proferida.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. A senten\u00e7a arbitral ser\u00e1 assinada pelo \u00e1rbitro ou por todos os \u00e1rbitros. Caber\u00e1 ao presidente do tribunal arbitral, na hip\u00f3tese de um ou alguns dos \u00e1rbitros n\u00e3o poder ou n\u00e3o querer assinar a senten\u00e7a, certificar tal fato.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 27.\u00a0<\/strong>A senten\u00e7a arbitral decidir\u00e1 sobre a responsabilidade das partes acerca das custas e despesas com a arbitragem, bem como sobre verba decorrente de litig\u00e2ncia de m\u00e1-f\u00e9, se for o caso, respeitadas as disposi\u00e7\u00f5es da conven\u00e7\u00e3o da arbitragem, se houver.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 28.\u00a0<\/strong>Se, no decurso da arbitragem, as partes chegarem a acordo quanto ao lit\u00edgio, o \u00e1rbitro ou o tribunal arbitral poder\u00e1, a pedido das partes, declarar tal fato mediante senten\u00e7a arbitral, que conter\u00e1 os requisitos da art. 26 desta Lei.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 29.\u00a0<\/strong>Proferida a senten\u00e7a arbitral, d\u00e1-se por finda a arbitragem, devendo o \u00e1rbitro, ou o presidente do tribunal arbitral, enviar c\u00f3pias da decis\u00e3o \u00e0s partes, por via postal ou por outro meio qualquer de comunica\u00e7\u00e3o, mediante comprova\u00e7\u00e3o de recebimento, ou ainda, entregando-a diretamente \u00e0s partes mediante recibo.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 30.<\/strong> No prazo de 5 (cinco) dias, a contar do recebimento da notifica\u00e7\u00e3o ou da ci\u00eancia pessoal da senten\u00e7a arbitral, salvo se outro prazo for acordado entre as partes, a parte interessada, mediante comunica\u00e7\u00e3o \u00e0 outra parte, poder\u00e1 solicitar ao \u00e1rbitro ou ao tribunal arbitral que:\u00a0<strong> (Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">I &#8211; corrija qualquer erro material da senten\u00e7a arbitral;<br \/>II &#8211; esclare\u00e7a alguma obscuridade, d\u00favida ou contradi\u00e7\u00e3o da senten\u00e7a arbitral, ou se pronuncie sobre ponto omitido a respeito do qual devia manifestar-se a decis\u00e3o.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. O \u00e1rbitro ou o tribunal arbitral decidir\u00e1 no prazo de 10 (dez) dias ou em prazo acordado com as partes, aditar\u00e1 a senten\u00e7a arbitral e notificar\u00e1 as partes na forma do art. 29. <strong>(Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 31.<\/strong>\u00a0A senten\u00e7a arbitral produz, entre as partes e seus sucessores, os mesmos efeitos da senten\u00e7a proferida pelos \u00f3rg\u00e3os do Poder Judici\u00e1rio e, sendo condenat\u00f3ria, constitui t\u00edtulo executivo.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 32.\u00a0<\/strong>\u00a0\u00c9 nula a senten\u00e7a arbitral se:<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">I &#8211; for nula a conven\u00e7\u00e3o de arbitragem;\u00a0 <strong>(Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<\/strong><br \/>II &#8211; emanou de quem n\u00e3o podia ser \u00e1rbitro;<br \/>III &#8211; n\u00e3o contiver os requisitos do art. 26 desta Lei;<br \/>IV &#8211; for proferida fora dos limites da conven\u00e7\u00e3o de arbitragem;<br \/>V &#8211; <strong>(Revogado pela Lei n\u00ba 13.129, de 2015)<\/strong>;<br \/>VI &#8211; comprovado que foi proferida por prevarica\u00e7\u00e3o, concuss\u00e3o ou corrup\u00e7\u00e3o passiva;<br \/>VII &#8211; proferida fora do prazo, respeitado o disposto no art. 12, inciso III, desta Lei; e<br \/>VIII &#8211; forem desrespeitados os princ\u00edpios de que trata o art. 21, \u00a7 2\u00ba, desta Lei.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 33.<\/strong>\u00a0A parte interessada poder\u00e1 pleitear ao \u00f3rg\u00e3o do Poder Judici\u00e1rio competente a declara\u00e7\u00e3o de nulidade da senten\u00e7a arbitral, nos casos previstos nesta Lei.\u00a0<strong>(Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">\u00a7 1\u00ba A demanda para a declara\u00e7\u00e3o de nulidade da senten\u00e7a arbitral, parcial ou final, seguir\u00e1 as regras do procedimento comum, previstas na Lei no 5.869, de 11 de janeiro de 1973 (C\u00f3digo de Processo Civil), e dever\u00e1 ser proposta no prazo de at\u00e9 90 (noventa) dias ap\u00f3s o recebimento da notifica\u00e7\u00e3o da respectiva senten\u00e7a, parcial ou final, ou da decis\u00e3o do pedido de esclarecimentos.\u00a0 <strong>(Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<\/strong><br \/>\u00a7 2\u00ba\u00a0A senten\u00e7a que julgar procedente o pedido declarar\u00e1 a nulidade da senten\u00e7a arbitral, nos casos do art. 32, e determinar\u00e1, se for o caso, que o \u00e1rbitro ou o tribunal profira nova senten\u00e7a arbitral.\u00a0<strong>(Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<br \/><\/strong>\u00a7 3\u00ba A declara\u00e7\u00e3o de nulidade da senten\u00e7a arbitral tamb\u00e9m poder\u00e1 ser arguida mediante impugna\u00e7\u00e3o, conforme o art. 475-L e seguintes da Lei no 5.869, de 11 de janeiro de 1973 (C\u00f3digo de Processo Civil), se houver execu\u00e7\u00e3o judicial.\u00a0 <strong>(Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<br \/><\/strong>\u00a7 4\u00ba A parte interessada poder\u00e1 ingressar em ju\u00edzo para requerer a prola\u00e7\u00e3o de senten\u00e7a arbitral complementar, se o \u00e1rbitro n\u00e3o decidir todos os pedidos submetidos \u00e0 arbitragem.\u00a0<strong>(Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: center;\"><strong>Cap\u00edtulo VI<br \/><\/strong><strong>DO RECONHECIMENTO E EXECU\u00c7\u00c3O DE SENTEN\u00c7AS ARBITRAIS ESTRANGEIRAS<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 34.<\/strong>\u00a0A senten\u00e7a arbitral estrangeira ser\u00e1 reconhecida ou executada no Brasil de conformidade com os tratados internacionais com efic\u00e1cia no ordenamento interno e, na sua aus\u00eancia, estritamente de acordo com os termos desta Lei.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. Considera-se senten\u00e7a arbitral estrangeira a que tenha sido proferida fora do territ\u00f3rio nacional.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 35.<\/strong> Para ser reconhecida ou executada no Brasil, a senten\u00e7a arbitral estrangeira est\u00e1 sujeita, unicamente, \u00e0 homologa\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a.\u00a0<strong>(Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 36.<\/strong>\u00a0Aplica-se \u00e0 homologa\u00e7\u00e3o para reconhecimento ou execu\u00e7\u00e3o de senten\u00e7a arbitral estrangeira, no que couber, o disposto nos arts.\u00a0483 e 484 do C\u00f3digo de Processo Civil.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 37.\u00a0<\/strong>A homologa\u00e7\u00e3o de senten\u00e7a arbitral estrangeira ser\u00e1 requerida pela parte interessada, devendo a peti\u00e7\u00e3o inicial conter as indica\u00e7\u00f5es da lei processual, conforme o art. 282 do C\u00f3digo de Processo Civil, e ser instru\u00edda, necessariamente, com:<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">I &#8211; o original da senten\u00e7a arbitral ou uma c\u00f3pia devidamente certificada, autenticada pelo consulado brasileiro e acompanhada de tradu\u00e7\u00e3o oficial;<br \/>II &#8211; o original da conven\u00e7\u00e3o de arbitragem ou c\u00f3pia devidamente certificada, acompanha de tradu\u00e7\u00e3o oficial.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 38.<\/strong>\u00a0Somente poder\u00e1 ser negada a homologa\u00e7\u00e3o para reconhecimento ou execu\u00e7\u00e3o de senten\u00e7a arbitral estrangeira, quando o r\u00e9u demonstrar que:<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">I &#8211; as partes na conven\u00e7\u00e3o de arbitragem eram incapazes;<br \/>I &#8211; a conven\u00e7\u00e3o de arbitragem n\u00e3o era v\u00e1lida segundo a lei \u00e0 qual as partes a submeteram, ou na falta de indica\u00e7\u00e3o, em virtude da lei dos pa\u00edses onde a senten\u00e7a arbitral foi proferida;<br \/>III &#8211; n\u00e3o foi notificado da designa\u00e7\u00e3o do \u00e1rbitro ou do procedimento de arbitragem, ou tenha sido violado o princ\u00edpio do contradit\u00f3rio, impossibilitando a ampla defesa;<br \/>IV &#8211; a senten\u00e7a arbitral foi proferida fora dos limites da conven\u00e7\u00e3o de arbitragem, e n\u00e3o foi poss\u00edvel separar a parte excedente daquela submetida \u00e0 arbitragem;<br \/>V &#8211; a institui\u00e7\u00e3o da arbitragem n\u00e3o est\u00e1 de acordo com o compromisso arbitral ou cl\u00e1usula compromiss\u00f3ria;<br \/>VI &#8211; a senten\u00e7a arbitral n\u00e3o se tenha, ainda, tornado obrigat\u00f3ria para as partes, tenha sido anulada, ou ainda, tenha sido suspensa por \u00f3rg\u00e3o judicial do pa\u00eds onde a senten\u00e7a arbitral for prolatada.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 39.<\/strong> A homologa\u00e7\u00e3o para o reconhecimento ou a execu\u00e7\u00e3o da senten\u00e7a arbitral estrangeira tamb\u00e9m ser\u00e1 denegada se o Superior Tribunal de Justi\u00e7a constatar que:\u00a0 <strong>(Reda\u00e7\u00e3o dada pela Lei n\u00ba 13.129, de 2015)<\/strong><\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">I &#8211; segundo a lei brasileira, o objeto do lit\u00edgio n\u00e3o \u00e9 suscet\u00edvel de ser resolvido por arbitragem;<br \/>II &#8211; a decis\u00e3o ofende a ordem p\u00fablica nacional.<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">Par\u00e1grafo \u00fanico. N\u00e3o ser\u00e1 considerada ofensa \u00e0 ordem p\u00fablica nacional a efetiva\u00e7\u00e3o da cita\u00e7\u00e3o da parte residente ou domiciliada no Brasil, nos moldes da conven\u00e7\u00e3o de arbitragem ou da lei processual do pa\u00eds onde se realizou a arbitragem, admitindo-se, inclusive, a cita\u00e7\u00e3o postal com prova inequ\u00edvoca de recebimento, desde que assegure \u00e0 parte brasileira tempo h\u00e1bil para o direito de defesa.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 40.<\/strong>\u00a0A denega\u00e7\u00e3o da homologa\u00e7\u00e3o para reconhecimento ou execu\u00e7\u00e3o de senten\u00e7a arbitral estrangeira por v\u00edcios formais, n\u00e3o obsta que a parte interessada renove o pedido, uma vez sanados os v\u00edcios apresentados.<\/p>\r\n<p style=\"text-align: center;\"><strong>Cap\u00edtulo VII<br \/><\/strong><strong>DISPOSI\u00c7\u00d5ES FINAIS<\/strong><\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 41.<\/strong>\u00a0Os arts. 267, inciso VII, 301, inciso IX e 584, inciso III, do C\u00f3digo de Processo Civil passam a ter a seguinte reda\u00e7\u00e3o:<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">&#8220;Art. 267&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..<\/p>\r\n<p style=\"text-align: justify; padding-left: 120px;\">VII &#8211; pela conven\u00e7\u00e3o de arbitragem;&#8221;<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">&#8220;Art. 301&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..<\/p>\r\n<p style=\"text-align: justify; padding-left: 120px;\">IX &#8211; conven\u00e7\u00e3o de arbitragem;&#8221;<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">&#8220;Art. 584&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;..<\/p>\r\n<p style=\"text-align: justify; padding-left: 120px;\">III &#8211; a senten\u00e7a arbitral e a senten\u00e7a homologat\u00f3ria de transa\u00e7\u00e3o ou de concilia\u00e7\u00e3o;&#8221;<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 42.<\/strong>\u00a0O art. 520 do C\u00f3digo de Processo Civil passa a ter mais um inciso, com a seguinte reda\u00e7\u00e3o:<\/p>\r\n<p style=\"text-align: justify; padding-left: 60px;\">&#8220;Art.520&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;<\/p>\r\n<p style=\"text-align: justify; padding-left: 120px;\">VI &#8211; julgar procedente o pedido de institui\u00e7\u00e3o de arbitragem.&#8221;<\/p>\r\n<p><strong>Art. 43.<\/strong>\u00a0Esta Lei entrar\u00e1 em vigor sessenta dias ap\u00f3s a data de sua publica\u00e7\u00e3o.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Art. 44.<\/strong> Ficam revogados os arts. 1.037 a 1.048 da Lei n\u00ba 3.071, de 1\u00ba de janeiro de 1916, C\u00f3digo Civil Brasileiro; os arts. 101 e 1.072 a 1.102 da Lei n\u00ba 5.869, de 11 de janeiro de 1973, C\u00f3digo de Processo Civil; e demais disposi\u00e7\u00f5es em contr\u00e1rio.<\/p>\r\n<p style=\"text-align: justify;\">Bras\u00edlia, 23 de setembro de 1996; 175\u00ba da Independ\u00eancia e 108\u00ba da Rep\u00fablica.<\/p>\r\n<p style=\"text-align: justify;\">Fernando Henrique Cardoso<br \/>Nelson A. Jobim<\/p>\r\n\r\n<div class=\"wp-block-spacer\" style=\"height: 100px;\" aria-hidden=\"true\">\u00a0<\/div>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>LEI N\u00ba 9.307, DE 23 DE SETEMBRO DE 1996Disp\u00f5e sobre a arbitragem. Com altera\u00e7\u00f5es advindas da Lei 13.129\/2015 O PRESIDENTE DA REP\u00daBLICAFa\u00e7o saber que o Congresso Nacional decreta e eu sanciono a seguinte: Cap\u00edtulo IDISPOSI\u00c7\u00d5ES GERAIS Art. 1\u00ba As pessoas &hellip; <a href=\"http:\/\/sitesadam.com.br\/modelo\/lei-de-arbitragem\/\">Conte\u00fado<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"kt_blocks_editor_width":""},"_links":{"self":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/pages\/9545"}],"collection":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/comments?post=9545"}],"version-history":[{"count":14,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/pages\/9545\/revisions"}],"predecessor-version":[{"id":10056,"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/pages\/9545\/revisions\/10056"}],"wp:attachment":[{"href":"http:\/\/sitesadam.com.br\/modelo\/wp-json\/wp\/v2\/media?parent=9545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}